{"id":10359,"date":"2022-08-19T10:36:52","date_gmt":"2022-08-19T14:36:52","guid":{"rendered":"https:\/\/pembrokediocese.com\/article\/trois-obstacles-a-letablissement-dune-culture-dinvitation-dans-votre-paroisse-copy\/"},"modified":"2022-08-19T11:34:36","modified_gmt":"2022-08-19T15:34:36","slug":"la-mission-de-leglise","status":"publish","type":"post","link":"https:\/\/pembrokediocese.com\/fr\/article\/la-mission-de-leglise\/","title":{"rendered":"Article &#8211; La mission de l\u2019\u00c9glise"},"content":{"rendered":"<p>Telle que d\u00e9finie par les documents de l\u2019\u00c9glise, la mission de l\u2019\u00c9glise est d\u2019\u00e9vang\u00e9liser, \u00ab c&rsquo;est-\u00e0-dire d&rsquo;annoncer \u00e0 tous la bonne nouvelle du salut, d&rsquo;engendrer par le bapt\u00eame de nouvelles cr\u00e9atures dans le Christ et de les \u00e9duquer \u00e0 vivre en fils de Dieu [1] \u00bb.\u00a0 La mission de l\u2019\u00c9glise est de rendre le Royaume de Dieu pr\u00e9sent dans notre monde [2], en conduisant les gens vers l\u2019amiti\u00e9 avec le Christ, vers la communion d\u2019amour avec le Seigneur qui est la vraie lumi\u00e8re dans notre vie [3].<\/p>\n<p>\u00c9vang\u00e9liser, explique le Pape Paul VI, \u00ab constitue la mission essentielle de l\u2019Eglise. (\u2026) \u00c9vang\u00e9liser est, en effet, la gr\u00e2ce et la vocation propre de l\u2019Eglise, son identit\u00e9 la plus profonde. Elle existe pour \u00e9vang\u00e9liser, c\u2019est-\u00e0-dire pour pr\u00eacher et enseigner, \u00eatre le canal du don de la gr\u00e2ce, r\u00e9concilier les p\u00e9cheurs avec Dieu, perp\u00e9tuer le sacrifice du christ dans la sainte messe, qui est le m\u00e9morial de sa mort et de sa r\u00e9surrection glorieuse [4] \u00bb.<\/p>\n<p>Le Pape Jean-Paul II dit que \u00ab la t\u00e2che pastorale prioritaire de la nouvelle \u00e9vang\u00e9lisation incombe \u00e0 tout le peuple de Dieu, et demande une nouvelle ardeur, de nouvelles m\u00e9thodes et un nouveau langage pour l&rsquo;annonce et le t\u00e9moignage \u00e9vang\u00e9liques [5] \u00bb.<\/p>\n<p>Nos paroisses, nos communaut\u00e9s chr\u00e9tiennes et tous les fid\u00e8les sont appel\u00e9s \u00e0 embrasser cet \u00e9lan de transformation missionnaire.<\/p>\n<p>Pierre-Alain Giffard<br \/>\n___________________________________________<\/p>\n<p>[1] Sacr\u00e9e Congr\u00e9gation pour l\u2019\u00e9ducation catholique, <em>L\u2019\u00e9cole catholique<\/em>, 19 mars 1977, # 7.<br \/>\n[2] Cf. Evangelii Gaudium, 176.<br \/>\n[3] Cf. Hom\u00e9lie du cardinal Joseph Ratzinger, Basilique Saint-Pierre, mardi 28 septembre 2004.<br \/>\n[4] Cf. Evangelii Nuntiandi, n. 14.<br \/>\n[5] Pastores Dabo Vobis, 18.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Autres articles sur l&rsquo;\u00e9vang\u00e9lisation et le renouveau des paroisses :<\/strong><\/p>\n<ul>\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/trois-obstacles-a-letablissement-dune-culture-dinvitation-dans-votre-paroisse\/\">Trois obstacles \u00e0 l\u2019\u00e9tablissement d\u2019une culture d\u2019invitation dans votre paroisse<\/a><\/strong><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisateur-relationnel\/\"><strong class=\"post-title\">L\u2019\u00e9vang\u00e9lisateur relationnel<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/faire-eglise-a-la-maison\/\"><strong class=\"post-title\">Faire \u00c9glise \u00e0 la maison<\/strong><\/a><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-fille-aveugle\/\">La fille aveugle<\/a><\/strong><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/un-groupe-de-gernouilles\/\"><strong>Un groupe de grenouilles<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/lelephant-attache\/\"><strong>L\u2019\u00e9l\u00e9phant attach\u00e9<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/paroisse-de-la-nativite\/\"><strong>Le renouveau de la paroisse de la Nativit\u00e9 \u00e0 Baltimore<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-foi-grandit-copy\/\"><strong>La foi grandit lorsqu\u2019on la partage<\/strong><\/a><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/dans-les-souliers-des-sans-eglises\/\">Dans les souliers des \u201csans-\u00e9glises\u201d<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-cellules-paroissiales-devangelisation-2-copy\/\">Les cellules paroissiales d\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/caracteristiques-uniques-des-paroisses-missionnaires\/\">Six caract\u00e9ristiques uniques des paroisses missionnaires<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/devenir-une-paroisse-missionnaire\/\">Quelques \u00e9tapes pour devenir une paroisse missionnaire<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quest-ce-que-levangelisation\/\">Qu\u2019est-ce que l\u2019\u00e9vang\u00e9lisation et dans quel esprit la pratiquer ?<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/auto-evaluation\/\">Questions de discussion et d\u2019auto-\u00e9valuation pour l\u2019\u00e9vang\u00e9lisation en paroisse<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-priere-de-jesus\/\">La pri\u00e8re de J\u00e9sus: une m\u00e9thode pour prier en tout temps<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/pratiquer-leur-foi\/\">Qu\u2019est-ce qui peut aider les enfants \u00e9lev\u00e9s dans la religion catholique \u00e0 continuer \u00e0 pratiquer leur foi \u00e0 l\u2019\u00e2ge adulte ?<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-tactiques-de-satan-1ere-partie\/\">Les tactiques de Satan<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/apprendre-a-etre-missionnaire\/\">Apprendre \u00e0 \u00eatre missionnaire<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quand-nous-crions-vers-dieu\/\">Quand nous crions vers Dieu, il r\u00e9pond<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent-copy\/\">Pr\u00e9sence et Proclamation<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent\/\">Sauver ceux qui se perdent<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-paroisse-saint-nazaire-lhistoire-dune-transformation-missionnaire\/\">La paroisse Saint-Nazaire: L\u2019histoire d\u2019une transformation missionnaire<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/evangelisation-et-petits-groupes-de-partage\/\">\u00c9vang\u00e9lisation et petits groupes de partage<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/evangeliser-en-invitant-des-personnes-a-recevoir-jesus-comme-seigneur-et-sauveur\/\">\u00c9vang\u00e9liser en invitant des personnes \u00e0 recevoir J\u00e9sus comme Seigneur et Sauveur<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/vous-allez-recevoir-une-force\/\">Vous allez recevoir une force\u2026<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/avez-vous-entendu-parler-de-la-loi-des-trois-ecoutes-et-des-sept-contacts\/\">Avez-vous entendu parler de la loi des trois \u00e9coutes et des sept contacts ?<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/trois-habitudes-dune-vie-chretienne-fructueuse\/\">Trois habitudes d\u2019une vie chr\u00e9tienne fructueuse<\/a><\/strong><\/li>\n<\/ul>\n<div class=\"info\">\n<hr \/>\n<\/div>\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\">\n<p><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1993 size-full\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying-100x100.png 100w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\">LECTURES RECOMMANDEES<\/a><\/h4>\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\" target=\"_self\" >En savoir plus <\/a>\n<\/div>\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\">\n<p><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/prayer-group\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3620\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-300x300.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-300x300.png 300w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-100x100.png 100w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-400x400.png 400w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-210x210.png 210w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle.png 684w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/prayer-group\/\">PRI\u00c8RES ET GROUPES DE PRIERE POUR LE PROJET DIOC\u00c9SAIN DE NOUVELLE \u00c9VANG\u00c9LISATION<\/a><\/h4>\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"\/fr\/nouvelle-evangelisation\/prayer-group\/\" target=\"_self\" >En savoir plus<\/a>\n<\/div>\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\">\n<p><a href=\"https:\/\/pembrokediocese.com\/donate\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7117 size-medium aligncenter\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-200x200.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-200x200.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-768x768.png 768w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-100x100.png 100w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-400x400.png 400w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-210x210.png 210w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept.png 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/donate\/\">DONNER POUR LE PROJET DIOC\u00c9SAIN DE NOUVELLE \u00c9VANG\u00c9LISATION<\/a><\/h4>\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"https:\/\/pembrokediocese.com\/donate\/\" target=\"_self\" >En savoir plus<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Telle que d\u00e9finie par les documents de l\u2019\u00c9glise, la mission de l\u2019\u00c9glise est d\u2019\u00e9vang\u00e9liser, \u00ab c&rsquo;est-\u00e0-dire d&rsquo;annoncer \u00e0 tous la bonne nouvelle du salut, d&rsquo;engendrer par le bapt\u00eame de nouvelles cr\u00e9atures dans le Christ et de les \u00e9duquer \u00e0 vivre en fils de Dieu [1] \u00bb.\u00a0 La mission de l\u2019\u00c9glise est de rendre le Royaume de Dieu pr\u00e9sent dans notre monde [2], en conduisant les gens vers l\u2019amiti\u00e9 avec le Christ, vers la communion d\u2019amour avec le Seigneur qui est la vraie lumi\u00e8re dans notre vie [3]. \u00c9vang\u00e9liser, explique le Pape Paul VI, \u00ab constitue la mission essentielle de l\u2019Eglise. (\u2026) \u00c9vang\u00e9liser est, en effet, la gr\u00e2ce et la vocation propre de l\u2019Eglise, son identit\u00e9 la plus profonde. Elle existe pour \u00e9vang\u00e9liser, c\u2019est-\u00e0-dire pour pr\u00eacher et enseigner, \u00eatre le canal du don de la gr\u00e2ce, r\u00e9concilier les p\u00e9cheurs avec Dieu, perp\u00e9tuer le sacrifice du christ dans la sainte messe, qui est le m\u00e9morial de sa mort et de sa r\u00e9surrection glorieuse [4] \u00bb. Le Pape Jean-Paul II dit que \u00ab la t\u00e2che pastorale prioritaire de la nouvelle \u00e9vang\u00e9lisation incombe \u00e0 tout le peuple de Dieu, et demande une nouvelle ardeur, de nouvelles m\u00e9thodes et un nouveau langage pour l&rsquo;annonce et le t\u00e9moignage \u00e9vang\u00e9liques [5] \u00bb. Nos paroisses, nos communaut\u00e9s chr\u00e9tiennes et tous les fid\u00e8les sont appel\u00e9s \u00e0 embrasser cet \u00e9lan de transformation missionnaire. Pierre-Alain Giffard ___________________________________________ [1] Sacr\u00e9e Congr\u00e9gation pour l\u2019\u00e9ducation catholique, L\u2019\u00e9cole catholique, 19 mars 1977, # 7. [2] Cf. Evangelii Gaudium, 176. [3] Cf. Hom\u00e9lie du cardinal Joseph Ratzinger, Basilique Saint-Pierre, mardi 28 septembre 2004. [4] Cf. Evangelii Nuntiandi, n. 14. [5] Pastores Dabo Vobis, 18. &nbsp; Autres articles sur l&rsquo;\u00e9vang\u00e9lisation et le renouveau des paroisses : Trois obstacles \u00e0 l\u2019\u00e9tablissement d\u2019une culture d\u2019invitation dans votre paroisse L\u2019\u00e9vang\u00e9lisateur relationnel Faire \u00c9glise \u00e0 la maison La fille aveugle Un groupe de grenouilles L\u2019\u00e9l\u00e9phant attach\u00e9 Le renouveau de la paroisse de la Nativit\u00e9 \u00e0 Baltimore La foi grandit lorsqu\u2019on la partage Dans les souliers des \u201csans-\u00e9glises\u201d Les cellules paroissiales d\u2019\u00e9vang\u00e9lisation Six caract\u00e9ristiques uniques des paroisses missionnaires Quelques \u00e9tapes pour devenir une paroisse missionnaire Qu\u2019est-ce que l\u2019\u00e9vang\u00e9lisation et dans quel esprit la pratiquer ? Questions de discussion et d\u2019auto-\u00e9valuation pour l\u2019\u00e9vang\u00e9lisation en paroisse La pri\u00e8re de J\u00e9sus: une m\u00e9thode pour prier en tout temps Qu\u2019est-ce qui peut aider les enfants \u00e9lev\u00e9s dans la religion catholique \u00e0 continuer \u00e0 pratiquer leur foi \u00e0 l\u2019\u00e2ge adulte ? Les tactiques de Satan Apprendre \u00e0 \u00eatre missionnaire Quand nous crions vers Dieu, il r\u00e9pond Pr\u00e9sence et Proclamation Sauver ceux qui se perdent La paroisse Saint-Nazaire: L\u2019histoire d\u2019une transformation missionnaire \u00c9vang\u00e9lisation et petits groupes de partage \u00c9vang\u00e9liser en invitant des personnes \u00e0 recevoir J\u00e9sus comme Seigneur et Sauveur Vous allez recevoir une force\u2026 Avez-vous entendu parler de la loi des trois \u00e9coutes et des sept contacts ? Trois habitudes d\u2019une vie chr\u00e9tienne fructueuse<\/p>\n","protected":false},"author":13,"featured_media":10363,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[84,156],"tags":[],"class_list":["post-10359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","category-textes-a-lire"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/10359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/comments?post=10359"}],"version-history":[{"count":10,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/10359\/revisions"}],"predecessor-version":[{"id":10389,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/10359\/revisions\/10389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media\/10363"}],"wp:attachment":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media?parent=10359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/categories?post=10359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/tags?post=10359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}