{"id":12007,"date":"2023-03-11T15:03:59","date_gmt":"2023-03-11T20:03:59","guid":{"rendered":"https:\/\/pembrokediocese.com\/?p=12007"},"modified":"2025-01-20T11:00:05","modified_gmt":"2025-01-20T16:00:05","slug":"une-priere-bibique-pour-la-guerison","status":"publish","type":"post","link":"https:\/\/pembrokediocese.com\/fr\/article\/une-priere-bibique-pour-la-guerison\/","title":{"rendered":"ARTICLE &#8211; Pri\u00e8re pour la gu\u00e9rison : Tu es le Seigneur qui me gu\u00e9rit"},"content":{"rendered":"\r\n<p><em>P\u00e8re c\u00e9leste, je viens \u00e0 toi sachant que tu es Yahweh qui me gu\u00e9rit (Exode 15:26). Je te demande d\u2019\u00e9loigner de moi la maladie et de me redonner \u00e0 la sant\u00e9 (Psaume 103:2-3). Je te remercie d&rsquo;avoir envoy\u00e9 dans le monde ton Fils J\u00e9sus, qui chassait les esprits mauvais et gu\u00e9rissait tous les malades (Matthieu 8:16-17). Son amour et sa compassion n&rsquo;ont pas chang\u00e9 (Lamentations 3:22-23). Il est le m\u00eame hier, aujourd&rsquo;hui et pour toujours (H\u00e9breux 13:8). Je te demande de bien vouloir d\u00e9verser sur moi ton Saint-Esprit pour d\u00e9rtuire les oeuvres du diable dans ma vie (\u00c9ph\u00e9siens 6:12). Je te b\u00e9nis, mon Dieu, et je n&rsquo;oublie aucun de tes bienfaits (Psaume 103:2). Je crois en ta promesse de pardonner tous mes p\u00e9ch\u00e9s et de gu\u00e9rir toutes mes maladies (Psaume 103:3). Il est \u00e9crit que par tes blessures, j\u2019ai \u00e9t\u00e9 gu\u00e9ris (1 Pierre 2:24). \u00c0 toi soit la louange, l&rsquo;honneur, la gloire et la puissance dans les si\u00e8cles des si\u00e8cles ! Amen. (Apocalypse 5:13)<\/em><\/p>\r\n\r\n\r\n\r\n<p>Tout au long des \u00c9vangiles, le minist\u00e8re de J\u00e9sus d\u00e9montre le d\u00e9sir de Dieu de nous gu\u00e9rir. J\u00e9sus gu\u00e9rissait les malades, chassait les d\u00e9mons et ressuscitait les morts, montrant ainsi sa puissance et son autorit\u00e9 sur la maladie et le mal.<\/p>\r\n\r\n\r\n\r\n<p>Cependant, le minist\u00e8re de gu\u00e9rison de J\u00e9sus ne se r\u00e9sumait pas \u00e0 une simple d\u00e9monstration de puissance, il \u00e9tait principalement l&rsquo;expression de l&rsquo;amour et de la compassion de Dieu pour l&rsquo;humanit\u00e9. Dans Matthieu 9:35, il est \u00e9crit: \u00ab\u00a0J\u00e9sus parcourait toutes les villes et les villages, enseignant dans les synagogues, pr\u00eachant la bonne nouvelle du royaume, et gu\u00e9rissant <em>toute <\/em>maladie et <em>toute<\/em> infirmit\u00e9\u00a0\u00bb (italiques sont n\u00f4tres). Le minist\u00e8re de gu\u00e9rison de J\u00e9sus faisait partie de sa mission plus large de proclamer le Royaume de Dieu et de r\u00e9tablir toutes les dimensions de nos vie.<\/p>\r\n\r\n\r\n\r\n<p>J\u00e9sus est ressucit\u00e9, il est vivant et continue d\u2019oeuvrer pour notre salut. Ses \u0153uvres ne se limitent pas \u00e0 la gu\u00e9rison physique, elles englobent \u00e9galement notre bien-\u00eatre spirituel, mental et \u00e9motionnel. J\u00e9sus veut pardonner nos p\u00e9ch\u00e9s, gu\u00e9rir nos relations et redonner espoir \u00e0 ceux et celles qui en ont besoin.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-right\" style=\"text-align: right;\">Pierre-Alain Giffard, Coordonnateur de la pastorale dioc\u00e9saine<\/p>\r\n<p><strong>Livre sur la revitalisation et la croissance des paroisses<\/strong><\/p>\r\n<ul>\r\n<li><a href=\"https:\/\/www.amazon.ca\/PAROISSES-VIVANTES-transformation-missionnaire-communaut%C3%A9s\/dp\/B0CR86D15B\/ref=sr_1_1?crid=3MN0K2YR8HQ7J&amp;keywords=paroisses+vivantes&amp;qid=1704572814&amp;sprefix=%2Caps%2C92&amp;sr=8-1\" target=\"_blank\" rel=\"noopener\" aria-label=\"LIVRE \u00c0 LIRE \u2013 PAROISSES VIVANTES: Guide pratique pour la transformation missionnaire des communaut\u00e9s chr\u00e9tiennes (Pr\u00e9face de Mgr Damphousse) (opens in a new tab)\"><strong class=\"post-title\">PAROISSES VIVANTES : Guide pratique pour la transformation missionnaire des communaut\u00e9s chr\u00e9tiennes (Pr\u00e9face de Mgr Damphousse)<\/strong><\/a><\/li>\r\n<\/ul>\r\n<p><strong>Autres articles et ressources pour l&rsquo;\u00e9vang\u00e9lisation et le renouveau des paroisses :<\/strong><\/p>\r\n<ul>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisation-partager-la-joie-la-paix-et-lesperance-du-christ\/\">L\u2019\u00e9vang\u00e9lisation : Partager la Joie, la Paix et l\u2019Esp\u00e9rance du Christ<\/a><\/strong><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-priere-pour-les-personnes-qui-ont-besoin-de-lamour-de-dieu-et-de-son-salut\/\"><strong><strong class=\"post-title\">Une pri\u00e8re pour ceux et celles que nous esp\u00e9rons voir rencontrer le Christ<\/strong><\/strong><\/a><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-leadership-sacerdotal-dans-levangelisation\/\">Leadership sacerdotal dans l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/temoignage-levangelisation-autour-dun-cafe-a-luniversite-de-mary-washington\/\">L\u2019\u00e9vang\u00e9lisation autour d\u2019un caf\u00e9 \u00e0 l\u2019Universit\u00e9 de Mary Washington<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisation-un-temoignage-vivant-de-lamour-divin\/\">L\u2019\u00c9vang\u00e9lisation : Un T\u00e9moignage Vivant de l\u2019Amour Divin<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/vivre-de-la-joie-de-levangile\/\">Vivre de la joie de l\u2019\u00c9vangile<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/au-commencement-etait-le-verbe-le-role-essentiel-des-ecritures-dans-levangelisation\/\">Au Commencement \u00c9tait le Verbe: Le R\u00f4le Essentiel des \u00c9critures dans l\u2019\u00c9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/evangeliser-quelques-mots-suffisent\/\">\u00c9vang\u00e9liser avec quelques mots<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/demander-chaque-jour-la-grace-daider-quelquun\/\">Demander chaque jour la gr\u00e2ce d\u2019aider quelqu\u2019un<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-paroisse-comme-expression-de-lamour-de-dieu-pour-le-monde-2\/\">La paroisse comme expression de l\u2019amour de Dieu pour le monde<\/a><\/strong><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-si-personne-ne-parle-personne-ne-saura\/\"><strong><strong class=\"post-title\">Si personne ne parle, personne ne saura <\/strong><\/strong><\/a><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/evangeliser-par-la-guerison-manifester-la-presence-aimante-de-dieu\/\">\u00c9vang\u00e9liser par la gu\u00e9rison : manifester la pr\u00e9sence aimante de Dieu<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-parabole-du-sage-proprietaire\/\">La Parabole du Sage Propri\u00e9taire<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/signes-extraordinaires-au-quotidien\/\">Signes Extraordinaires au Quotidien<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-le-message-evangelisateur-de-medjugorje\/\">Le message \u00e9vang\u00e9lisateur de Medjugorje<\/a><\/strong><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-difference-entre-le-proselytisme-et-levangelisation-authentique\/\"><strong><strong class=\"post-title\">La diff\u00e9rence entre le pros\u00e9lytisme et l\u2019\u00e9vang\u00e9lisation authentique<\/strong><\/strong><\/a><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/dieu-a-besoin-damour-de-reconciliation-et-dun-esprit-de-pardon\/\">Ce que Dieu a besoin, c\u2019est de l\u2019amour, de la r\u00e9conciliation et un esprit de pardon<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/article-levangelisation-une-mission-collaborative-damour\/\">L\u2019\u00e9vang\u00e9lisation : Une mission collaborative d\u2019amour<\/a><\/strong><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-lapproche-convaincante-du-pere-james-mallon-pour-transformer-les-paroisses-dune-mentalite-de-maintenance-en-une-communaute-missionnaire-florissante\/\">L\u2019approche du P\u00e8re James Mallon pour transformer les paroisses en communaut\u00e9s missionnaires florissantes<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-priere-et-le-service-qui-trouvent-grace-aux-yeux-de-dieu\/\">La pri\u00e8re et le service qui trouvent gr\u00e2ce aux yeux de Dieu<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-pouvoir-transformateur-de-lamour\/\">Le Pouvoir Transformateur de l\u2019Amour<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-puissance-surnaturelle-de-la-priere-et-de-lamour-envers-dieu\/\">La puissance surnaturelle de la pri\u00e8re et de l\u2019amour envers Dieu<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisation-au-quotidien\/\"><strong class=\"post-title\">L\u2019\u00c9vang\u00e9lisation au Quotidien<\/strong><\/a><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/chaque-acte-damour-est-evangelisation\/\">Chaque acte d\u2019amour est \u00e9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/aimer-jesus-et-le-faire-aimer\/\">Aimer J\u00e9sus et le Faire Aimer<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/adopter-un-style-de-vie-dadoration-et-de-louange\/\">Adopter un style de vie d\u2019adoration et de louange<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/priere-pour-demander-a-dieu-la-guerison\/\">Pri\u00e8re pour demander \u00e0 Dieu la gu\u00e9rison<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/ce-qui-a-prouve-attirer-les-gens-vers-le-christ\/\">Ce qui a prouv\u00e9 attirer les gens vers le Christ<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisation-trouver-la-vie-et-partager-la-vie\/\">L\u2019\u00c9vang\u00e9lisation : Trouver la Vie et Partager la Vie<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-leucharistie-source-et-sommet-de-toute-evangelisation\/\">L\u2019Eucharistie : Source et sommet de toute \u00e9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/etapes-pratiques-pour-atteindre-les-personnes-sans-communaute-chretienne\/\">Pistes pratiques pour atteindre les personnes \u00e9loign\u00e9es de la foi<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/guide-de-partage-de-la-bible-en-petits-groupes-une-approche-synodale\/\">Guide de Partage de la Bible en Petits Groupes : Une Approche Synodale<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/amener-quelquun-au-christ-en-suscitant-en-lui-un-sentiment-damour-et-de-louange-envers-dieu\/\">Amener quelqu\u2019un au Christ en suscitant en lui un sentiment d\u2019amour et de louange envers Dieu<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/proclamer-la-parole-de-dieu-un-appel-sacre\/\">Proclamer la parole de Dieu : Un appel sacr\u00e9\u00a0<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/du-declin-au-renouveau-la-transformation-de-leglise-new-life-de-farmington\/\">Du d\u00e9clin au Renouveau : La Transformation de l\u2019\u00c9glise New Life de Farmington<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/lenseignement-social-de-leglise-et-levangelisation\/\">La doctrine sociale de l\u2019\u00c9glise et l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-bienveillance-une-perspective-chretienne\/\">La Bienveillance : Une Perspective Chr\u00e9tienne<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/comment-amener-quelquun-au-christ\/\">Comment amener quelqu\u2019un au Christ<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-finalite-ultime-de-la-vie-humaine-glorifier-dieu\/\">La finalit\u00e9 ultime de la vie humaine \u2013 Glorifier Dieu<\/a><\/strong><\/strong><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/de-lagonie-a-une-nouvelle-vie-le-parcours-de-revitalisation-dune-eglise-de-campagne\/\"><strong class=\"post-title\">De l\u2019Agonie \u00e0 une Nouvelle Vie : Le Parcours de Revitalisation d\u2019une \u00c9glise de Campagne<\/strong><\/a><\/strong><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisation-en-une-phrase-goutez-et-voyez-le-seigneur-est-bon-psaume-349\/\">L\u2019\u00e9vang\u00e9lisation en une phrase: \u00ab Go\u00fbtez et voyez : le Seigneur est bon ! \u00bb (Psaume 34,9)<\/a><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-renouveau-des-eglises-rurales\/\">Le renouveau des \u00e9glises rurales<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-repondre-a-la-baisse-de-frequentation-de-nos-eglises\/\">Facteurs cl\u00e9s attirant les gens vers la foi catholique<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/repondre-a-la-diminution-de-laffluence-dans-nos-eglises\/\">R\u00e9pondre \u00e0 la baisse de fr\u00e9quentation de nos \u00e9glises<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/favoriser-une-atmosphere-sacree-lors-de-la-liturgie-dominicale\/\">Favoriser une Atmosph\u00e8re Sacr\u00e9e lors de la Liturgie Dominicale<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/prier\/priere-pour-recevoir-le-bapteme-dans-lesprit-saint\/\">Pri\u00e8re pour recevoir le bapt\u00eame dans l\u2019Esprit-Saint<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-soif-ardente-du-christ-pour-les-mes\/\">La Soif Ardente du Christ pour les \u00c2mes<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/partager-la-bonne-nouvelle-avec-les-noms-redempteurs-de-dieu\/\">Prier et Partager la Bonne Nouvelle avec les Noms R\u00e9dempteurs de Dieu<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/repondre-a-lappel-a-evangeliser\/\">R\u00e9pondre \u00e0 l\u2019Appel \u00e0 \u00c9vang\u00e9liser<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-quelle-est-la-chose-qui-plait-le-plus-a-dieu-amener-les-ames-au-christ\/\">Qu\u2019est ce qui pla\u00eet le plus \u00e0 Dieu ? Amener les \u00e2mes au Christ<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-croissance-de-leglise-de-la-nativite-p-michael-white\/\">La croissance de l\u2019\u00c9glise de la Nativit\u00e9 (P. Michael White)<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-croissance-de-la-paroisse-saint-benedict-james-mallon\/\">La croissance de la paroisse Saint-Benedict (James Mallon)<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-cinq-piliers-de-la-foi-chretienne\/\">Cinq piliers de la vie chr\u00e9tienne<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-rencontre-personnelle-avec-jesus\/\">Rencontrer J\u00e9sus: Chemin de Transformation Personnelle<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/que-signifie-avoir-une-relation-personnelle-avec-jesus\/\">Que signifie avoir une relation personnelle avec J\u00e9sus ?<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/liberer-le-potentiel-devangelisation-de-votre-paroisse\/\">Lib\u00e9rer le potentiel d\u2019\u00e9vang\u00e9lisation de votre paroisse<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-lobjectif-ultime-de-levangelisation\/\">L\u2019objectif ultime de l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-la-soif-damour-de-dieu-et-notre-mission-de-la-faire-connaitre\/\">La soif d\u2019amour de Dieu et notre mission de la faire conna\u00eetre<\/a><\/strong><\/strong><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/des-dimanches-memorables\/\">Des dimanches m\u00e9morables<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-plan-en-trois-etapes-du-pere-bedard-pour-evangeliser\/\">Le plan en trois \u00e9tapes du p\u00e8re B\u00e9dard pour \u00e9vang\u00e9liser<\/a><\/strong><\/strong><\/li>\r\n<li><strong class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/GUIDE-POUR-LA-TRANSFORMATION-MISSIONNAIRE-DES-PAROISSES.pdf\">Guide pour la transformation missionnaire des paroisses<\/a><\/strong><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/un-guide-pratique-pour-demarrer-un-petit-groupe-devangelisation\/\">Semeurs de foi : Un guide pratique pour d\u00e9marrer un petit groupe d\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-transformation-missionnaire-de-la-paroisse-de-santeustorgio\/\">La transformation missionnaire de la paroisse de Sant\u2019Eustorgio<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/creer-des-communautes-catholiques-dynamiques-sagesse-tiree-du-livre-excellent-catholic-parishes\/\"><strong class=\"post-title\">Cr\u00e9er des Communaut\u00e9s Catholiques Dynamiques : Sagesse tir\u00e9e du livre \u2018Excellent Catholic Parishes\u2019<\/strong><\/a><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/partager-levangile-en-fonction-des-besoins-et-de-la-receptivite-des-gens\/\"><strong class=\"post-title\">Partager l\u2019\u00c9vangile en fonction des besoins et de la r\u00e9ceptivit\u00e9 des gens<\/strong><\/a><\/strong><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-priere-pour-inviter-des-personnes-a-des-rencontres-devangelisation\/\">Une pri\u00e8re pour inviter des personnes \u00e0 des rencontres d\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/accueillir-les-invites-et-les-visiteurs-a-leglise\/\">Accueillir les invit\u00e9s et les visiteurs \u00e0 l\u2019\u00e9glise: les choses \u00e0 faire et \u00e0 ne pas faire<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/caracteristiques-dune-paroisse-evangelisatrice\/\">Caract\u00e9ristiques d\u2019une paroisse \u00e9vang\u00e9lisatrice<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/differentes-dimensions-de-levangelisation\/\">Diff\u00e9rentes dimensions de l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-la-vraie-mesure-du-succes\/\"><strong class=\"post-title\">La vraie mesure du succ\u00e8s<\/strong><\/a><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/article-le-pape-francois-sur-levangelisation\/\">Le pape Francois sur l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/reveiller-la-paroisse-rurale-pour-levangelisation\/\">R\u00e9veiller la paroisse rurale pour l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quest-ce-qui-amene-les-gens-au-christ\/\">Qu\u2019est-ce qui am\u00e8ne les gens au Christ ?<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-evangeliser-par-des-petits-actes-de-gentillesse\/\">\u00c9vang\u00e9liser par des petits actes de gentillesse<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-des-questions-pour-entamer-des-conversations-spirituelles\/\"><strong class=\"post-title\">Des questions pour entamer des conversations spirituelles<\/strong><\/a><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/a-trois-pieds-de-lor\/\">\u00c0 trois pieds de l\u2019or<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/evangeliser-a-travers-nos-interactions-sociales\/\">\u00c9vang\u00e9liser en d\u00e9veloppant nos comp\u00e9tences sociales<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/rassembler-temoigner-et-inviter\/\">Rassembler, t\u00e9moigner et inviter<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/priere-pour-recevoir-les-dons-spirituels-du-saint-esprit\/\"><strong class=\"post-title\">Pri\u00e8re pour recevoir les dons spirituels du Saint Esprit<\/strong><\/a><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-langage-de-la-croix-la-voix-de-levangelisation\/\">Le langage de la croix est le langage de l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-facteurs-cles-pour-la-croissance-de-la-paroisse\/\">Facteurs cl\u00e9s pour la croissance de la paroisse selon Rich Birch<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-comment-vaincre-satan\/\"><strong class=\"post-title\">Comment vaincre Satan ?<\/strong><\/a><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/apporter-amour-espoir-et-guerison-par-levangile\/\"><strong class=\"post-title\">Apporter Amour, Espoir et Gu\u00e9rison par l\u2019\u00c9vangile<\/strong><\/a><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-quest-ce-que-lamour\/\"><strong class=\"post-title\">Qu\u2019est-ce que l\u2019amour ?<\/strong><\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-touche-par-le-maitre\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Touch\u00e9 par le Ma\u00eetre<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-un-homme-un-chien-et-lamour-ultime\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Un homme, un chien, et l\u2019amour ultime<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/des-facons-pratiques-daimer-les-autres\/\"><strong>A<\/strong><\/a><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/des-facons-pratiques-daimer-les-autres\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>u c\u0153ur de l\u2019\u00e9vang\u00e9lisation : Aimer Dieu et les autres<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/aimer-nos-ennemis-et-se-reconcilier-avec-les-autres\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Aimer nos ennemis et se r\u00e9concilier avec les autres<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-priere-bibique-pour-la-guerison\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pri\u00e8re pour la gu\u00e9rison : Tu es le Seigneur qui me gu\u00e9rit<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-vivre-une-vie-damour-lheritage-de-mere-teresa\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Vivre une vie d\u2019amour : L\u2019h\u00e9ritage de M\u00e8re Teresa<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-force-puissante-est-a-loeuvre\/\"><strong>Sous le <\/strong><\/a><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-force-puissante-est-a-loeuvre\/\" target=\"_blank\" rel=\"noreferrer noopener\">c<\/a><\/strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-force-puissante-est-a-loeuvre\/\"><strong>ouvert des t\u00e9n\u00e8bres, une force puissante est \u00e0 l\u2019\u0153uvre<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-evangeliser-avec-amour-et-pour-lamour\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Vivre une vie d\u2019amour : Le\u00e7ons du Nouveau Testament<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/19-orientations-pastorales-pour-le-renouveau-et-la-croissance-des-paroisses\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>19 orientations pastorales qui contribuent \u00e0 la croissance des paroisses<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-renouveau-missionnaire-de-la-catechese\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Le renouveau missionnaire de la cat\u00e9ch\u00e8se<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/les-caracteristiques-des-paroisses-missionnaires\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Les caract\u00e9ristiques des paroisses missionnaires<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/priere-de-guerison\/\"><strong>Pri\u00e8re de gu\u00e9rison attribu\u00e9e \u00e0 saint Padre Pio<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/partager-notre-foi\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Nous sommes appel\u00e9s \u00e0 partager notre foi avec les autres<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/devrait-on-chercher-la-croissance-de-leglise\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Devrait-on chercher la croissance de l\u2019\u00c9glise ?<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/trouvez-un-besoin-et-comblez-le\/\" target=\"_blank\" rel=\"noreferrer noopener\">Trouvez un besoin et comblez-le : R\u00e9v\u00e9ler le c\u0153ur de Dieu dans son quartier<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/evangeliser-au-quotidien\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>15 habitudes pour \u00e9vang\u00e9liser au quotidien<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-mission-de-leglise\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>La mission de l\u2019\u00c9glise<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/trois-obstacles-a-letablissement-dune-culture-dinvitation-dans-votre-paroisse\/\" target=\"_blank\" rel=\"noreferrer noopener\">Trois obstacles \u00e0 l\u2019\u00e9tablissement d\u2019une culture d\u2019invitation dans votre paroisse<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisateur-relationnel\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>L\u2019\u00e9vang\u00e9lisateur relationnel<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/faire-eglise-a-la-maison\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Faire \u00c9glise \u00e0 la maison<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-fille-aveugle\/\" target=\"_blank\" rel=\"noreferrer noopener\">La fille aveugle<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/un-groupe-de-gernouilles\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Un groupe de grenouilles<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/lelephant-attache\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>L\u2019\u00e9l\u00e9phant attach\u00e9<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/paroisse-de-la-nativite\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Le renouveau de la paroisse de la Nativit\u00e9 \u00e0 Baltimore<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-foi-grandit-copy\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>La foi grandit lorsqu\u2019on la partage<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/dans-les-souliers-des-sans-eglises\/\" target=\"_blank\" rel=\"noreferrer noopener\">Dans les souliers des \u201csans-\u00e9glises\u201d<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-cellules-paroissiales-devangelisation-2-copy\/\" target=\"_blank\" rel=\"noreferrer noopener\">Les cellules paroissiales d\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/caracteristiques-uniques-des-paroisses-missionnaires\/\" target=\"_blank\" rel=\"noreferrer noopener\">Six caract\u00e9ristiques uniques des paroisses missionnaires<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/devenir-une-paroisse-missionnaire\/\" target=\"_blank\" rel=\"noreferrer noopener\">Quelques \u00e9tapes pour devenir une paroisse missionnaire<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quest-ce-que-levangelisation\/\" target=\"_blank\" rel=\"noreferrer noopener\">Qu\u2019est-ce que l\u2019\u00e9vang\u00e9lisation et dans quel esprit la pratiquer ?<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/auto-evaluation\/\" target=\"_blank\" rel=\"noreferrer noopener\">Questions de discussion et d\u2019auto-\u00e9valuation pour l\u2019\u00e9vang\u00e9lisation en paroisse<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-priere-de-jesus\/\" target=\"_blank\" rel=\"noreferrer noopener\">La pri\u00e8re de J\u00e9sus: une m\u00e9thode pour prier en tout temps<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/pratiquer-leur-foi\/\" target=\"_blank\" rel=\"noreferrer noopener\">Qu\u2019est-ce qui peut aider les enfants \u00e9lev\u00e9s dans la religion catholique \u00e0 continuer \u00e0 pratiquer leur foi \u00e0 l\u2019\u00e2ge adulte ?<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-tactiques-de-satan-1ere-partie\/\" target=\"_blank\" rel=\"noreferrer noopener\">Les tactiques de Satan<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/apprendre-a-etre-missionnaire\/\" target=\"_blank\" rel=\"noreferrer noopener\">Apprendre \u00e0 \u00eatre missionnaire<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quand-nous-crions-vers-dieu\/\" target=\"_blank\" rel=\"noreferrer noopener\">Quand nous crions vers Dieu, il r\u00e9pond<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent-copy\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pr\u00e9sence et Proclamation<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sauver ceux qui se perdent<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-paroisse-saint-nazaire-lhistoire-dune-transformation-missionnaire\/\" target=\"_blank\" rel=\"noreferrer noopener\">La paroisse Saint-Nazaire: L\u2019histoire d\u2019une transformation missionnaire<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/evangelisation-et-petits-groupes-de-partage\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9vang\u00e9lisation et petits groupes de partage<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/evangeliser-en-invitant-des-personnes-a-recevoir-jesus-comme-seigneur-et-sauveur\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9vang\u00e9liser en invitant des personnes \u00e0 recevoir J\u00e9sus comme Seigneur et Sauveur<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/vous-allez-recevoir-une-force\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vous allez recevoir une force\u2026<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/avez-vous-entendu-parler-de-la-loi-des-trois-ecoutes-et-des-sept-contacts\/\" target=\"_blank\" rel=\"noreferrer noopener\">Avez-vous entendu parler de la loi des trois \u00e9coutes et des sept contacts ?<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/trois-habitudes-dune-vie-chretienne-fructueuse\/\" target=\"_blank\" rel=\"noreferrer noopener\">Trois habitudes d\u2019une vie chr\u00e9tienne fructueuse<\/a><\/strong><\/li>\r\n<\/ul>\r\n<ul><\/ul>\r\n<!-- \/wp:post-content -->\r\n\r\n<!-- wp:separator --><hr class=\"wp-block-separator has-alpha-channel-opacity\" \/><!-- \/wp:separator -->\r\n\r\n<!-- wp:shortcode -->\r\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\"> <a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1993 size-full\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying-100x100.png 100w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\r\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\">LECTURES RECOMMANDEES<\/a><\/h4>\r\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\" target=\"_self\" >En savoir plus <\/a>\r\n<\/div>\r\n<!-- \/wp:shortcode -->\r\n\r\n<!-- wp:shortcode -->\r\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\"> <a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/prayer-group\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3620\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-300x300.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-300x300.png 300w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-100x100.png 100w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-400x400.png 400w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-210x210.png 210w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle.png 684w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\r\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/prayer-group\/\">PRI\u00c8RES ET GROUPES DE PRIERE POUR LE PROJET DIOC\u00c9SAIN DE NOUVELLE \u00c9VANG\u00c9LISATION<\/a><\/h4>\r\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"\/fr\/nouvelle-evangelisation\/prayer-group\/\" target=\"_self\" >En savoir plus<\/a>\r\n<\/div>\r\n<!-- \/wp:shortcode -->\r\n\r\n<!-- wp:shortcode -->\r\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\"> <a href=\"https:\/\/pembrokediocese.com\/donate\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7117 size-medium aligncenter\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-200x200.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-200x200.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-768x768.png 768w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-100x100.png 100w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-400x400.png 400w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-210x210.png 210w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept.png 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\r\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/donate\/\">DONNER POUR LE PROJET DIOC\u00c9SAIN DE NOUVELLE \u00c9VANG\u00c9LISATION<\/a><\/h4>\r\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"https:\/\/pembrokediocese.com\/donate\/\" target=\"_self\" >En savoir plus<\/a>\r\n<\/div>\r\n<!-- \/wp:shortcode -->","protected":false},"excerpt":{"rendered":"<p>P\u00e8re c\u00e9leste, je viens \u00e0 toi sachant que tu es Yahweh qui me gu\u00e9rit (Exode 15:26). Je te demande d\u2019\u00e9loigner de moi la maladie et de me redonner \u00e0 la sant\u00e9 (Psaume 103:2-3). Je te remercie d&rsquo;avoir envoy\u00e9 dans le monde ton Fils J\u00e9sus, qui chassait les esprits mauvais et gu\u00e9rissait tous les malades (Matthieu 8:16-17). Son amour et sa compassion n&rsquo;ont pas chang\u00e9 (Lamentations 3:22-23). Il est le m\u00eame hier, aujourd&rsquo;hui et pour toujours (H\u00e9breux 13:8). Je te demande de bien vouloir d\u00e9verser sur moi ton Saint-Esprit pour d\u00e9rtuire les oeuvres du diable dans ma vie (\u00c9ph\u00e9siens 6:12). Je te b\u00e9nis, mon Dieu, et je n&rsquo;oublie aucun de tes bienfaits (Psaume 103:2). Je crois en ta promesse de pardonner tous mes p\u00e9ch\u00e9s et de gu\u00e9rir toutes mes maladies (Psaume 103:3). Il est \u00e9crit que par tes blessures, j\u2019ai \u00e9t\u00e9 gu\u00e9ris (1 Pierre 2:24). \u00c0 toi soit la louange, l&rsquo;honneur, la gloire et la puissance dans les si\u00e8cles des si\u00e8cles ! Amen. (Apocalypse 5:13) Tout au long des \u00c9vangiles, le minist\u00e8re de J\u00e9sus d\u00e9montre le d\u00e9sir de Dieu de nous gu\u00e9rir. J\u00e9sus gu\u00e9rissait les malades, chassait les d\u00e9mons et ressuscitait les morts, montrant ainsi sa puissance et son autorit\u00e9 sur la maladie et le mal. Cependant, le minist\u00e8re de gu\u00e9rison de J\u00e9sus ne se r\u00e9sumait pas \u00e0 une simple d\u00e9monstration de puissance, il \u00e9tait principalement l&rsquo;expression de l&rsquo;amour et de la compassion de Dieu pour l&rsquo;humanit\u00e9. Dans Matthieu 9:35, il est \u00e9crit: \u00ab\u00a0J\u00e9sus parcourait toutes les villes et les villages, enseignant dans les synagogues, pr\u00eachant la bonne nouvelle du royaume, et gu\u00e9rissant toute maladie et toute infirmit\u00e9\u00a0\u00bb (italiques sont n\u00f4tres). Le minist\u00e8re de gu\u00e9rison de J\u00e9sus faisait partie de sa mission plus large de proclamer le Royaume de Dieu et de r\u00e9tablir toutes les dimensions de nos vie. J\u00e9sus est ressucit\u00e9, il est vivant et continue d\u2019oeuvrer pour notre salut. Ses \u0153uvres ne se limitent pas \u00e0 la gu\u00e9rison physique, elles englobent \u00e9galement notre bien-\u00eatre spirituel, mental et \u00e9motionnel. J\u00e9sus veut pardonner nos p\u00e9ch\u00e9s, gu\u00e9rir nos relations et redonner espoir \u00e0 ceux et celles qui en ont besoin. Pierre-Alain Giffard, Coordonnateur de la pastorale dioc\u00e9saine Livre sur la revitalisation et la croissance des paroisses PAROISSES VIVANTES : Guide pratique pour la transformation missionnaire des communaut\u00e9s chr\u00e9tiennes (Pr\u00e9face de Mgr Damphousse) Autres articles et ressources pour l&rsquo;\u00e9vang\u00e9lisation et le renouveau des paroisses : L\u2019\u00e9vang\u00e9lisation : Partager la Joie, la Paix et l\u2019Esp\u00e9rance du Christ Une pri\u00e8re pour ceux et celles que nous esp\u00e9rons voir rencontrer le Christ Leadership sacerdotal dans l\u2019\u00e9vang\u00e9lisation L\u2019\u00e9vang\u00e9lisation autour d\u2019un caf\u00e9 \u00e0 l\u2019Universit\u00e9 de Mary Washington L\u2019\u00c9vang\u00e9lisation : Un T\u00e9moignage Vivant de l\u2019Amour Divin Vivre de la joie de l\u2019\u00c9vangile Au Commencement \u00c9tait le Verbe: Le R\u00f4le Essentiel des \u00c9critures dans l\u2019\u00c9vang\u00e9lisation \u00c9vang\u00e9liser avec quelques mots Demander chaque jour la gr\u00e2ce d\u2019aider quelqu\u2019un La paroisse comme expression de l\u2019amour de Dieu pour le monde Si personne ne parle, personne ne saura \u00c9vang\u00e9liser par la gu\u00e9rison : manifester la pr\u00e9sence aimante de Dieu La Parabole du Sage Propri\u00e9taire Signes Extraordinaires au Quotidien Le message \u00e9vang\u00e9lisateur de Medjugorje La diff\u00e9rence entre le pros\u00e9lytisme et l\u2019\u00e9vang\u00e9lisation authentique Ce que Dieu [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":12004,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[84,153,156],"tags":[],"class_list":["post-12007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","category-prier","category-textes-a-lire"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/12007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/comments?post=12007"}],"version-history":[{"count":23,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/12007\/revisions"}],"predecessor-version":[{"id":16205,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/12007\/revisions\/16205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media\/12004"}],"wp:attachment":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media?parent=12007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/categories?post=12007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/tags?post=12007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}