{"id":13458,"date":"2023-11-07T10:50:02","date_gmt":"2023-11-07T15:50:02","guid":{"rendered":"https:\/\/pembrokediocese.com\/?p=13458"},"modified":"2023-12-04T16:21:15","modified_gmt":"2023-12-04T21:21:15","slug":"bulletin-hebdomadaire-le-7-novembre-2023-ferie","status":"publish","type":"post","link":"https:\/\/pembrokediocese.com\/fr\/article\/bulletin-hebdomadaire-le-7-novembre-2023-ferie\/","title":{"rendered":"BULLETIN HEBDOMADAIRE  &#8211; le 7 novembre 2023 (F\u00e9rie)"},"content":{"rendered":"<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n\r\n\r\n<h4 class=\"wp-block-heading\"><strong><i><a href=\"mailto:reception@pembrokediocese.com?subject=Abonnez-vous au bulletin hebdomadaire&amp;amp;body=Bonjour, je souhaite m'abonner au Bulletin Hebdomadaire s'il vous plait. Merci.\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-8004\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr-200x205.png\" alt=\"\" width=\"124\" height=\"127\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr-200x205.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr-768x785.png 768w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr.png 840w\" sizes=\"(max-width: 124px) 100vw, 124px\" \/><\/a><\/i><\/strong><\/h4>\r\n\r\n\r\n\r\n<h1 class=\"wp-block-heading\"><em><strong>Va sur les routes et dans les sentiers, et fais entrer les gens de force, afin que ma maison soit remplie.<\/strong><\/em><\/h1>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>(Luc 14, 15-24)<\/strong><\/h3>\r\n\r\n\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><strong>DU DIOC\u00c8SE<\/strong><\/h2>\r\n<h3><strong>Installation de Mgr Guy Desrochers\u00a0<\/strong><\/h3>\r\n<p>La messe d&rsquo;installation du 18 octobre 2023 de Mgr Guy Desrochers, archev\u00eaque de Moncton, (version abr\u00e9g\u00e9e) peut maintenant \u00eatre visionn\u00e9e sur YouTube\u00a0: <a href=\"https:\/\/www.youtube.com\/watch?v=r6wX0YmYz64&amp;t=5s\">Installation 18 Octobre 2023 &#8211; YouTube<\/a><\/p>\r\n<h3><strong>Administrateur dioc\u00e9sain\u00a0<\/strong><\/h3>\r\n<p>\u00c0 la suite de l&rsquo;installation de Mgr Guy Desrochers, C.Ss.R., comme archev\u00eaque de Moncton le 18 octobre 2023, le Coll\u00e8ge des consulteurs du dioc\u00e8se de Pembroke a \u00e9lu, le 19 octobre 2023, le p\u00e8re George Ryan Holly comme administrateur dioc\u00e9sain de Pembroke, conform\u00e9ment au droit canonique (c. 421 \u00a71).<\/p>\r\n<h3><strong>Nomination pastorale\u00a0<\/strong><\/h3>\r\n<p>Avant son installation \u00e0 Moncton, Mgr Desrochers a autoris\u00e9 le diacre Christopher Barrett \u00e0 exercer son minist\u00e8re diaconal dans l&rsquo;archidioc\u00e8se d&rsquo;Ottawa-Cornwall. Le diacre Chris a \u00e9t\u00e9 affect\u00e9 par Mgr Marcel Damphousse \u00e0 la paroisse Sainte-Croix d&rsquo;Ottawa <strong>\u00e0 compter du 2 novembre 2023.<\/strong><\/p>\r\n\r\n\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n\r\n\r\n\r\n\r\n<h2><strong>LE SYNODE<\/strong><\/h2>\r\n<h3><strong>Nouvelles du Synode (27-10-2023)\u00a0<\/strong><\/h3>\r\n<p>La XVI\u00e8me Assembl\u00e9e g\u00e9n\u00e9rale ordinaire du Synode des \u00e9v\u00eaques s\u2019est r\u00e9cemment achev\u00e9e et, dans une lettre adress\u00e9e au Peuple de Dieu. (<a href=\"https:\/\/www.synod.va\/content\/dam\/synod\/news\/2023-10-25_letter_to_the_people_of_god\/FRA-2023.10.25-Lettera-al-Popolo-di-Dio.docx\">https:\/\/www.synod.va\/content\/dam\/synod\/news\/2023-10-25_letter_to_the_people_of_god\/ENG_2023.10.25-Lettera-al-Popolo-di-Dio.docx<\/a>)<\/p>\r\n<p>L\u2019assembl\u00e9e a soulign\u00e9 l\u2019importance de la conversion pastorale et missionnaire, en insistant sur le \u00a0 \u00a0que son r\u00f4le est de proclamer l\u2019\u00c9vangile et de servir l\u2019amour de Dieu pour le monde. La centralit\u00e9 de l\u2019amour, en particulier l\u2019amour Trinitaire et Eucharistique, a \u00e9t\u00e9 soulign\u00e9e. L\u2019\u00c9glise esp\u00e8re encourager la communion missionnaire et la synodalit\u00e9 parmi ses membres, en soulignant la n\u00e9cessit\u00e9 d\u2019un engagement authentique de la part de tous et de toutes.<\/p>\r\n<p>Pour y parvenir, le document pr\u00e9cise, l\u2019\u00c9glise doit \u00e9couter toutes les voix, en particulier celles des personnes marginalis\u00e9es et des victimes d\u2019abus dans ses rangs. Elle doit \u00e9galement s\u2019engager aupr\u00e8s des la\u00efcs et des familles. La voix proph\u00e9tique de la vie consacr\u00e9e et de ceux et celles qui recherchent la v\u00e9rit\u00e9 ne doit pas \u00eatre ignor\u00e9e. <a href=\"https:\/\/pembrokediocese.com\/fr\/synode\/\">(Lire la suite\u2026)<\/a><\/p>\r\n<p>\r\n\r\n<\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p>\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<h2 class=\"wp-block-heading\"><strong>DE LA CECC<\/strong><\/h2>\r\n<h3><strong>Nomination \u00e9piscopale pour le dioc\u00e8se de Bathurst<\/strong><\/h3>\r\n<p><strong>28 octobre 2023<\/strong>\u00a0\u2013 Sa Saintet\u00e9 le pape Fran\u00e7ois a nomm\u00e9 le P\u00e8re Michel Proulx, O. Praem., \u00e9v\u00eaque de Bathurst. Au moment de sa nomination, le P\u00e8re Proulx \u00e9tait Prieur du Monast\u00e8re des Pr\u00e9montr\u00e9s de St-Constant (Qu\u00e9bec) depuis 2008. <a href=\"https:\/\/www.cecc.ca\/communique-de-presse\/nomination-episcopale-pour-le-diocese-de-bathurst\/\">(Lire la suite\u2026)<\/a><\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p>\r\n\r\n<\/p>\r\n<h2 class=\"wp-block-heading\"><strong>V\u00c9RIT\u00c9 ET R\u00c9CONCILIATION<\/strong><\/h2>\r\n<p>\r\n\r\n\r\n\r\n<\/p>\r\n<h3><strong>Droits des peuples autochtones\u00a0 <\/strong><\/h3>\r\n<ol>\r\n<li>Il ne peut y avoir d\u2019activit\u00e9s militaires sur les terres ou territoires des peuples autochtones, \u00e0 moins que ces activit\u00e9s ne soient justifi\u00e9es par des raisons d\u2019int\u00e9r\u00eat public ou qu\u2019elles n\u2019aient \u00e9t\u00e9 librement d\u00e9cid\u00e9es en accord avec les peuples autochtones concern\u00e9s, ou demand\u00e9es par ces derniers.<\/li>\r\n<li>Les \u00c9tats engagent des consultations effectives avec les peuples autochtones concern\u00e9s, par le biais de proc\u00e9dures appropri\u00e9es et, en particulier, par l\u2019interm\u00e9diaire de leurs institutions repr\u00e9sentatives, avant d\u2019utiliser leurs terres et territoires pour des activit\u00e9s militaires.<\/li>\r\n<\/ol>\r\n<p><em>Article 30 \u2013 D\u00e9claration des Nations unies sur les droits des peuples autochtones.<\/em><\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p>\r\n\r\n<\/p>\r\n<h2 class=\"wp-block-heading\"><strong>L\u2019\u00c9QUIPE D\u2019\u00c9VANG\u00c9LISATION<\/strong><\/h2>\r\n<p>\r\n\r\n\r\n\r\n<\/p>\r\n<h3 class=\"wp-block-heading\"><strong>Cr\u00e9er des communaut\u00e9s Catholiques Dynamiques\u00a0: Sagesse tir\u00e9e du livre <em>\u2018Excellent Catholic <\/em><em>Parishes\u2019<\/em> <\/strong><\/h3>\r\n<p><em>Par Pierre-Alain Giffard, directeur de la pastorale dioc\u00e9saine<\/em><\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>Selon le livre\u00a0Excellent Catholic Parishes : The Guide to Best Places and Practices,\u00a0\u00e9crit par Paul Wilkes (2001), plusieurs facteurs peuvent aider une paroisse catholique \u00e0 devenir une communaut\u00e9 vivante et dynamique. Ces facteurs sont le r\u00e9sultat de recherches approfondies men\u00e9es par l\u2019auteur, Paul Wilkes, et son \u00e9quipe de chercheurs, Marty Minchin et Melanie Bruce. L\u2019\u00e9quipe a visit\u00e9 des centaines de paroisses catholiques \u00e0 travers les \u00c9tats-Unis, menant des entretiens avec les pasteurs, le personnel et les paroissiens, et observant les divers programmes et initiatives mis en place. <a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/creer-des-communautes-catholiques-dynamiques-sagesse-tiree-du-livre-excellent-catholic-parishes\/\">(Lire la suite\u2026)<\/a><\/p>\r\n<p>\r\n\r\n<\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<h2 class=\"wp-block-heading\"><strong>LE SAINT-SI\u00c8GE<\/strong><\/h2>\r\n<h3><strong>Intention de pri\u00e8re du Saint-P\u00e8re pour le mois de novembre 2023\u00a0<\/strong><\/h3>\r\n<p><strong>Pour le Pape<\/strong>\u2013 Prions pour le Pape, afin que, dans l\u2019exercice de sa mission, il continue \u00e0 accompagner dans la foi le troupeau qui lui est confi\u00e9, avec l\u2019aide de l\u2019Esprit Saint.<\/p>\r\n<p>\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p>\r\n\r\n\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p><\/p>\r\n<h2 class=\"wp-block-heading\"><strong>AUTRES\u00a0<\/strong><\/h2>\r\n<h3><strong>Programme de conf\u00e9rences\u00a0<\/strong><\/h3>\r\n<p>Le CDEVS (Centre Dominicain d&rsquo;\u00c9thique et de Vie Spirituelle) est tr\u00e8s heureuse de vous proposer son nouveau programme de conf\u00e9rences pour ce d\u00e9but d\u2019ann\u00e9e acad\u00e9mique! 3 conf\u00e9rences reparties en 2 cycles vous sont offertes gratuitement en ligne :<\/p>\r\n<p><strong>C<\/strong><strong>ycle<\/strong> <strong>s<\/strong><strong>ur la vie spirituelle\u00a0: \u00ab\u00a0Consolation et esp\u00e9rance\u00a0\u00bb<\/strong><\/p>\r\n<ul>\r\n<li><em>\u00ab\u00a0Console-moi!\u00a0\u00bb <\/em>par Brigitte Quintal <strong>le mardi 21 novembre 2023<\/strong> \u00e0 19h30<\/li>\r\n<\/ul>\r\n<p><strong>Cycle sur l\u2019\u00e9thique des soins\u00a0: \u00ab\u00a0Relation d\u2019aide et aides \u00e0 la relation\u00a0\u00bb<\/strong><\/p>\r\n<ul>\r\n<li><em>\u00ab\u00a0Aide-moi!\u00a0\u00bb <\/em>par Thomas de Gabory <strong>le mardi 12 d\u00e9cembre 2023<\/strong> \u00e0 19h30<\/li>\r\n<\/ul>\r\n<p><a href=\"https:\/\/centredominicain.com\/events\/formation-test-la-dignite-restauree\/\">Inscrivez-vous d\u00e8s maintenant<\/a>, ou n\u2019h\u00e9sitez pas \u00e0 communiquer avec nous sur <a href=\"mailto:info@centredominicain.com\">info@centredominicain.com<\/a>. \u00a0<\/p>\r\n<p><!-- \/wp:post-content --><\/p>","protected":false},"excerpt":{"rendered":"<p>Va sur les routes et dans les sentiers, et fais entrer les gens de force, afin que ma maison soit remplie. (Luc 14, 15-24) DU DIOC\u00c8SE Installation de Mgr Guy Desrochers\u00a0 La messe d&rsquo;installation du 18 octobre 2023 de Mgr Guy Desrochers, archev\u00eaque de Moncton, (version abr\u00e9g\u00e9e) peut maintenant \u00eatre visionn\u00e9e sur YouTube\u00a0: Installation 18 Octobre 2023 &#8211; YouTube Administrateur dioc\u00e9sain\u00a0 \u00c0 la suite de l&rsquo;installation de Mgr Guy Desrochers, C.Ss.R., comme archev\u00eaque de Moncton le 18 octobre 2023, le Coll\u00e8ge des consulteurs du dioc\u00e8se de Pembroke a \u00e9lu, le 19 octobre 2023, le p\u00e8re George Ryan Holly comme administrateur dioc\u00e9sain de Pembroke, conform\u00e9ment au droit canonique (c. 421 \u00a71). Nomination pastorale\u00a0 Avant son installation \u00e0 Moncton, Mgr Desrochers a autoris\u00e9 le diacre Christopher Barrett \u00e0 exercer son minist\u00e8re diaconal dans l&rsquo;archidioc\u00e8se d&rsquo;Ottawa-Cornwall. Le diacre Chris a \u00e9t\u00e9 affect\u00e9 par Mgr Marcel Damphousse \u00e0 la paroisse Sainte-Croix d&rsquo;Ottawa \u00e0 compter du 2 novembre 2023. LE SYNODE Nouvelles du Synode (27-10-2023)\u00a0 La XVI\u00e8me Assembl\u00e9e g\u00e9n\u00e9rale ordinaire du Synode des \u00e9v\u00eaques s\u2019est r\u00e9cemment achev\u00e9e et, dans une lettre adress\u00e9e au Peuple de Dieu. (https:\/\/www.synod.va\/content\/dam\/synod\/news\/2023-10-25_letter_to_the_people_of_god\/ENG_2023.10.25-Lettera-al-Popolo-di-Dio.docx) L\u2019assembl\u00e9e a soulign\u00e9 l\u2019importance de la conversion pastorale et missionnaire, en insistant sur le \u00a0 \u00a0que son r\u00f4le est de proclamer l\u2019\u00c9vangile et de servir l\u2019amour de Dieu pour le monde. La centralit\u00e9 de l\u2019amour, en particulier l\u2019amour Trinitaire et Eucharistique, a \u00e9t\u00e9 soulign\u00e9e. L\u2019\u00c9glise esp\u00e8re encourager la communion missionnaire et la synodalit\u00e9 parmi ses membres, en soulignant la n\u00e9cessit\u00e9 d\u2019un engagement authentique de la part de tous et de toutes. Pour y parvenir, le document pr\u00e9cise, l\u2019\u00c9glise doit \u00e9couter toutes les voix, en particulier celles des personnes marginalis\u00e9es et des victimes d\u2019abus dans ses rangs. Elle doit \u00e9galement s\u2019engager aupr\u00e8s des la\u00efcs et des familles. La voix proph\u00e9tique de la vie consacr\u00e9e et de ceux et celles qui recherchent la v\u00e9rit\u00e9 ne doit pas \u00eatre ignor\u00e9e. (Lire la suite\u2026) V\u00c9RIT\u00c9 ET R\u00c9CONCILIATION Droits des peuples autochtones\u00a0 Il ne peut y avoir d\u2019activit\u00e9s militaires sur les terres ou territoires des peuples autochtones, \u00e0 moins que ces activit\u00e9s ne soient justifi\u00e9es par des raisons d\u2019int\u00e9r\u00eat public ou qu\u2019elles n\u2019aient \u00e9t\u00e9 librement d\u00e9cid\u00e9es en accord avec les peuples autochtones concern\u00e9s, ou demand\u00e9es par ces derniers. Les \u00c9tats engagent des consultations effectives avec les peuples autochtones concern\u00e9s, par le biais de proc\u00e9dures appropri\u00e9es et, en particulier, par l\u2019interm\u00e9diaire de leurs institutions repr\u00e9sentatives, avant d\u2019utiliser leurs terres et territoires pour des activit\u00e9s militaires. Article 30 \u2013 D\u00e9claration des Nations unies sur les droits des peuples autochtones. L\u2019\u00c9QUIPE D\u2019\u00c9VANG\u00c9LISATION Cr\u00e9er des communaut\u00e9s Catholiques Dynamiques\u00a0: Sagesse tir\u00e9e du livre \u2018Excellent Catholic Parishes\u2019 Par Pierre-Alain Giffard, directeur de la pastorale dioc\u00e9saine Selon le livre\u00a0Excellent Catholic Parishes : The Guide to Best Places and Practices,\u00a0\u00e9crit par Paul Wilkes (2001), plusieurs facteurs peuvent aider une paroisse catholique \u00e0 devenir une communaut\u00e9 vivante et dynamique. Ces facteurs sont le r\u00e9sultat de recherches approfondies men\u00e9es par l\u2019auteur, Paul Wilkes, et son \u00e9quipe de chercheurs, Marty Minchin et Melanie Bruce. L\u2019\u00e9quipe a visit\u00e9 des centaines de paroisses catholiques \u00e0 travers les \u00c9tats-Unis, menant des entretiens avec les pasteurs, le personnel et les paroissiens, et observant les divers programmes et initiatives [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":3815,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[114,84,156],"tags":[],"class_list":["post-13458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bulletin","category-article","category-textes-a-lire"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/13458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/comments?post=13458"}],"version-history":[{"count":3,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/13458\/revisions"}],"predecessor-version":[{"id":13640,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/13458\/revisions\/13640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media\/3815"}],"wp:attachment":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media?parent=13458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/categories?post=13458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/tags?post=13458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}