{"id":13518,"date":"2023-11-15T08:17:53","date_gmt":"2023-11-15T13:17:53","guid":{"rendered":"https:\/\/pembrokediocese.com\/?p=13518"},"modified":"2023-12-04T16:21:14","modified_gmt":"2023-12-04T21:21:14","slug":"la-transformation-missionnaire-de-la-paroisse-de-santeustorgio","status":"publish","type":"post","link":"https:\/\/pembrokediocese.com\/fr\/article\/la-transformation-missionnaire-de-la-paroisse-de-santeustorgio\/","title":{"rendered":"Article: La transformation missionnaire de la paroisse de Sant&rsquo;Eustorgio"},"content":{"rendered":"\r\n<p><span style=\"font-weight: 400;\">Lorsque Don Pigi a \u00e9t\u00e9 nomm\u00e9 cur\u00e9 de la paroisse de Sant&rsquo;Eustorgio (Italie), seuls 12 % des paroissiens assistaient \u00e0 la messe du dimanche. Don Pigi se sentait d\u00e9courag\u00e9 et enferm\u00e9 dans la routine, incapable d&rsquo;\u00e9tablir un lien significatif avec sa communaut\u00e9 paroissiale.\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">La situation a chang\u00e9 lorsqu&rsquo;il a pris connaissance du renouveau paroissial en cours \u00e0 Saint-Boniface, en Floride, sous l&rsquo;\u00e9gide du p\u00e8re Michel Eivers. Boniface avait des cellules d&rsquo;\u00e9vang\u00e9lisation paroissiales florissantes &#8211; des petits groupes se r\u00e9unissant chaque semaine chez les membres pour prier, partager des exp\u00e9riences de vie et grandir dans la foi.\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Don Pigi s&rsquo;est rendu compte que l&rsquo;engagement des la\u00efcs dans les efforts d&rsquo;\u00e9vang\u00e9lisation \u00e9tait la cl\u00e9 de la revitalisation de sa paroisse. Don Pigi a introduit le mod\u00e8le des cellules dans sa paroisse apr\u00e8s avoir form\u00e9 des responsables la\u00efcs. Les cellules se concentrent sur le d\u00e9veloppement d&rsquo;une relation personnelle avec J\u00e9sus, la pri\u00e8re, le soutien mutuel et le partage de la foi dans la vie quotidienne et dans les r\u00e9seaux.\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Les membres des cellules ont \u00e9t\u00e9 encourag\u00e9s \u00e0 \u00eatre des \u00ab\u00a0p\u00eacheurs d&rsquo;hommes\u00a0\u00bb, \u00e0 t\u00e9moigner par leurs actions et \u00e0 partager la fa\u00e7on dont le Christ a chang\u00e9 leur vie. Les cellules se sont multipli\u00e9es au fur et \u00e0 mesure que les membres en invitaient d&rsquo;autres. Elles sont rest\u00e9es connect\u00e9es \u00e0 l&rsquo;ensemble de la paroisse gr\u00e2ce \u00e0 des liens structur\u00e9s de leadership.\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Don Pigi a transform\u00e9 la paroisse en une communaut\u00e9 accueillante, guid\u00e9e par l&rsquo;Esprit, o\u00f9 les gens pouvaient faire l&rsquo;exp\u00e9rience de l&rsquo;amour de Dieu et le partager. Cependant, il savait que le renouvellement de la communaut\u00e9 n\u00e9cessitait plus que de simples petits groupes. Il a offert aux membres une formation continue sur la pri\u00e8re, l&rsquo;attention aux autres et le t\u00e9moignage. Il voulait que la communaut\u00e9 aille au-del\u00e0 de la connaissance de t\u00eate et qu&rsquo;elle ait une foi vivante issue de la rencontre personnelle avec le Christ. Cela n\u00e9cessitait une exp\u00e9rience permanente de Dieu \u00e0 travers la pri\u00e8re, les \u00c9critures, les sacrements et le service. La foi s&rsquo;acquiert plus qu&rsquo;elle ne s&rsquo;enseigne.\u00a0<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Don Pigi a enseigne que la v\u00e9ritable \u00e9vang\u00e9lisation consiste \u00e0 donner l&rsquo;exemple de la mis\u00e9ricorde de Dieu et \u00e0 t\u00e9moigner de l&rsquo;impact concret de J\u00e9sus sur la vie d&rsquo;une personne. Il s&rsquo;agit d&rsquo;une invitation \u00e0 la relation, et non d&rsquo;arguments convaincants. Les personnes transform\u00e9es par le Christ peuvent transformer les autres.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Gr\u00e2ce \u00e0 l&rsquo;adoration Eucharistique, aux cellules paroissiales et \u00e0 l&rsquo;accent mis sur l&rsquo;\u00e9vang\u00e9lisation, la paroisse Sant&rsquo;Eustorgio a \u00e9t\u00e9 renouvel\u00e9e, les membres se soutenant mutuellement dans la vie et le partage d&rsquo;une foi vibrante.\u00a0<\/span><\/p>\r\n<p><strong>En savoir plus sur les cellules paroissiales d&rsquo;\u00e9vang\u00e9lisation<\/strong><\/p>\r\n<ul>\r\n<li><a href=\"https:\/\/www.cellules-evangelisation.org\/demarrer-les-cellules-en-paroisse\/comment-demarrer\/\"><span style=\"font-weight: 400;\">Comment d\u00e9marrer ?<\/span><\/a><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-cellules-paroissiales-devangelisation\/\"><span style=\"font-weight: 400;\">Les cellules paroissiales d&rsquo;\u00e9vang\u00e9lisation dans la paroisse de Saint-Boniface<\/span><\/a><\/li>\r\n<\/ul>\r\n<p class=\"has-text-align-right\">\r\n\r\n<\/p>\r\n<p style=\"text-align: right;\">Pierre-Alain Giffard<\/p>\r\n<p><strong>Autres articles sur l&rsquo;\u00e9vang\u00e9lisation et le renouveau des paroisses :<\/strong><\/p>\r\n<ul>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/creer-des-communautes-catholiques-dynamiques-sagesse-tiree-du-livre-excellent-catholic-parishes\/\"><strong class=\"post-title\">Cr\u00e9er des Communaut\u00e9s Catholiques Dynamiques : Sagesse tir\u00e9e du livre \u2018Excellent Catholic Parishes\u2019<\/strong><\/a><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/partager-levangile-en-fonction-des-besoins-et-de-la-receptivite-des-gens\/\"><strong class=\"post-title\">Partager l\u2019\u00c9vangile en fonction des besoins et de la r\u00e9ceptivit\u00e9 des gens<\/strong><\/a><\/strong><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-priere-pour-inviter-des-personnes-a-des-rencontres-devangelisation\/\">Une pri\u00e8re pour inviter des personnes \u00e0 des rencontres d\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/accueillir-les-invites-et-les-visiteurs-a-leglise\/\">Accueillir les invit\u00e9s et les visiteurs \u00e0 l\u2019\u00e9glise: les choses \u00e0 faire et \u00e0 ne pas faire<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/caracteristiques-dune-paroisse-evangelisatrice\/\">Caract\u00e9ristiques d\u2019une paroisse \u00e9vang\u00e9lisatrice<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/differentes-dimensions-de-levangelisation\/\">Diff\u00e9rentes dimensions de l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-la-vraie-mesure-du-succes\/\"><strong class=\"post-title\">La vraie mesure du succ\u00e8s<\/strong><\/a><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/article-le-pape-francois-sur-levangelisation\/\">Le pape Francois sur l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/reveiller-la-paroisse-rurale-pour-levangelisation\/\">R\u00e9veiller la paroisse rurale pour l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quest-ce-qui-amene-les-gens-au-christ\/\">Qu\u2019est-ce qui am\u00e8ne les gens au Christ ?<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-evangeliser-par-des-petits-actes-de-gentillesse\/\">\u00c9vang\u00e9liser par des petits actes de gentillesse<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-des-questions-pour-entamer-des-conversations-spirituelles\/\"><strong class=\"post-title\">Des questions pour entamer des conversations spirituelles<\/strong><\/a><\/li>\r\n<li><strong class=\"post-title\"><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/a-trois-pieds-de-lor\/\">\u00c0 trois pieds de l\u2019or<\/a><\/strong><\/strong><\/li>\r\n<li><strong class=\"post-title\"><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/evangeliser-a-travers-nos-interactions-sociales\/\">\u00c9vang\u00e9liser en d\u00e9veloppant nos comp\u00e9tences sociales<\/a><\/strong><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/rassembler-temoigner-et-inviter\/\">Rassembler, t\u00e9moigner et inviter<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/priere-pour-recevoir-les-dons-spirituels-du-saint-esprit\/\"><strong class=\"post-title\">Pri\u00e8re pour recevoir les dons spirituels du Saint Esprit<\/strong><\/a><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-langage-de-la-croix-la-voix-de-levangelisation\/\">Le langage de la croix est le langage de l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-facteurs-cles-pour-la-croissance-de-la-paroisse\/\">Facteurs cl\u00e9s pour la croissance de la paroisse selon Rich Birch<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-comment-vaincre-satan\/\"><strong class=\"post-title\">Comment vaincre Satan ?<\/strong><\/a><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/apporter-amour-espoir-et-guerison-par-levangile\/\"><strong class=\"post-title\">Apporter Amour, Espoir et Gu\u00e9rison par l\u2019\u00c9vangile<\/strong><\/a><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-quest-ce-que-lamour\/\"><strong class=\"post-title\">Qu\u2019est-ce que l\u2019amour ?<\/strong><\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-touche-par-le-maitre\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Touch\u00e9 par le Ma\u00eetre<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-un-homme-un-chien-et-lamour-ultime\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Un homme, un chien, et l\u2019amour ultime<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/des-facons-pratiques-daimer-les-autres\/\"><strong>A<\/strong><\/a><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/des-facons-pratiques-daimer-les-autres\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>u c\u0153ur de l\u2019\u00e9vang\u00e9lisation : Aimer Dieu et les autres<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/aimer-nos-ennemis-et-se-reconcilier-avec-les-autres\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Aimer nos ennemis et se r\u00e9concilier avec les autres<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-priere-bibique-pour-la-guerison\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pri\u00e8re pour la gu\u00e9rison : Tu es le Seigneur qui me gu\u00e9rit<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-vivre-une-vie-damour-lheritage-de-mere-teresa\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Vivre une vie d\u2019amour : L\u2019h\u00e9ritage de M\u00e8re Teresa<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-force-puissante-est-a-loeuvre\/\"><strong>Sous le <\/strong><\/a><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-force-puissante-est-a-loeuvre\/\" target=\"_blank\" rel=\"noreferrer noopener\">c<\/a><\/strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-force-puissante-est-a-loeuvre\/\"><strong>ouvert des t\u00e9n\u00e8bres, une force puissante est \u00e0 l\u2019\u0153uvre<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-evangeliser-avec-amour-et-pour-lamour\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Vivre une vie d\u2019amour : Le\u00e7ons du Nouveau Testament<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/19-orientations-pastorales-pour-le-renouveau-et-la-croissance-des-paroisses\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>19 orientations pastorales qui contribuent \u00e0 la croissance des paroisses<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-renouveau-missionnaire-de-la-catechese\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Le renouveau missionnaire de la cat\u00e9ch\u00e8se<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/les-caracteristiques-des-paroisses-missionnaires\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Les caract\u00e9ristiques des paroisses missionnaires<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/partager-notre-foi\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pri\u00e8re de gu\u00e9rison attribu\u00e9e \u00e0 saint Padre Pio<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/partager-notre-foi\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Nous sommes appel\u00e9s \u00e0 partager notre foi avec les autres<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/devrait-on-chercher-la-croissance-de-leglise\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Devrait-on chercher la croissance de l\u2019\u00c9glise ?<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/trouvez-un-besoin-et-comblez-le\/\" target=\"_blank\" rel=\"noreferrer noopener\">Trouvez un besoin et comblez-le : R\u00e9v\u00e9ler le c\u0153ur de Dieu dans son quartier<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/evangeliser-au-quotidien\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>15 habitudes pour \u00e9vang\u00e9liser au quotidien<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-mission-de-leglise\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>La mission de l\u2019\u00c9glise<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/trois-obstacles-a-letablissement-dune-culture-dinvitation-dans-votre-paroisse\/\" target=\"_blank\" rel=\"noreferrer noopener\">Trois obstacles \u00e0 l\u2019\u00e9tablissement d\u2019une culture d\u2019invitation dans votre paroisse<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisateur-relationnel\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>L\u2019\u00e9vang\u00e9lisateur relationnel<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/faire-eglise-a-la-maison\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Faire \u00c9glise \u00e0 la maison<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-fille-aveugle\/\" target=\"_blank\" rel=\"noreferrer noopener\">La fille aveugle<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/un-groupe-de-gernouilles\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Un groupe de grenouilles<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/lelephant-attache\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>L\u2019\u00e9l\u00e9phant attach\u00e9<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/paroisse-de-la-nativite\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Le renouveau de la paroisse de la Nativit\u00e9 \u00e0 Baltimore<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-foi-grandit-copy\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>La foi grandit lorsqu\u2019on la partage<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/dans-les-souliers-des-sans-eglises\/\" target=\"_blank\" rel=\"noreferrer noopener\">Dans les souliers des \u201csans-\u00e9glises\u201d<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-cellules-paroissiales-devangelisation-2-copy\/\" target=\"_blank\" rel=\"noreferrer noopener\">Les cellules paroissiales d\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/caracteristiques-uniques-des-paroisses-missionnaires\/\" target=\"_blank\" rel=\"noreferrer noopener\">Six caract\u00e9ristiques uniques des paroisses missionnaires<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/devenir-une-paroisse-missionnaire\/\" target=\"_blank\" rel=\"noreferrer noopener\">Quelques \u00e9tapes pour devenir une paroisse missionnaire<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quest-ce-que-levangelisation\/\" target=\"_blank\" rel=\"noreferrer noopener\">Qu\u2019est-ce que l\u2019\u00e9vang\u00e9lisation et dans quel esprit la pratiquer ?<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/auto-evaluation\/\" target=\"_blank\" rel=\"noreferrer noopener\">Questions de discussion et d\u2019auto-\u00e9valuation pour l\u2019\u00e9vang\u00e9lisation en paroisse<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-priere-de-jesus\/\" target=\"_blank\" rel=\"noreferrer noopener\">La pri\u00e8re de J\u00e9sus: une m\u00e9thode pour prier en tout temps<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/pratiquer-leur-foi\/\" target=\"_blank\" rel=\"noreferrer noopener\">Qu\u2019est-ce qui peut aider les enfants \u00e9lev\u00e9s dans la religion catholique \u00e0 continuer \u00e0 pratiquer leur foi \u00e0 l\u2019\u00e2ge adulte ?<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-tactiques-de-satan-1ere-partie\/\" target=\"_blank\" rel=\"noreferrer noopener\">Les tactiques de Satan<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/apprendre-a-etre-missionnaire\/\" target=\"_blank\" rel=\"noreferrer noopener\">Apprendre \u00e0 \u00eatre missionnaire<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quand-nous-crions-vers-dieu\/\" target=\"_blank\" rel=\"noreferrer noopener\">Quand nous crions vers Dieu, il r\u00e9pond<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent-copy\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pr\u00e9sence et Proclamation<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sauver ceux qui se perdent<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-paroisse-saint-nazaire-lhistoire-dune-transformation-missionnaire\/\" target=\"_blank\" rel=\"noreferrer noopener\">La paroisse Saint-Nazaire: L\u2019histoire d\u2019une transformation missionnaire<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/evangelisation-et-petits-groupes-de-partage\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9vang\u00e9lisation et petits groupes de partage<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/evangeliser-en-invitant-des-personnes-a-recevoir-jesus-comme-seigneur-et-sauveur\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9vang\u00e9liser en invitant des personnes \u00e0 recevoir J\u00e9sus comme Seigneur et Sauveur<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/vous-allez-recevoir-une-force\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vous allez recevoir une force\u2026<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/avez-vous-entendu-parler-de-la-loi-des-trois-ecoutes-et-des-sept-contacts\/\" target=\"_blank\" rel=\"noreferrer noopener\">Avez-vous entendu parler de la loi des trois \u00e9coutes et des sept contacts ?<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/trois-habitudes-dune-vie-chretienne-fructueuse\/\" target=\"_blank\" rel=\"noreferrer noopener\">Trois habitudes d\u2019une vie chr\u00e9tienne fructueuse<\/a><\/strong><\/li>\r\n<\/ul>\r\n<p class=\"has-text-align-right\"><!-- \/wp:post-content -->\r\n\r\n<!-- wp:separator --><\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p class=\"has-text-align-right\"><!-- \/wp:separator -->\r\n\r\n<!-- wp:shortcode --><\/p>\r\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\"> <a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1993 size-full\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying-100x100.png 100w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\r\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\">LECTURES RECOMMANDEES<\/a><\/h4>\r\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\" target=\"_self\" >En savoir plus <\/a>\r\n<\/div>\r\n<p class=\"has-text-align-right\"><!-- \/wp:shortcode -->\r\n\r\n<!-- wp:shortcode --><\/p>\r\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\"> <a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/prayer-group\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3620\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-300x300.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-300x300.png 300w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-100x100.png 100w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-400x400.png 400w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-210x210.png 210w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle.png 684w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\r\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/prayer-group\/\">PRI\u00c8RES ET GROUPES DE PRIERE POUR LE PROJET DIOC\u00c9SAIN DE NOUVELLE \u00c9VANG\u00c9LISATION<\/a><\/h4>\r\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"\/fr\/nouvelle-evangelisation\/prayer-group\/\" target=\"_self\" >En savoir plus<\/a>\r\n<\/div>\r\n<p class=\"has-text-align-right\"><!-- \/wp:shortcode -->\r\n\r\n<!-- wp:shortcode --><\/p>\r\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\"> <a href=\"https:\/\/pembrokediocese.com\/donate\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7117 size-medium aligncenter\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-200x200.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-200x200.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-768x768.png 768w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-100x100.png 100w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-400x400.png 400w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-210x210.png 210w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept.png 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\r\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/donate\/\">DONNER POUR LE PROJET DIOC\u00c9SAIN DE NOUVELLE \u00c9VANG\u00c9LISATION<\/a><\/h4>\r\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"https:\/\/pembrokediocese.com\/donate\/\" target=\"_self\" >En savoir plus<\/a>\r\n<\/div>\r\n<p class=\"has-text-align-right\"><!-- \/wp:shortcode --><\/p>","protected":false},"excerpt":{"rendered":"<p>Lorsque Don Pigi a \u00e9t\u00e9 nomm\u00e9 cur\u00e9 de la paroisse de Sant&rsquo;Eustorgio (Italie), seuls 12 % des paroissiens assistaient \u00e0 la messe du dimanche. Don Pigi se sentait d\u00e9courag\u00e9 et enferm\u00e9 dans la routine, incapable d&rsquo;\u00e9tablir un lien significatif avec sa communaut\u00e9 paroissiale.\u00a0 La situation a chang\u00e9 lorsqu&rsquo;il a pris connaissance du renouveau paroissial en cours \u00e0 Saint-Boniface, en Floride, sous l&rsquo;\u00e9gide du p\u00e8re Michel Eivers. Boniface avait des cellules d&rsquo;\u00e9vang\u00e9lisation paroissiales florissantes &#8211; des petits groupes se r\u00e9unissant chaque semaine chez les membres pour prier, partager des exp\u00e9riences de vie et grandir dans la foi.\u00a0 Don Pigi s&rsquo;est rendu compte que l&rsquo;engagement des la\u00efcs dans les efforts d&rsquo;\u00e9vang\u00e9lisation \u00e9tait la cl\u00e9 de la revitalisation de sa paroisse. Don Pigi a introduit le mod\u00e8le des cellules dans sa paroisse apr\u00e8s avoir form\u00e9 des responsables la\u00efcs. Les cellules se concentrent sur le d\u00e9veloppement d&rsquo;une relation personnelle avec J\u00e9sus, la pri\u00e8re, le soutien mutuel et le partage de la foi dans la vie quotidienne et dans les r\u00e9seaux.\u00a0 Les membres des cellules ont \u00e9t\u00e9 encourag\u00e9s \u00e0 \u00eatre des \u00ab\u00a0p\u00eacheurs d&rsquo;hommes\u00a0\u00bb, \u00e0 t\u00e9moigner par leurs actions et \u00e0 partager la fa\u00e7on dont le Christ a chang\u00e9 leur vie. Les cellules se sont multipli\u00e9es au fur et \u00e0 mesure que les membres en invitaient d&rsquo;autres. Elles sont rest\u00e9es connect\u00e9es \u00e0 l&rsquo;ensemble de la paroisse gr\u00e2ce \u00e0 des liens structur\u00e9s de leadership.\u00a0 Don Pigi a transform\u00e9 la paroisse en une communaut\u00e9 accueillante, guid\u00e9e par l&rsquo;Esprit, o\u00f9 les gens pouvaient faire l&rsquo;exp\u00e9rience de l&rsquo;amour de Dieu et le partager. Cependant, il savait que le renouvellement de la communaut\u00e9 n\u00e9cessitait plus que de simples petits groupes. Il a offert aux membres une formation continue sur la pri\u00e8re, l&rsquo;attention aux autres et le t\u00e9moignage. Il voulait que la communaut\u00e9 aille au-del\u00e0 de la connaissance de t\u00eate et qu&rsquo;elle ait une foi vivante issue de la rencontre personnelle avec le Christ. Cela n\u00e9cessitait une exp\u00e9rience permanente de Dieu \u00e0 travers la pri\u00e8re, les \u00c9critures, les sacrements et le service. La foi s&rsquo;acquiert plus qu&rsquo;elle ne s&rsquo;enseigne.\u00a0 Don Pigi a enseigne que la v\u00e9ritable \u00e9vang\u00e9lisation consiste \u00e0 donner l&rsquo;exemple de la mis\u00e9ricorde de Dieu et \u00e0 t\u00e9moigner de l&rsquo;impact concret de J\u00e9sus sur la vie d&rsquo;une personne. Il s&rsquo;agit d&rsquo;une invitation \u00e0 la relation, et non d&rsquo;arguments convaincants. Les personnes transform\u00e9es par le Christ peuvent transformer les autres. Gr\u00e2ce \u00e0 l&rsquo;adoration Eucharistique, aux cellules paroissiales et \u00e0 l&rsquo;accent mis sur l&rsquo;\u00e9vang\u00e9lisation, la paroisse Sant&rsquo;Eustorgio a \u00e9t\u00e9 renouvel\u00e9e, les membres se soutenant mutuellement dans la vie et le partage d&rsquo;une foi vibrante.\u00a0 En savoir plus sur les cellules paroissiales d&rsquo;\u00e9vang\u00e9lisation Comment d\u00e9marrer ? Les cellules paroissiales d&rsquo;\u00e9vang\u00e9lisation dans la paroisse de Saint-Boniface Pierre-Alain Giffard Autres articles sur l&rsquo;\u00e9vang\u00e9lisation et le renouveau des paroisses : Cr\u00e9er des Communaut\u00e9s Catholiques Dynamiques : Sagesse tir\u00e9e du livre \u2018Excellent Catholic Parishes\u2019 Partager l\u2019\u00c9vangile en fonction des besoins et de la r\u00e9ceptivit\u00e9 des gens Une pri\u00e8re pour inviter des personnes \u00e0 des rencontres d\u2019\u00e9vang\u00e9lisation Accueillir les invit\u00e9s et les visiteurs \u00e0 l\u2019\u00e9glise: les choses \u00e0 faire et \u00e0 ne pas faire Caract\u00e9ristiques d\u2019une paroisse \u00e9vang\u00e9lisatrice Diff\u00e9rentes dimensions de l\u2019\u00e9vang\u00e9lisation La vraie mesure du succ\u00e8s Le pape [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":13516,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[84,156],"tags":[],"class_list":["post-13518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","category-textes-a-lire"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/13518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/comments?post=13518"}],"version-history":[{"count":3,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/13518\/revisions"}],"predecessor-version":[{"id":13521,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/13518\/revisions\/13521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media\/13516"}],"wp:attachment":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media?parent=13518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/categories?post=13518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/tags?post=13518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}