{"id":13636,"date":"2022-09-04T16:26:36","date_gmt":"2022-09-04T20:26:36","guid":{"rendered":"https:\/\/pembrokediocese.com\/?p=13636"},"modified":"2023-12-04T16:28:59","modified_gmt":"2023-12-04T21:28:59","slug":"article-la-paroisse-saint-nazaire-lhistoire-dune-transformation-missionnaire","status":"publish","type":"post","link":"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/article-la-paroisse-saint-nazaire-lhistoire-dune-transformation-missionnaire\/","title":{"rendered":"ARTICLE &#8211; La paroisse Saint-Nazaire: L\u2019histoire d\u2019une transformation missionnaire"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">L&rsquo;\u00e9glise Saint-Nazaire est un autre exemple de transformation missionnaire paroissiale.\u00a0 Situ\u00e9e \u00e0 Sanary-sur-Mer en France, elle changea de cur\u00e9 en 1994. \u00c0 son arriv\u00e9e, il constata que les fid\u00e8les \u00e9taient impliqu\u00e9s dans les activit\u00e9s de la paroisse, mais que la plupart de la communaut\u00e9 \u00e9tait compos\u00e9e de personnes \u00e2g\u00e9es.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Voulant que \u00e7a change, il emmena son vicaire paroissial et deux groupes de la\u00efcs visiter une paroisse missionnaire en Italie. Ils particip\u00e8rent aussi \u00e0 un s\u00e9minaire sur les petits groupes d\u2019\u00e9vang\u00e9lisation. \u00c0 son retour l\u2019\u00e9quipe d\u00e9cida de mettre en pratique ce qu\u2019ils avaient appris. En 1996, trois groupes d\u2019\u00e9vang\u00e9lisation furent form\u00e9s dans la paroisse, compos\u00e9 chacun de dix personnes. Gr\u00e2ce aux efforts d\u2019\u00e9vang\u00e9lisation, ceux-ci commenc\u00e8rent \u00e0 grandir. Lorsqu\u2019un groupe se d\u00e9veloppait au-del\u00e0 de 10 personnes celui-ci \u00e9tait partag\u00e9 en deux pour se multiplier. En 2010, ils \u00e9taient plus d\u2019une centaine de paroissiens \u00e0 se r\u00e9unir hebdomadairement dans des maisons priv\u00e9es.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ces groupes se r\u00e9unissent une fois par semaine et leurs membres annoncent la Bonne Nouvelle dans leur milieu par la parole et le service. Ils prient pour ceux et celles qu&rsquo;ils \u00e9vang\u00e9lisent ainsi que pour les membres du groupe afin que ceux-ci acqui\u00e8rent une mentalit\u00e9 missionnaire.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Notons que l\u2019accent est mis non seulement sur les petits groupes, mais aussi sur la pri\u00e8re communautaire. Entre autres, l&rsquo;adoration du Saint-Sacrement a \u00e9t\u00e9 instaur\u00e9e dans une chapelle de la ville pour soutenir les efforts d\u2019\u00e9vang\u00e9lisation. Les paroissiens y assurent une permanence de pri\u00e8re 7 jours sur 7, jour et nuit.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Les membres des petits groupes s\u2019engagent aussi dans un minist\u00e8re paroissial : l\u2019accompagnement des familles en deuil, la liturgie, la cat\u00e9ch\u00e8se, les services aupr\u00e8s des pauvres, la chorale, la pr\u00e9paration au mariage, le secr\u00e9tariat, l\u2019accueil des fid\u00e8les avant les messes, etc.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pour cette \u00c9glise paroissiale qui s\u2019est inspir\u00e9e de l\u2019exp\u00e9rience milanaise (voir le bulletin dioc\u00e9sain du 21 juillet : <\/span><a href=\"https:\/\/pembrokediocese.com\/fr\/bulletin\/27-juillet-2021\/\"><span style=\"font-weight: 400;\">Un exemple d\u2019\u00e9vang\u00e9lisation en paroisse<\/span><\/a><span style=\"font-weight: 400;\">), les petits groupes et la pri\u00e8re ont permis \u00e0 ses membres de se renouveler de l&rsquo;int\u00e9rieur. Cela a aussi aid\u00e9 toute la communaut\u00e9 chr\u00e9tienne \u00e0 red\u00e9couvrir son identit\u00e9 missionnaire et la vie de tous ses membres a \u00e9t\u00e9 transform\u00e9e par une relation plus intime avec le Christ.<\/span><\/p>\n<p style=\"text-align: right;\"><i><span style=\"font-weight: 400;\">Par Pierre-Alain Giffard, directeur de la pastorale dioc\u00e9saine<\/span><\/i><\/p>\n<ul>\n<li class=\"post-title\"><strong>Autres articles sur l&rsquo;\u00e9vang\u00e9lisation et le renouveau des paroisses :<\/strong>\n<ul>\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/trois-obstacles-a-letablissement-dune-culture-dinvitation-dans-votre-paroisse\/\">Trois obstacles \u00e0 l\u2019\u00e9tablissement d\u2019une culture d\u2019invitation dans votre paroisse<\/a><\/strong><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisateur-relationnel\/\"><strong class=\"post-title\">L\u2019\u00e9vang\u00e9lisateur relationnel<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/faire-eglise-a-la-maison\/\"><strong class=\"post-title\">Faire \u00c9glise \u00e0 la maison<\/strong><\/a><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-fille-aveugle\/\">La fille aveugle<\/a><\/strong><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/un-groupe-de-gernouilles\/\"><strong>Un groupe de grenouilles<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/lelephant-attache\/\"><strong>L\u2019\u00e9l\u00e9phant attach\u00e9<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/paroisse-de-la-nativite\/\"><strong>Le renouveau de la paroisse de la Nativit\u00e9 \u00e0 Baltimore<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-foi-grandit-copy\/\"><strong>La foi grandit lorsqu\u2019on la partage<\/strong><\/a><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/dans-les-souliers-des-sans-eglises\/\">Dans les souliers des \u201csans-\u00e9glises\u201d<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-cellules-paroissiales-devangelisation-2-copy\/\">Les cellules paroissiales d\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/caracteristiques-uniques-des-paroisses-missionnaires\/\">Six caract\u00e9ristiques uniques des paroisses missionnaires<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/devenir-une-paroisse-missionnaire\/\">Quelques \u00e9tapes pour devenir une paroisse missionnaire<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quest-ce-que-levangelisation\/\">Qu\u2019est-ce que l\u2019\u00e9vang\u00e9lisation et dans quel esprit la pratiquer ?<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/auto-evaluation\/\">Questions de discussion et d\u2019auto-\u00e9valuation pour l\u2019\u00e9vang\u00e9lisation en paroisse<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-priere-de-jesus\/\">La pri\u00e8re de J\u00e9sus: une m\u00e9thode pour prier en tout temps<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/pratiquer-leur-foi\/\">Qu\u2019est-ce qui peut aider les enfants \u00e9lev\u00e9s dans la religion catholique \u00e0 continuer \u00e0 pratiquer leur foi \u00e0 l\u2019\u00e2ge adulte ?<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-tactiques-de-satan-1ere-partie\/\">Les tactiques de Satan<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/apprendre-a-etre-missionnaire\/\">Apprendre \u00e0 \u00eatre missionnaire<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quand-nous-crions-vers-dieu\/\">Quand nous crions vers Dieu, il r\u00e9pond<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent-copy\/\">Pr\u00e9sence et Proclamation<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent\/\">Sauver ceux qui se perdent<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-paroisse-saint-nazaire-lhistoire-dune-transformation-missionnaire\/\">La paroisse Saint-Nazaire: L\u2019histoire d\u2019une transformation missionnaire<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/evangelisation-et-petits-groupes-de-partage\/\">\u00c9vang\u00e9lisation et petits groupes de partage<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/evangeliser-en-invitant-des-personnes-a-recevoir-jesus-comme-seigneur-et-sauveur\/\">\u00c9vang\u00e9liser en invitant des personnes \u00e0 recevoir J\u00e9sus comme Seigneur et Sauveur<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/vous-allez-recevoir-une-force\/\">Vous allez recevoir une force\u2026<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/avez-vous-entendu-parler-de-la-loi-des-trois-ecoutes-et-des-sept-contacts\/\">Avez-vous entendu parler de la loi des trois \u00e9coutes et des sept contacts ?<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/trois-habitudes-dune-vie-chretienne-fructueuse\/\">Trois habitudes d\u2019une vie chr\u00e9tienne fructueuse<\/a><\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<div class=\"info\">\n<hr \/>\n<\/div>\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\">\n<p><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1993 size-full\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying-100x100.png 100w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\">LECTURES RECOMMANDEES<\/a><\/h4>\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\" target=\"_self\" >En savoir plus <\/a>\n<\/div>\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\">\n<p><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/prayer-group\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3620\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-300x300.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-300x300.png 300w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-100x100.png 100w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-400x400.png 400w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-210x210.png 210w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle.png 684w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/prayer-group\/\">PRI\u00c8RES ET GROUPES DE PRIERE POUR LE PROJET DIOC\u00c9SAIN DE NOUVELLE \u00c9VANG\u00c9LISATION<\/a><\/h4>\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"\/fr\/nouvelle-evangelisation\/prayer-group\/\" target=\"_self\" >En savoir plus<\/a>\n<\/div>\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\">\n<p><a href=\"https:\/\/pembrokediocese.com\/donate\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7117 size-medium aligncenter\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-200x200.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-200x200.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-768x768.png 768w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-100x100.png 100w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-400x400.png 400w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-210x210.png 210w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept.png 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/donate\/\">DONNER POUR LE PROJET DIOC\u00c9SAIN DE NOUVELLE \u00c9VANG\u00c9LISATION<\/a><\/h4>\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"https:\/\/pembrokediocese.com\/donate\/\" target=\"_self\" >En savoir plus<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9glise Saint-Nazaire est un autre exemple de transformation missionnaire paroissiale.\u00a0 Situ\u00e9e \u00e0 Sanary-sur-Mer en France, elle changea de cur\u00e9 en 1994. \u00c0 son arriv\u00e9e, il constata que les fid\u00e8les \u00e9taient impliqu\u00e9s dans les activit\u00e9s de la paroisse, mais que la plupart de la communaut\u00e9 \u00e9tait compos\u00e9e de personnes \u00e2g\u00e9es. Voulant que \u00e7a change, il emmena son vicaire paroissial et deux groupes de la\u00efcs visiter une paroisse missionnaire en Italie. Ils particip\u00e8rent aussi \u00e0 un s\u00e9minaire sur les petits groupes d\u2019\u00e9vang\u00e9lisation. \u00c0 son retour l\u2019\u00e9quipe d\u00e9cida de mettre en pratique ce qu\u2019ils avaient appris. En 1996, trois groupes d\u2019\u00e9vang\u00e9lisation furent form\u00e9s dans la paroisse, compos\u00e9 chacun de dix personnes. Gr\u00e2ce aux efforts d\u2019\u00e9vang\u00e9lisation, ceux-ci commenc\u00e8rent \u00e0 grandir. Lorsqu\u2019un groupe se d\u00e9veloppait au-del\u00e0 de 10 personnes celui-ci \u00e9tait partag\u00e9 en deux pour se multiplier. En 2010, ils \u00e9taient plus d\u2019une centaine de paroissiens \u00e0 se r\u00e9unir hebdomadairement dans des maisons priv\u00e9es. Ces groupes se r\u00e9unissent une fois par semaine et leurs membres annoncent la Bonne Nouvelle dans leur milieu par la parole et le service. Ils prient pour ceux et celles qu&rsquo;ils \u00e9vang\u00e9lisent ainsi que pour les membres du groupe afin que ceux-ci acqui\u00e8rent une mentalit\u00e9 missionnaire. Notons que l\u2019accent est mis non seulement sur les petits groupes, mais aussi sur la pri\u00e8re communautaire. Entre autres, l&rsquo;adoration du Saint-Sacrement a \u00e9t\u00e9 instaur\u00e9e dans une chapelle de la ville pour soutenir les efforts d\u2019\u00e9vang\u00e9lisation. Les paroissiens y assurent une permanence de pri\u00e8re 7 jours sur 7, jour et nuit. Les membres des petits groupes s\u2019engagent aussi dans un minist\u00e8re paroissial : l\u2019accompagnement des familles en deuil, la liturgie, la cat\u00e9ch\u00e8se, les services aupr\u00e8s des pauvres, la chorale, la pr\u00e9paration au mariage, le secr\u00e9tariat, l\u2019accueil des fid\u00e8les avant les messes, etc. Pour cette \u00c9glise paroissiale qui s\u2019est inspir\u00e9e de l\u2019exp\u00e9rience milanaise (voir le bulletin dioc\u00e9sain du 21 juillet : Un exemple d\u2019\u00e9vang\u00e9lisation en paroisse), les petits groupes et la pri\u00e8re ont permis \u00e0 ses membres de se renouveler de l&rsquo;int\u00e9rieur. Cela a aussi aid\u00e9 toute la communaut\u00e9 chr\u00e9tienne \u00e0 red\u00e9couvrir son identit\u00e9 missionnaire et la vie de tous ses membres a \u00e9t\u00e9 transform\u00e9e par une relation plus intime avec le Christ. Par Pierre-Alain Giffard, directeur de la pastorale dioc\u00e9saine Autres articles sur l&rsquo;\u00e9vang\u00e9lisation et le renouveau des paroisses : Trois obstacles \u00e0 l\u2019\u00e9tablissement d\u2019une culture d\u2019invitation dans votre paroisse L\u2019\u00e9vang\u00e9lisateur relationnel Faire \u00c9glise \u00e0 la maison La fille aveugle Un groupe de grenouilles L\u2019\u00e9l\u00e9phant attach\u00e9 Le renouveau de la paroisse de la Nativit\u00e9 \u00e0 Baltimore La foi grandit lorsqu\u2019on la partage Dans les souliers des \u201csans-\u00e9glises\u201d Les cellules paroissiales d\u2019\u00e9vang\u00e9lisation Six caract\u00e9ristiques uniques des paroisses missionnaires Quelques \u00e9tapes pour devenir une paroisse missionnaire Qu\u2019est-ce que l\u2019\u00e9vang\u00e9lisation et dans quel esprit la pratiquer ? Questions de discussion et d\u2019auto-\u00e9valuation pour l\u2019\u00e9vang\u00e9lisation en paroisse La pri\u00e8re de J\u00e9sus: une m\u00e9thode pour prier en tout temps Qu\u2019est-ce qui peut aider les enfants \u00e9lev\u00e9s dans la religion catholique \u00e0 continuer \u00e0 pratiquer leur foi \u00e0 l\u2019\u00e2ge adulte ? Les tactiques de Satan Apprendre \u00e0 \u00eatre missionnaire Quand nous crions vers Dieu, il r\u00e9pond Pr\u00e9sence et Proclamation Sauver ceux qui se perdent La paroisse Saint-Nazaire: L\u2019histoire d\u2019une transformation missionnaire [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[156],"tags":[],"class_list":["post-13636","post","type-post","status-publish","format-standard","hentry","category-textes-a-lire"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/13636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/comments?post=13636"}],"version-history":[{"count":1,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/13636\/revisions"}],"predecessor-version":[{"id":13649,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/13636\/revisions\/13649"}],"wp:attachment":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media?parent=13636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/categories?post=13636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/tags?post=13636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}