{"id":15794,"date":"2024-12-03T16:24:43","date_gmt":"2024-12-03T21:24:43","guid":{"rendered":"https:\/\/pembrokediocese.com\/?p=15794"},"modified":"2024-12-03T16:30:51","modified_gmt":"2024-12-03T21:30:51","slug":"la-paroisse-comme-expression-de-lamour-de-dieu-pour-le-monde-2","status":"publish","type":"post","link":"https:\/\/pembrokediocese.com\/fr\/article\/la-paroisse-comme-expression-de-lamour-de-dieu-pour-le-monde-2\/","title":{"rendered":"Article &#8211; La paroisse comme expression de l&rsquo;amour de Dieu pour le monde"},"content":{"rendered":"\r\n<p><span style=\"font-weight: 400;\">Face \u00e0 la baisse de la fr\u00e9quentation des \u00e9glises et \u00e0 une s\u00e9cularisation croissante, l&rsquo;\u00c9glise catholique est invit\u00e9e \u00e0 repenser le r\u00f4le de la paroisse comme un avant-poste missionnaire, reflet de l\u2019amour infini de Dieu pour tous (cf. <\/span><i><span style=\"font-weight: 400;\">Evangelii Gaudium<\/span><\/i><span style=\"font-weight: 400;\">, 28). Les statistiques sont alarmantes : la participation r\u00e9guli\u00e8re \u00e0 la messe s\u2019effondre. Pourtant, cette crise offre \u00e0 l\u2019\u00c9glise une occasion unique de revenir \u00e0 ses racines \u00e9vang\u00e9lisatrices et de devenir une communaut\u00e9 vibrante, attirant tous les hommes et les femmes vers l\u2019amour transformateur de J\u00e9sus-Christ.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Au c\u0153ur de ce renouveau, il est essentiel de reconna\u00eetre que la paroisse ne se limite pas \u00e0 servir un petit nombre de fid\u00e8les habitu\u00e9s, mais qu\u2019elle est appel\u00e9e \u00e0 \u00eatre un phare d\u2019esp\u00e9rance et un canal de l\u2019amour divin pour tout le voisinage. Comme le souligne le pape Fran\u00e7ois, les paroisses doivent passer d\u2019une mentalit\u00e9 de simple gestion \u00e0 une dynamique missionnaire, abandonnant le confort des pratiques fig\u00e9es pour se tourner activement vers ceux qui n\u2019ont pas encore fait l\u2019exp\u00e9rience de la joie de l\u2019\u00c9vangile.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Ce mouvement missionnaire doit s\u2019enraciner dans une vie de pri\u00e8re dynamique. Sans une pri\u00e8re constante et fervente \u2013 personnelle et communautaire \u2013 la paroisse ne pourra esp\u00e9rer une action \u00e9vang\u00e9lisatrice efficace. De l\u2019adoration eucharistique aux groupes de pri\u00e8re et \u00e0 l\u2019intercession pour les besoins de la communaut\u00e9, la paroisse doit cultiver une atmosph\u00e8re de d\u00e9pendance \u00e0 l\u2019Esprit Saint, convaincue que c\u2019est Dieu, \u00e0 travers le t\u00e9moignage de son peuple, qui attire les c\u0153urs \u00e0 lui.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Fortifi\u00e9e par la pri\u00e8re, la paroisse devient alors un lieu o\u00f9 les relations sont des vecteurs d\u2019\u00e9vang\u00e9lisation. L\u2019accent est mis sur chaque paroissien, appel\u00e9 \u00e0 adopter une posture d\u2019ouverture, d\u2019hospitalit\u00e9 et d\u2019intentionnalit\u00e9 relationnelle. Les fid\u00e8les sont invit\u00e9s \u00e0 devenir des disciples-missionnaires, tissant des liens authentiques avec leurs voisins, coll\u00e8gues et connaissances. Par ces connexions significatives, ils t\u00e9moignent de l\u2019amour de Dieu et orientent doucement les autres vers une relation avec J\u00e9sus-Christ.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Cette approche relationnelle de l\u2019\u00e9vang\u00e9lisation exige \u00e9galement une reconsid\u00e9ration de l\u2019exp\u00e9rience dominicale de la paroisse. Plut\u00f4t que de se limiter aux besoins des habitu\u00e9s, il est n\u00e9cessaire que la liturgie et la vie communautaire soient accueillantes, accessibles et engageantes pour ceux qui se sentent \u00e9loign\u00e9s de l\u2019\u00c9glise. Cela peut inclure un minist\u00e8re d\u2019accueil chaleureux pour les nouveaux venus, des hom\u00e9lies compr\u00e9hensibles, ainsi qu\u2019une musique liturgique qui \u00e9l\u00e8ve l\u2019esprit et le c\u0153ur, invitant chacun \u00e0 une profonde exp\u00e9rience spirituelle. L\u2019objectif est de cr\u00e9er un environnement o\u00f9 les non-pratiquants se sentent accueillis, valoris\u00e9s et attir\u00e9s par la pr\u00e9sence aimante et transformante du Christ.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Parall\u00e8lement, un processus d\u2019int\u00e9gration progressive des nouveaux croyants dans la vie de la communaut\u00e9 paroissiale s\u2019impose. Les petits groupes \u2013 qu\u2019ils soient centr\u00e9s sur la pri\u00e8re, l\u2019\u00e9tude biblique, le soutien mutuel ou le service \u2013 deviennent des incubateurs de foi, des lieux o\u00f9 les relations s\u2019approfondissent, la formation spirituelle se r\u00e9alise, et les futurs leaders sont identifi\u00e9s et form\u00e9s. Ces groupes peuvent ensuite devenir des tremplins pour inviter d\u2019autres personnes \u00e0 rejoindre la famille paroissiale.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Prendre soin des plus d\u00e9munis, tant \u00e0 l\u2019int\u00e9rieur qu\u2019\u00e0 l\u2019ext\u00e9rieur de la communaut\u00e9 paroissiale, est \u00e9galement une expression vitale de l\u2019amour de Dieu pour le monde. Une paroisse v\u00e9ritablement missionnaire doit donner la priorit\u00e9 aux actions en faveur des marginalis\u00e9s, des souffrants et des n\u00e9cessiteux, incarnant ainsi l\u2019appel du Christ \u00e0 servir \u00ab les plus petits \u00bb (cf. Matthieu 25, 40). Qu\u2019il s\u2019agisse d\u2019initiatives organis\u00e9es, comme des banques alimentaires, ou de gestes informels de bienveillance par les paroissiens, cet engagement envers les moins fortun\u00e9s r\u00e9v\u00e8le la puissance transformatrice de l\u2019\u00c9vangile en action.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">\u00c0 la base de cette vision missionnaire, le r\u00f4le du cur\u00e9 est crucial. En tant que pasteur principal, le pr\u00eatre doit d\u00e9finir et communiquer r\u00e9guli\u00e8rement la vocation \u00e9vang\u00e9lisatrice de la paroisse, en donnant l\u2019exemple par une vie de pri\u00e8re et en guidant la communaut\u00e9 dans ses efforts missionnaires. Il doit aussi habiliter les la\u00efcs, en identifiant et en formant des leaders qui partageront le travail de faire des disciples. Abandonnant une approche pastorale centr\u00e9e sur le contr\u00f4le, le pr\u00eatre doit accepter de d\u00e9l\u00e9guer, c\u00e9l\u00e9brant le minist\u00e8re de tous les baptis\u00e9s.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">En fin de compte, une paroisse revitalis\u00e9e devient une manifestation de l\u2019amour prodigue de Dieu \u2013 une communaut\u00e9 qui refl\u00e8te la qu\u00eate incessante du P\u00e8re pour les \u00e9gar\u00e9s, l\u2019\u00e9treinte compatissante envers les prodigues, et la puissance transformatrice du Christ ressuscit\u00e9. Dans une telle paroisse, les barri\u00e8res qui \u00e9loignent souvent les gens de l\u2019\u00c9glise \u2013 qu\u2019elles soient intellectuelles, \u00e9motionnelles ou culturelles \u2013 s\u2019effondrent progressivement, \u00e0 mesure que l\u2019amour de Dieu devient tangible \u00e0 travers le t\u00e9moignage de son peuple.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Cette vision d\u2019une paroisse comme expression de l\u2019amour divin n\u2019est ni facile, ni r\u00e9alisable rapidement ou sans douleur. Elle exige d\u2019abandonner les habitudes du \u00ab toujours fait ainsi \u00bb pour embrasser l\u2019\u0153uvre sacrificielle et inspir\u00e9e par l\u2019Esprit de l\u2019\u00e9vang\u00e9lisation. Elle n\u00e9cessite un engagement renouvel\u00e9 \u00e0 la pri\u00e8re, un focus inlassable sur les relations, et un mod\u00e8le de leadership fond\u00e9 sur la collaboration et l\u2019autonomisation. Pour les paroisses qui rel\u00e8veront ce d\u00e9fi, les fruits ne seront pas seulement mesur\u00e9s en termes de croissance num\u00e9rique, mais surtout dans les vies transform\u00e9es par l\u2019\u00c9vangile et une communaut\u00e9 rayonnant de la beaut\u00e9 de la saintet\u00e9 dans un monde en qu\u00eate d\u2019amour divin.<\/span><\/p>\r\n<p style=\"text-align: right;\">Pierre-Alain Giffard, Directeur de la pastorale diocesaine<\/p>\r\n<p style=\"text-align: right;\">Courriel: pierre.alain.giffard@gmail.com<\/p>\r\n<p><strong>Autres articles sur l&rsquo;\u00e9vang\u00e9lisation et le renouveau des paroisses :<\/strong><\/p>\r\n<ul>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-si-personne-ne-parle-personne-ne-saura\/\"><strong><strong class=\"post-title\">Si personne ne parle, personne ne saura <\/strong><\/strong><\/a><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/evangeliser-par-la-guerison-manifester-la-presence-aimante-de-dieu\/\">\u00c9vang\u00e9liser par la gu\u00e9rison : manifester la pr\u00e9sence aimante de Dieu<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-parabole-du-sage-proprietaire\/\">La Parabole du Sage Propri\u00e9taire<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/signes-extraordinaires-au-quotidien\/\">Signes Extraordinaires au Quotidien<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-le-message-evangelisateur-de-medjugorje\/\">Le message \u00e9vang\u00e9lisateur de Medjugorje<\/a><\/strong><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-difference-entre-le-proselytisme-et-levangelisation-authentique\/\"><strong><strong class=\"post-title\">La diff\u00e9rence entre le pros\u00e9lytisme et l\u2019\u00e9vang\u00e9lisation authentique<\/strong><\/strong><\/a><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/dieu-a-besoin-damour-de-reconciliation-et-dun-esprit-de-pardon\/\">Ce que Dieu a besoin, c\u2019est de l\u2019amour, de la r\u00e9conciliation et un esprit de pardon<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/article-levangelisation-une-mission-collaborative-damour\/\">L\u2019\u00e9vang\u00e9lisation : Une mission collaborative d\u2019amour<\/a><\/strong><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-lapproche-convaincante-du-pere-james-mallon-pour-transformer-les-paroisses-dune-mentalite-de-maintenance-en-une-communaute-missionnaire-florissante\/\">L\u2019approche du P\u00e8re James Mallon pour transformer les paroisses en communaut\u00e9s missionnaires florissantes<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-priere-et-le-service-qui-trouvent-grace-aux-yeux-de-dieu\/\">La pri\u00e8re et le service qui trouvent gr\u00e2ce aux yeux de Dieu<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-pouvoir-transformateur-de-lamour\/\">Le Pouvoir Transformateur de l\u2019Amour<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-puissance-surnaturelle-de-la-priere-et-de-lamour-envers-dieu\/\">La puissance surnaturelle de la pri\u00e8re et de l\u2019amour envers Dieu<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisation-au-quotidien\/\"><strong class=\"post-title\">L\u2019\u00c9vang\u00e9lisation au Quotidien<\/strong><\/a><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/chaque-acte-damour-est-evangelisation\/\">Chaque acte d\u2019amour est \u00e9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/aimer-jesus-et-le-faire-aimer\/\">Aimer J\u00e9sus et le Faire Aimer<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/adopter-un-style-de-vie-dadoration-et-de-louange\/\">Adopter un style de vie d\u2019adoration et de louange<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/priere-pour-demander-a-dieu-la-guerison\/\">Pri\u00e8re pour demander \u00e0 Dieu la gu\u00e9rison<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/ce-qui-a-prouve-attirer-les-gens-vers-le-christ\/\">Ce qui a prouv\u00e9 attirer les gens vers le Christ<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisation-trouver-la-vie-et-partager-la-vie\/\">L\u2019\u00c9vang\u00e9lisation : Trouver la Vie et Partager la Vie<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-leucharistie-source-et-sommet-de-toute-evangelisation\/\">L\u2019Eucharistie : Source et sommet de toute \u00e9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/etapes-pratiques-pour-atteindre-les-personnes-sans-communaute-chretienne\/\">Pistes pratiques pour atteindre les personnes \u00e9loign\u00e9es de la foi<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/guide-de-partage-de-la-bible-en-petits-groupes-une-approche-synodale\/\">Guide de Partage de la Bible en Petits Groupes : Une Approche Synodale<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/amener-quelquun-au-christ-en-suscitant-en-lui-un-sentiment-damour-et-de-louange-envers-dieu\/\">Amener quelqu\u2019un au Christ en suscitant en lui un sentiment d\u2019amour et de louange envers Dieu<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/proclamer-la-parole-de-dieu-un-appel-sacre\/\">Proclamer la parole de Dieu : Un appel sacr\u00e9\u00a0<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/du-declin-au-renouveau-la-transformation-de-leglise-new-life-de-farmington\/\">Du d\u00e9clin au Renouveau : La Transformation de l\u2019\u00c9glise New Life de Farmington<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/lenseignement-social-de-leglise-et-levangelisation\/\">La doctrine sociale de l\u2019\u00c9glise et l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-bienveillance-une-perspective-chretienne\/\">La Bienveillance : Une Perspective Chr\u00e9tienne<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/comment-amener-quelquun-au-christ\/\">Comment amener quelqu\u2019un au Christ<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-finalite-ultime-de-la-vie-humaine-glorifier-dieu\/\">La finalit\u00e9 ultime de la vie humaine \u2013 Glorifier Dieu<\/a><\/strong><\/strong><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/de-lagonie-a-une-nouvelle-vie-le-parcours-de-revitalisation-dune-eglise-de-campagne\/\"><strong class=\"post-title\">De l\u2019Agonie \u00e0 une Nouvelle Vie : Le Parcours de Revitalisation d\u2019une \u00c9glise de Campagne<\/strong><\/a><\/strong><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisation-en-une-phrase-goutez-et-voyez-le-seigneur-est-bon-psaume-349\/\">L\u2019\u00e9vang\u00e9lisation en une phrase: \u00ab Go\u00fbtez et voyez : le Seigneur est bon ! \u00bb (Psaume 34,9)<\/a><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-renouveau-des-eglises-rurales\/\">Le renouveau des \u00e9glises rurales<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-repondre-a-la-baisse-de-frequentation-de-nos-eglises\/\">Facteurs cl\u00e9s attirant les gens vers la foi catholique<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/repondre-a-la-diminution-de-laffluence-dans-nos-eglises\/\">R\u00e9pondre \u00e0 la baisse de fr\u00e9quentation de nos \u00e9glises<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/favoriser-une-atmosphere-sacree-lors-de-la-liturgie-dominicale\/\">Favoriser une Atmosph\u00e8re Sacr\u00e9e lors de la Liturgie Dominicale<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/prier\/priere-pour-recevoir-le-bapteme-dans-lesprit-saint\/\">Pri\u00e8re pour recevoir le bapt\u00eame dans l\u2019Esprit-Saint<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-soif-ardente-du-christ-pour-les-mes\/\">La Soif Ardente du Christ pour les \u00c2mes<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/partager-la-bonne-nouvelle-avec-les-noms-redempteurs-de-dieu\/\">Prier et Partager la Bonne Nouvelle avec les Noms R\u00e9dempteurs de Dieu<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/repondre-a-lappel-a-evangeliser\/\">R\u00e9pondre \u00e0 l\u2019Appel \u00e0 \u00c9vang\u00e9liser<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-quelle-est-la-chose-qui-plait-le-plus-a-dieu-amener-les-ames-au-christ\/\">Qu\u2019est ce qui pla\u00eet le plus \u00e0 Dieu ? Amener les \u00e2mes au Christ<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-croissance-de-leglise-de-la-nativite-p-michael-white\/\">La croissance de l\u2019\u00c9glise de la Nativit\u00e9 (P. Michael White)<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-croissance-de-la-paroisse-saint-benedict-james-mallon\/\">La croissance de la paroisse Saint-Benedict (James Mallon)<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-cinq-piliers-de-la-foi-chretienne\/\">Cinq piliers de la vie chr\u00e9tienne<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-rencontre-personnelle-avec-jesus\/\">Rencontrer J\u00e9sus: Chemin de Transformation Personnelle<\/a><\/strong><\/strong><strong><strong class=\"post-title\"><br \/><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/que-signifie-avoir-une-relation-personnelle-avec-jesus\/\">Que signifie avoir une relation personnelle avec J\u00e9sus ?<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/liberer-le-potentiel-devangelisation-de-votre-paroisse\/\">Lib\u00e9rer le potentiel d\u2019\u00e9vang\u00e9lisation de votre paroisse<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-lobjectif-ultime-de-levangelisation\/\">L\u2019objectif ultime de l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-la-soif-damour-de-dieu-et-notre-mission-de-la-faire-connaitre\/\">La soif d\u2019amour de Dieu et notre mission de la faire conna\u00eetre<\/a><\/strong><\/strong><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/des-dimanches-memorables\/\">Des dimanches m\u00e9morables<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-plan-en-trois-etapes-du-pere-bedard-pour-evangeliser\/\"><strong>Le plan en trois \u00e9tapes du p\u00e8re B\u00e9d<\/strong>ard pour \u00e9vang\u00e9liser<\/a><\/strong><\/strong><\/li>\r\n<li><strong class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/GUIDE-POUR-LA-TRANSFORMATION-MISSIONNAIRE-DES-PAROISSES.pdf\">Guide pour la transformation missionnaire des paroisses<\/a><\/strong><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/un-guide-pratique-pour-demarrer-un-petit-groupe-devangelisation\/\">Semeurs de foi : Un guide pratique pour d\u00e9marrer un petit groupe d\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-transformation-missionnaire-de-la-paroisse-de-santeustorgio\/\">La transformation missionnaire de la paroisse de Sant\u2019Eustorgio<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/creer-des-communautes-catholiques-dynamiques-sagesse-tiree-du-livre-excellent-catholic-parishes\/\"><strong class=\"post-title\">Cr\u00e9er des Communaut\u00e9s Catholiques Dynamiques : Sagesse tir\u00e9e du livre \u2018Excellent Catholic Parishes\u2019<\/strong><\/a><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/partager-levangile-en-fonction-des-besoins-et-de-la-receptivite-des-gens\/\"><strong class=\"post-title\">Partager l\u2019\u00c9vangile en fonction des besoins et de la r\u00e9ceptivit\u00e9 des gens<\/strong><\/a><\/strong><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-priere-pour-inviter-des-personnes-a-des-rencontres-devangelisation\/\">Une pri\u00e8re pour inviter des personnes \u00e0 des rencontres d\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/accueillir-les-invites-et-les-visiteurs-a-leglise\/\">Accueillir les invit\u00e9s et les visiteurs \u00e0 l\u2019\u00e9glise: les choses \u00e0 faire et \u00e0 ne pas faire<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/caracteristiques-dune-paroisse-evangelisatrice\/\">Caract\u00e9ristiques d\u2019une paroisse \u00e9vang\u00e9lisatrice<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/differentes-dimensions-de-levangelisation\/\">Diff\u00e9rentes dimensions de l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-la-vraie-mesure-du-succes\/\"><strong class=\"post-title\">La vraie mesure du succ\u00e8s<\/strong><\/a><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/article-le-pape-francois-sur-levangelisation\/\">Le pape Francois sur l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/reveiller-la-paroisse-rurale-pour-levangelisation\/\">R\u00e9veiller la paroisse rurale pour l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quest-ce-qui-amene-les-gens-au-christ\/\">Qu\u2019est-ce qui am\u00e8ne les gens au Christ ?<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-evangeliser-par-des-petits-actes-de-gentillesse\/\">\u00c9vang\u00e9liser par des petits actes de gentillesse<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-des-questions-pour-entamer-des-conversations-spirituelles\/\"><strong class=\"post-title\">Des questions pour entamer des conversations spirituelles<\/strong><\/a><\/li>\r\n<li><strong class=\"post-title\"><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/a-trois-pieds-de-lor\/\">\u00c0 trois pieds de l\u2019or<\/a><\/strong><\/strong><\/li>\r\n<li><strong class=\"post-title\"><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/evangeliser-a-travers-nos-interactions-sociales\/\">\u00c9vang\u00e9liser en d\u00e9veloppant nos comp\u00e9tences sociales<\/a><\/strong><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/rassembler-temoigner-et-inviter\/\">Rassembler, t\u00e9moigner et inviter<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/priere-pour-recevoir-les-dons-spirituels-du-saint-esprit\/\"><strong class=\"post-title\">Pri\u00e8re pour recevoir les dons spirituels du Saint Esprit<\/strong><\/a><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-langage-de-la-croix-la-voix-de-levangelisation\/\">Le langage de la croix est le langage de l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-facteurs-cles-pour-la-croissance-de-la-paroisse\/\">Facteurs cl\u00e9s pour la croissance de la paroisse selon Rich Birch<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-comment-vaincre-satan\/\"><strong class=\"post-title\">Comment vaincre Satan ?<\/strong><\/a><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/apporter-amour-espoir-et-guerison-par-levangile\/\"><strong class=\"post-title\">Apporter Amour, Espoir et Gu\u00e9rison par l\u2019\u00c9vangile<\/strong><\/a><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-quest-ce-que-lamour\/\"><strong class=\"post-title\">Qu\u2019est-ce que l\u2019amour ?<\/strong><\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-touche-par-le-maitre\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Touch\u00e9 par le Ma\u00eetre<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-un-homme-un-chien-et-lamour-ultime\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Un homme, un chien, et l\u2019amour ultime<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/des-facons-pratiques-daimer-les-autres\/\"><strong>A<\/strong><\/a><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/des-facons-pratiques-daimer-les-autres\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>u c\u0153ur de l\u2019\u00e9vang\u00e9lisation : Aimer Dieu et les autres<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/aimer-nos-ennemis-et-se-reconcilier-avec-les-autres\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Aimer nos ennemis et se r\u00e9concilier avec les autres<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-priere-bibique-pour-la-guerison\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pri\u00e8re pour la gu\u00e9rison : Tu es le Seigneur qui me gu\u00e9rit<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-vivre-une-vie-damour-lheritage-de-mere-teresa\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Vivre une vie d\u2019amour : L\u2019h\u00e9ritage de M\u00e8re Teresa<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-force-puissante-est-a-loeuvre\/\"><strong>Sous le <\/strong><\/a><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-force-puissante-est-a-loeuvre\/\" target=\"_blank\" rel=\"noreferrer noopener\">c<\/a><\/strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-force-puissante-est-a-loeuvre\/\"><strong>ouvert des t\u00e9n\u00e8bres, une force puissante est \u00e0 l\u2019\u0153uvre<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-evangeliser-avec-amour-et-pour-lamour\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Vivre une vie d\u2019amour : Le\u00e7ons du Nouveau Testament<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/19-orientations-pastorales-pour-le-renouveau-et-la-croissance-des-paroisses\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>19 orientations pastorales qui contribuent \u00e0 la croissance des paroisses<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-renouveau-missionnaire-de-la-catechese\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Le renouveau missionnaire de la cat\u00e9ch\u00e8se<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/les-caracteristiques-des-paroisses-missionnaires\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Les caract\u00e9ristiques des paroisses missionnaires<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/priere-de-guerison\/\"><strong>Pri\u00e8re de gu\u00e9rison attribu\u00e9e \u00e0 saint Padre Pio<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/partager-notre-foi\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Nous sommes appel\u00e9s \u00e0 partager notre foi avec les autres<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/devrait-on-chercher-la-croissance-de-leglise\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Devrait-on chercher la croissance de l\u2019\u00c9glise ?<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/trouvez-un-besoin-et-comblez-le\/\" target=\"_blank\" rel=\"noreferrer noopener\">Trouvez un besoin et comblez-le : R\u00e9v\u00e9ler le c\u0153ur de Dieu dans son quartier<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/evangeliser-au-quotidien\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>15 habitudes pour \u00e9vang\u00e9liser au quotidien<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-mission-de-leglise\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>La mission de l\u2019\u00c9glise<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/trois-obstacles-a-letablissement-dune-culture-dinvitation-dans-votre-paroisse\/\" target=\"_blank\" rel=\"noreferrer noopener\">Trois obstacles \u00e0 l\u2019\u00e9tablissement d\u2019une culture d\u2019invitation dans votre paroisse<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisateur-relationnel\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>L\u2019\u00e9vang\u00e9lisateur relationnel<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/faire-eglise-a-la-maison\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Faire \u00c9glise \u00e0 la maison<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-fille-aveugle\/\" target=\"_blank\" rel=\"noreferrer noopener\">La fille aveugle<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/un-groupe-de-gernouilles\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Un groupe de grenouilles<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/lelephant-attache\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>L\u2019\u00e9l\u00e9phant attach\u00e9<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/paroisse-de-la-nativite\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Le renouveau de la paroisse de la Nativit\u00e9 \u00e0 Baltimore<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-foi-grandit-copy\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>La foi grandit lorsqu\u2019on la partage<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/dans-les-souliers-des-sans-eglises\/\" target=\"_blank\" rel=\"noreferrer noopener\">Dans les souliers des \u201csans-\u00e9glises\u201d<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-cellules-paroissiales-devangelisation-2-copy\/\" target=\"_blank\" rel=\"noreferrer noopener\">Les cellules paroissiales d\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/caracteristiques-uniques-des-paroisses-missionnaires\/\" target=\"_blank\" rel=\"noreferrer noopener\">Six caract\u00e9ristiques uniques des paroisses missionnaires<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/devenir-une-paroisse-missionnaire\/\" target=\"_blank\" rel=\"noreferrer noopener\">Quelques \u00e9tapes pour devenir une paroisse missionnaire<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quest-ce-que-levangelisation\/\" target=\"_blank\" rel=\"noreferrer noopener\">Qu\u2019est-ce que l\u2019\u00e9vang\u00e9lisation et dans quel esprit la pratiquer ?<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/auto-evaluation\/\" target=\"_blank\" rel=\"noreferrer noopener\">Questions de discussion et d\u2019auto-\u00e9valuation pour l\u2019\u00e9vang\u00e9lisation en paroisse<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-priere-de-jesus\/\" target=\"_blank\" rel=\"noreferrer noopener\">La pri\u00e8re de J\u00e9sus: une m\u00e9thode pour prier en tout temps<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/pratiquer-leur-foi\/\" target=\"_blank\" rel=\"noreferrer noopener\">Qu\u2019est-ce qui peut aider les enfants \u00e9lev\u00e9s dans la religion catholique \u00e0 continuer \u00e0 pratiquer leur foi \u00e0 l\u2019\u00e2ge adulte ?<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-tactiques-de-satan-1ere-partie\/\" target=\"_blank\" rel=\"noreferrer noopener\">Les tactiques de Satan<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/apprendre-a-etre-missionnaire\/\" target=\"_blank\" rel=\"noreferrer noopener\">Apprendre \u00e0 \u00eatre missionnaire<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quand-nous-crions-vers-dieu\/\" target=\"_blank\" rel=\"noreferrer noopener\">Quand nous crions vers Dieu, il r\u00e9pond<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent-copy\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pr\u00e9sence et Proclamation<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sauver ceux qui se perdent<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-paroisse-saint-nazaire-lhistoire-dune-transformation-missionnaire\/\" target=\"_blank\" rel=\"noreferrer noopener\">La paroisse Saint-Nazaire: L\u2019histoire d\u2019une transformation missionnaire<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/evangelisation-et-petits-groupes-de-partage\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9vang\u00e9lisation et petits groupes de partage<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/evangeliser-en-invitant-des-personnes-a-recevoir-jesus-comme-seigneur-et-sauveur\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9vang\u00e9liser en invitant des personnes \u00e0 recevoir J\u00e9sus comme Seigneur et Sauveur<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/vous-allez-recevoir-une-force\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vous allez recevoir une force\u2026<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/avez-vous-entendu-parler-de-la-loi-des-trois-ecoutes-et-des-sept-contacts\/\" target=\"_blank\" rel=\"noreferrer noopener\">Avez-vous entendu parler de la loi des trois \u00e9coutes et des sept contacts ?<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/trois-habitudes-dune-vie-chretienne-fructueuse\/\" target=\"_blank\" rel=\"noreferrer noopener\">Trois habitudes d\u2019une vie chr\u00e9tienne fructueuse<\/a><\/strong><\/li>\r\n<\/ul>\r\n<p class=\"has-text-align-right\"><!-- \/wp:post-content -->\r\n\r\n<!-- wp:separator --><\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p class=\"has-text-align-right\"><!-- \/wp:separator -->\r\n\r\n<!-- wp:shortcode --><\/p>\r\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\"> <a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1993 size-full\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying-100x100.png 100w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\r\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\">LECTURES RECOMMANDEES<\/a><\/h4>\r\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\" target=\"_self\" >En savoir plus <\/a>\r\n<\/div>\r\n<p class=\"has-text-align-right\"><!-- \/wp:shortcode -->\r\n\r\n<!-- wp:shortcode --><\/p>\r\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\"> <a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/prayer-group\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3620\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-300x300.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-300x300.png 300w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-100x100.png 100w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-400x400.png 400w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-210x210.png 210w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle.png 684w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\r\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/prayer-group\/\">PRI\u00c8RES ET GROUPES DE PRIERE POUR LE PROJET DIOC\u00c9SAIN DE NOUVELLE \u00c9VANG\u00c9LISATION<\/a><\/h4>\r\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"\/fr\/nouvelle-evangelisation\/prayer-group\/\" target=\"_self\" >En savoir plus<\/a>\r\n<\/div>\r\n<p class=\"has-text-align-right\"><!-- \/wp:shortcode -->\r\n\r\n<!-- wp:shortcode --><\/p>\r\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\"> <a href=\"https:\/\/pembrokediocese.com\/donate\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7117 size-medium aligncenter\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-200x200.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-200x200.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-768x768.png 768w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-100x100.png 100w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-400x400.png 400w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-210x210.png 210w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept.png 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\r\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/donate\/\">DONNER POUR LE PROJET DIOC\u00c9SAIN DE NOUVELLE \u00c9VANG\u00c9LISATION<\/a><\/h4>\r\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"https:\/\/pembrokediocese.com\/donate\/\" target=\"_self\" >En savoir plus<\/a>\r\n<\/div>\r\n<p class=\"has-text-align-right\"><!-- \/wp:shortcode --><\/p>","protected":false},"excerpt":{"rendered":"<p>Face \u00e0 la baisse de la fr\u00e9quentation des \u00e9glises et \u00e0 une s\u00e9cularisation croissante, l&rsquo;\u00c9glise catholique est invit\u00e9e \u00e0 repenser le r\u00f4le de la paroisse comme un avant-poste missionnaire, reflet de l\u2019amour infini de Dieu pour tous (cf. Evangelii Gaudium, 28). Les statistiques sont alarmantes : la participation r\u00e9guli\u00e8re \u00e0 la messe s\u2019effondre. Pourtant, cette crise offre \u00e0 l\u2019\u00c9glise une occasion unique de revenir \u00e0 ses racines \u00e9vang\u00e9lisatrices et de devenir une communaut\u00e9 vibrante, attirant tous les hommes et les femmes vers l\u2019amour transformateur de J\u00e9sus-Christ. Au c\u0153ur de ce renouveau, il est essentiel de reconna\u00eetre que la paroisse ne se limite pas \u00e0 servir un petit nombre de fid\u00e8les habitu\u00e9s, mais qu\u2019elle est appel\u00e9e \u00e0 \u00eatre un phare d\u2019esp\u00e9rance et un canal de l\u2019amour divin pour tout le voisinage. Comme le souligne le pape Fran\u00e7ois, les paroisses doivent passer d\u2019une mentalit\u00e9 de simple gestion \u00e0 une dynamique missionnaire, abandonnant le confort des pratiques fig\u00e9es pour se tourner activement vers ceux qui n\u2019ont pas encore fait l\u2019exp\u00e9rience de la joie de l\u2019\u00c9vangile. Ce mouvement missionnaire doit s\u2019enraciner dans une vie de pri\u00e8re dynamique. Sans une pri\u00e8re constante et fervente \u2013 personnelle et communautaire \u2013 la paroisse ne pourra esp\u00e9rer une action \u00e9vang\u00e9lisatrice efficace. De l\u2019adoration eucharistique aux groupes de pri\u00e8re et \u00e0 l\u2019intercession pour les besoins de la communaut\u00e9, la paroisse doit cultiver une atmosph\u00e8re de d\u00e9pendance \u00e0 l\u2019Esprit Saint, convaincue que c\u2019est Dieu, \u00e0 travers le t\u00e9moignage de son peuple, qui attire les c\u0153urs \u00e0 lui. Fortifi\u00e9e par la pri\u00e8re, la paroisse devient alors un lieu o\u00f9 les relations sont des vecteurs d\u2019\u00e9vang\u00e9lisation. L\u2019accent est mis sur chaque paroissien, appel\u00e9 \u00e0 adopter une posture d\u2019ouverture, d\u2019hospitalit\u00e9 et d\u2019intentionnalit\u00e9 relationnelle. Les fid\u00e8les sont invit\u00e9s \u00e0 devenir des disciples-missionnaires, tissant des liens authentiques avec leurs voisins, coll\u00e8gues et connaissances. Par ces connexions significatives, ils t\u00e9moignent de l\u2019amour de Dieu et orientent doucement les autres vers une relation avec J\u00e9sus-Christ. Cette approche relationnelle de l\u2019\u00e9vang\u00e9lisation exige \u00e9galement une reconsid\u00e9ration de l\u2019exp\u00e9rience dominicale de la paroisse. Plut\u00f4t que de se limiter aux besoins des habitu\u00e9s, il est n\u00e9cessaire que la liturgie et la vie communautaire soient accueillantes, accessibles et engageantes pour ceux qui se sentent \u00e9loign\u00e9s de l\u2019\u00c9glise. Cela peut inclure un minist\u00e8re d\u2019accueil chaleureux pour les nouveaux venus, des hom\u00e9lies compr\u00e9hensibles, ainsi qu\u2019une musique liturgique qui \u00e9l\u00e8ve l\u2019esprit et le c\u0153ur, invitant chacun \u00e0 une profonde exp\u00e9rience spirituelle. L\u2019objectif est de cr\u00e9er un environnement o\u00f9 les non-pratiquants se sentent accueillis, valoris\u00e9s et attir\u00e9s par la pr\u00e9sence aimante et transformante du Christ. Parall\u00e8lement, un processus d\u2019int\u00e9gration progressive des nouveaux croyants dans la vie de la communaut\u00e9 paroissiale s\u2019impose. Les petits groupes \u2013 qu\u2019ils soient centr\u00e9s sur la pri\u00e8re, l\u2019\u00e9tude biblique, le soutien mutuel ou le service \u2013 deviennent des incubateurs de foi, des lieux o\u00f9 les relations s\u2019approfondissent, la formation spirituelle se r\u00e9alise, et les futurs leaders sont identifi\u00e9s et form\u00e9s. Ces groupes peuvent ensuite devenir des tremplins pour inviter d\u2019autres personnes \u00e0 rejoindre la famille paroissiale. Prendre soin des plus d\u00e9munis, tant \u00e0 l\u2019int\u00e9rieur qu\u2019\u00e0 l\u2019ext\u00e9rieur de la communaut\u00e9 paroissiale, est \u00e9galement une expression vitale de l\u2019amour de Dieu pour le monde. [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":15790,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[84,156],"tags":[],"class_list":["post-15794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","category-textes-a-lire"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/15794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/comments?post=15794"}],"version-history":[{"count":3,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/15794\/revisions"}],"predecessor-version":[{"id":15797,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/15794\/revisions\/15797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media\/15790"}],"wp:attachment":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media?parent=15794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/categories?post=15794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/tags?post=15794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}