{"id":17377,"date":"2025-07-16T13:34:10","date_gmt":"2025-07-16T17:34:10","guid":{"rendered":"https:\/\/pembrokediocese.com\/?p=17377"},"modified":"2025-08-20T15:04:56","modified_gmt":"2025-08-20T19:04:56","slug":"article-de-la-pastorale-dentretien-a-la-pastorale-missionnaire-mobiliser-chaque-chretien-pour-temoigner-du-christ","status":"publish","type":"post","link":"https:\/\/pembrokediocese.com\/fr\/article\/article-de-la-pastorale-dentretien-a-la-pastorale-missionnaire-mobiliser-chaque-chretien-pour-temoigner-du-christ\/","title":{"rendered":"ARTICLE &#8211; De la pastorale d&rsquo;entretien \u00e0 la pastorale missionnaire: Mobiliser chaque chr\u00e9tien pour t\u00e9moigner du Christ"},"content":{"rendered":"\r\n<div id=\"model-response-message-contentr_154d0e7a2dcac255\" class=\"markdown markdown-main-panel\" dir=\"ltr\">\r\n<p><span style=\"font-weight: 400;\"><em>(Image: The Lost Sheep by Robert T Barrett | Altus Fine Art)<\/em><\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Du C\u0153ur de l\u2019\u00c9glise jaillit une vision \u00e0 deux facettes : d\u2019une part, contempler et adh\u00e9rer \u00e0 la volont\u00e9 de Dieu qui veut sauver toute l\u2019humanit\u00e9 ; d\u2019autre part, reconna\u00eetre et susciter, en chaque baptis\u00e9, la vocation de disciple missionnaire. Ces deux piliers forment le fondement m\u00eame d\u2019une \u00c9glise missionnaire.<\/span><\/p>\r\n<p><strong>La volont\u00e9 salvifique universelle de Dieu<\/strong><\/p>\r\n<p><span style=\"font-weight: 400;\">L\u2019\u00c9criture affirme sans d\u00e9tour : \u00ab Dieu veut que tous les hommes soient sauv\u00e9s et parviennent \u00e0 la connaissance de la v\u00e9rit\u00e9 \u00bb (1 Tm 2,4). Depuis le r\u00e9cit de la Cr\u00e9ation en Gen\u00e8se jusqu\u2019\u00e0 la vision ultime de l\u2019Apocalypse, la Bible r\u00e9v\u00e8le un Dieu qui n\u2019est ni passif ni exclusif, mais qui tend activement la main \u00e0 toutes les nations, \u00e0 tous les peuples. Le Christ lui-m\u00eame d\u00e9clare : \u00ab Et moi, quand j\u2019aurai \u00e9t\u00e9 \u00e9lev\u00e9 de terre, j\u2019attirerai \u00e0 moi tous les hommes \u00bb (Jn 12,32). Sa mission de salut est universelle.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Le Cat\u00e9chisme de l\u2019\u00c9glise catholique reprend cette v\u00e9rit\u00e9 avec force : \u00ab Par sa mort et sa R\u00e9surrection, J\u00e9sus-Christ a ouvert \u00e0 tous les hommes l\u2019acc\u00e8s \u00e0 la vie \u00e9ternelle \u00bb (CEC, n\u00b0 1026). Le Concile Vatican II a rappel\u00e9 avec une intensit\u00e9 renouvel\u00e9e cette universalit\u00e9, notamment dans Lumen Gentium et Gaudium et Spes. D\u00e8s lors, les pasteurs de l\u2019\u00c9glise ne peuvent se contenter de veiller sur ceux qui fr\u00e9quentent d\u00e9j\u00e0 les bancs des assembl\u00e9es ; ils sont appel\u00e9s \u00e0 chercher activement ceux et celles qui sont perdus, \u00e0 l\u2019image du Bon Pasteur : \u00ab Quel homme parmi vous, s\u2019il a cent brebis et qu\u2019il en perde une, ne laisse les quatre-vingt-dix-neuf autres au d\u00e9sert pour aller \u00e0 celle qui est perdue, jusqu\u2019\u00e0 ce qu\u2019il la retrouve ? \u00bb (Lc 15,4-7).<\/span><\/p>\r\n<p><strong>Tout chr\u00e9tien est envoy\u00e9<\/strong><\/p>\r\n<p><span style=\"font-weight: 400;\">L\u2019\u00c9glise n\u2019est pas simplement un refuge pour les croyants ; elle est, par essence, missionnaire. Le pape Fran\u00e7ois l\u2019affirme dans Evangelii Gaudium, n\u00b0 20 : \u00ab L\u2019action missionnaire est le paradigme de toute \u0153uvre de l\u2019\u00c9glise. \u00bb Le d\u00e9cret Ad Gentes du Concile Vatican II proclame de m\u00eame : \u00ab L\u2019\u00c9glise en p\u00e8lerinage est, par nature, missionnaire \u00bb (n\u00b0 2).<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Cette identit\u00e9 missionnaire n\u2019est pas r\u00e9serv\u00e9e au clerg\u00e9 ou aux religieux. Par le Bapt\u00eame et la Confirmation, chaque chr\u00e9tien est appel\u00e9 \u00e0 participer \u00e0 la mission de l\u2019\u00c9glise. Saint Jean-Paul II, dans Redemptoris Missio, n\u00b0 71, insiste : \u00ab Tous les la\u00efcs sont missionnaires en vertu de leur bapt\u00eame. \u00bb<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Cette conviction doit transformer le regard des responsables eccl\u00e9siaux : le peuple confi\u00e9 \u00e0 leurs soins n\u2019est pas une assembl\u00e9e passive de consommateurs de services religieux, mais un corps vivant de t\u00e9moins actifs de l\u2019\u00c9vangile. Chaque paroissien, chaque membre du Corps du Christ doit \u00eatre appel\u00e9 \u00e0 devenir missionnaire, dans sa famille, sur son lieu de travail, dans la soci\u00e9t\u00e9 tout enti\u00e8re.<\/span><\/p>\r\n<p><strong>L\u2019exp\u00e9rience des \u00c9glises en croissance : exemples contemporains<\/strong><\/p>\r\n<p><span style=\"font-weight: 400;\">Dans de nombreuses r\u00e9gions du monde, les communaut\u00e9s chr\u00e9tiennes qui connaissent une croissance durable partagent deux traits essentiels : elles s\u2019appuient sur la conscience vive de la volont\u00e9 universelle de salut de Dieu, et elles mobilisent effectivement tous les croyants comme missionnaires.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Ainsi, des recherches men\u00e9es par le Center for the Study of Global Christianity montrent que les \u00c9glises en expansion \u2013 qu\u2019elles soient catholiques, protestantes ou orthodoxes \u2013 investissent massivement dans la formation de petits groupes de disciples, le d\u00e9veloppement du leadership la\u00efc, et des initiatives d\u2019\u00e9vang\u00e9lisation. Ces communaut\u00e9s rappellent l\u2019image de l\u2019\u00c9glise apostolique telle qu\u2019elle appara\u00eet dans les Actes des Ap\u00f4tres : \u00ab Chaque jour, le Seigneur leur adjoignait ceux qui allaient \u00eatre sauv\u00e9s \u00bb (Ac 2,47).<\/span><\/p>\r\n<p><strong>Cons\u00e9quences pratiques pour les responsables d\u2019aujourd\u2019hui<\/strong><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\">Pour les \u00e9v\u00eaques, pr\u00eatres et autres responsables de l\u2019\u00c9glise, ces v\u00e9rit\u00e9s appellent non seulement une adh\u00e9sion doctrinale, mais surtout une mise en \u0153uvre concr\u00e8te. Voir la volont\u00e9 de Dieu de sauver tous les hommes implique de sortir d\u2019une simple logique d\u2019entretien pastoral pour entrer dans une dynamique missionnaire active. Mobiliser tous les chr\u00e9tiens comme missionnaires requiert des approches pr\u00e9cises :<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">\u2014 Des hom\u00e9lies qui rappellent sans rel\u00e2che aux fid\u00e8les leur vocation missionnaire (cf. Evangelii Gaudium, n\u00b0 120).<\/span><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\"> \u2014 Structurer la vie paroissiale autour de l\u2019\u00e9vang\u00e9lisation et de la formation de disciples, et non pas uniquement autour de l\u2019administration sacramentelle.<\/span><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\"> \u2014 Prioriser la formation de leaders la\u00efcs \u00e0 travers la cat\u00e9ch\u00e8se, le mentorat et la d\u00e9l\u00e9gation de responsabilit\u00e9s effectives.<\/span><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\"> \u2014 Veiller \u00e0 ce que les programmes pastoraux \u2013 minist\u00e8re aupr\u00e8s des jeunes, liturgie, action sociale \u2013 soient orient\u00e9s vers l\u2019annonce de l\u2019\u00c9vangile.<\/span><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\"> \u2014 D\u00e9velopper des initiatives sp\u00e9cifiques pour rejoindre ceux et celles qui ne connaissent pas le Christ ou s\u2019en sont \u00e9loign\u00e9s.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">L\u2019exhortation du pape Beno\u00eet XVI trouve ici tout son sens : \u00ab L\u2019\u00c9glise ne grandit pas par pros\u00e9lytisme, mais par attraction \u00bb (Deus Caritas Est, n\u00b0 1). Cette attraction n\u2019op\u00e8re que lorsque les membres de l\u2019\u00c9glise vivent et t\u00e9moignent concr\u00e8tement de l\u2019amour sauveur de Dieu dans tous les domaines de leur existence.<\/span><\/p>\r\n<p><strong>Conclusion : un appel \u00e0 une vision et une action renouvel\u00e9es<\/strong><\/p>\r\n<p><span style=\"font-weight: 400;\">En d\u00e9finitive, les responsables de l\u2019\u00c9glise doivent cultiver sans cesse ces deux visions indissociables : voir dans le Christ l\u2019immensit\u00e9 de la mis\u00e9ricorde divine, et reconna\u00eetre en chaque croyant la capacit\u00e9 d\u2019en \u00eatre un instrument vivant. L\u2019urgence de cette mission est aujourd\u2019hui plus grande que jamais, face aux d\u00e9fis spirituels et culturels de notre \u00e9poque.<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Les paroles de saint Paul conservent toute leur actualit\u00e9 : \u00ab Comment donc invoquer le Seigneur sans d\u2019abord croire en lui ? Et comment croire sans d\u2019abord l\u2019entendre ? Et comment entendre si personne ne proclame ? \u00bb (Rm 10,14).<\/span><\/p>\r\n<p><span style=\"font-weight: 400;\">Que, par la gr\u00e2ce de l\u2019Esprit Saint, chaque responsable eccl\u00e9sial entende \u00e0 nouveau cet appel, et qu\u2019il aide tout le peuple de Dieu \u00e0 se lever comme un seul corps, envoy\u00e9 dans le monde pour proclamer l\u2019amour sauveur de J\u00e9sus Christ.<\/span><\/p>\r\n<\/div>\r\n<p style=\"text-align: right;\">Pierre-Alain Giffard<br \/>pierre.alain.giffard@gmail.com<\/p>\r\n<p><strong>Livre \u00e0 lire sur la revitalisation et la croissance des paroisses<\/strong><\/p>\r\n<ul>\r\n<li><a href=\"https:\/\/www.amazon.ca\/PAROISSES-VIVANTES-transformation-missionnaire-communaut%C3%A9s\/dp\/B0CR86D15B\/ref=sr_1_1?crid=3MN0K2YR8HQ7J&amp;keywords=paroisses+vivantes&amp;qid=1704572814&amp;sprefix=%2Caps%2C92&amp;sr=8-1\" target=\"_blank\" rel=\"noopener\" aria-label=\"LIVRE \u00c0 LIRE \u2013 PAROISSES VIVANTES: Guide pratique pour la transformation missionnaire des communaut\u00e9s chr\u00e9tiennes (Pr\u00e9face de Mgr Damphousse) (opens in a new tab)\"><strong class=\"post-title\">Guide pratique pour la transformation missionnaire des communaut\u00e9s chr\u00e9tiennes (Pr\u00e9face de Mgr Damphousse)<\/strong><\/a><\/li>\r\n<\/ul>\r\n<p><strong>Autres articles et ressources pour l&rsquo;\u00e9vang\u00e9lisation et le renouveau des paroisses :<\/strong><\/p>\r\n<ul>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-eveiller-le-desir-du-christ\/\">\u00c9vang\u00e9liser, c\u2019est \u00e9veiller le d\u00e9sir de marcher avec le Christ<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-letincelle-manquante\/\">L\u2019\u00e9tincelle manquante<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-renouveau-de-la-vie-paroissiale-la-vision-de-larchidiocese-de-philadelphie\/\">Renouveau de la vie paroissiale : la vision de l\u2019Archidioc\u00e8se de Philadelphie<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-levangelisation-une-rencontre-qui-transforme-et-qui-envoie\/\">L\u2019\u00c9vang\u00e9lisation : Une Rencontre qui Transforme et qui Envoie<\/a><\/strong><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/article-levangelisation-comme-acte-de-compassion\/\"><strong class=\"post-title\">L\u2019\u00c9vang\u00e9lisation comme Acte de Compassion<\/strong><\/a><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-itineraire-dun-amour-vainqueur\/\">La victoire de l\u2019amour dans le jardin de l\u2019\u00e2me<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-la-patience-comme-aiguille-lamour-comme-fil\/\">La patience est l\u2019aiguille, l\u2019amour en est le fil<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-levangelisation-authentique-et-la-prevention-du-fanatisme\/\">L\u2019\u00e9vang\u00e9lisation authentique et la pr\u00e9vention du fanatisme<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-le-royaume-est-tout-proche-mais-quest-ce-que-cela-signifie-vraiment\/\">Le Royaume est tout proche \u2014 Mais qu\u2019est-ce que cela signifie vraiment ?<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-levangelisation-pourquoi-les-relations-comptent-plus-quon-ne-le-pense\/\">L\u2019\u00e9vang\u00e9lisation : pourquoi les relations comptent plus qu\u2019on ne le pense<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/lannonce-dune-merveilleuse-nouvelle\/\">L\u2019\u00e9vang\u00e9lisation : la joie d\u2019annoncer une merveilleuse nouvelle<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-la-derive-silencieuse\/\">La D\u00e9rive Silencieuse\u00a0<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/saint-francois-a-t-il-vraiment-dit-cela\/\">Saint Fran\u00e7ois a-t-il vraiment dit cela\u202f?<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-don-de-lechec-quand-tout-vacille-dieu-nous-faconne-et-nous-rend-docile\/\">Le don de l\u2019\u00e9chec : quand tout vacille, Dieu nous fa\u00e7onne et nous rend docile<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-prie-sois-transforme-parle-de-dieu\/\">Prie, Sois transform\u00e9, Proclame la Parole<\/a><\/strong><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/ceux-qui-comprennent-le-coeur-de-jesus-se-font-evangelisateurs\/\"><strong class=\"post-title\">Ceux qui comprennent le C\u0153ur de J\u00e9sus se font \u00e9vang\u00e9lisateurs<\/strong><\/a><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/renouveau-charismatique-dans-la-theologie-catholique\/\">Comprendre le Renouveau Charismatique dans la th\u00e9ologie catholique<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisation-un-appel-a-vivre-levangile\/\">L\u2019\u00c9vang\u00e9lisation : un appel \u00e0 vivre l\u2019\u00c9vangile<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/outil-dauto-evaluation-pour-discerner-votre-style-devangelisation\/\">Outil d\u2019Auto-\u00e9valuation pour Discerner Votre Style d\u2019\u00c9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/discerner-son-role-dans-levangelisation-et-le-renouveau\/\">Discerner son R\u00f4le dans l\u2019\u00c9vang\u00e9lisation et le Renouveau\u00a0<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/suivre-le-christ-une-benediction-ou-un-fardeau\/\">Suivre le Christ : Une b\u00e9n\u00e9diction ou un fardeau ?<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/pour-les-miracles-en-toute-situation\/\">Pour des miracles en toute situation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/visions-propheties-et-messages-divins-un-appel-au-discernement\/\">Visions, Proph\u00e9ties et Messages Divins : Un Appel au Discernement<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/enseignements-cles-pour-levangelisation-tires-de-catholic-parish-administration-a-handbook\/\">Enseignements Cl\u00e9s pour l\u2019\u00c9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-message-de-jesus-une-invitation-a-la-vie-nouvelle\/\">Le Message de J\u00e9sus : Une Invitation \u00e0 la Vie Nouvelle<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/illuminer-une-nuit-obscure\/\">Apporter la lumi\u00e8re en semant des graines d\u2019esp\u00e9rance et de foi<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/un-cercle-vertueux-devangelisation-en-5-etapes\/\">Un Cercle Vertueux d\u2019\u00c9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-notion-de-bonne-nouvelle\/\">La notion de \u00ab Bonne Nouvelle \u00bb<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-l-esprit-de-la-conversation-spirituelle-un-chemin-de-transformation-2\/\">L\u2019amour au c\u0153ur de la vie et de la mission de l\u2019\u00c9glise<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-l-esprit-de-la-conversation-spirituelle-un-chemin-de-transformation\/\">L\u2019\u00ab esprit \u00bb de la conversation spirituelle : Un chemin de transformation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-comment-partager-sa-foi\/\">Pri\u00e8re lorsque l\u2019on se sent perdu<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-comment-partager-sa-foi\/\">Comment Partager sa Foi<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/lamour-et-le-temps\/\">L\u2019 Amour et le Temps<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisation-partager-la-joie-la-paix-et-lesperance-du-christ\/\">L\u2019\u00e9vang\u00e9lisation : Partager la Joie, la Paix et l\u2019Esp\u00e9rance du Christ<\/a><\/strong><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-priere-pour-les-personnes-qui-ont-besoin-de-lamour-de-dieu-et-de-son-salut\/\"><strong><strong class=\"post-title\">Une pri\u00e8re pour ceux et celles que nous esp\u00e9rons voir rencontrer le Christ<\/strong><\/strong><\/a><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-leadership-sacerdotal-dans-levangelisation\/\">Leadership sacerdotal dans l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/temoignage-levangelisation-autour-dun-cafe-a-luniversite-de-mary-washington\/\">L\u2019\u00e9vang\u00e9lisation autour d\u2019un caf\u00e9 \u00e0 l\u2019Universit\u00e9 de Mary Washington<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisation-un-temoignage-vivant-de-lamour-divin\/\">L\u2019\u00c9vang\u00e9lisation : Un T\u00e9moignage Vivant de l\u2019Amour Divin<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/vivre-de-la-joie-de-levangile\/\">Vivre de la joie de l\u2019\u00c9vangile<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/au-commencement-etait-le-verbe-le-role-essentiel-des-ecritures-dans-levangelisation\/\">Au Commencement \u00c9tait le Verbe: Le R\u00f4le Essentiel des \u00c9critures dans l\u2019\u00c9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/evangeliser-quelques-mots-suffisent\/\">\u00c9vang\u00e9liser avec quelques mots<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/demander-chaque-jour-la-grace-daider-quelquun\/\">Demander chaque jour la gr\u00e2ce d\u2019aider quelqu\u2019un<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-paroisse-comme-expression-de-lamour-de-dieu-pour-le-monde-2\/\">La paroisse comme expression de l\u2019amour de Dieu pour le monde<\/a><\/strong><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-si-personne-ne-parle-personne-ne-saura\/\"><strong><strong class=\"post-title\">Si personne ne parle, personne ne saura <\/strong><\/strong><\/a><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/evangeliser-par-la-guerison-manifester-la-presence-aimante-de-dieu\/\">\u00c9vang\u00e9liser par la gu\u00e9rison : manifester la pr\u00e9sence aimante de Dieu<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-parabole-du-sage-proprietaire\/\">La Parabole du Sage Propri\u00e9taire<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/signes-extraordinaires-au-quotidien\/\">Signes Extraordinaires au Quotidien<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-le-message-evangelisateur-de-medjugorje\/\">Le message \u00e9vang\u00e9lisateur de Medjugorje<\/a><\/strong><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-difference-entre-le-proselytisme-et-levangelisation-authentique\/\"><strong><strong class=\"post-title\">La diff\u00e9rence entre le pros\u00e9lytisme et l\u2019\u00e9vang\u00e9lisation authentique<\/strong><\/strong><\/a><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/dieu-a-besoin-damour-de-reconciliation-et-dun-esprit-de-pardon\/\">Ce que Dieu a besoin, c\u2019est de l\u2019amour, de la r\u00e9conciliation et un esprit de pardon<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/article-levangelisation-une-mission-collaborative-damour\/\">L\u2019\u00e9vang\u00e9lisation : Une mission collaborative d\u2019amour<\/a><\/strong><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-lapproche-convaincante-du-pere-james-mallon-pour-transformer-les-paroisses-dune-mentalite-de-maintenance-en-une-communaute-missionnaire-florissante\/\">L\u2019approche du P\u00e8re James Mallon pour transformer les paroisses en communaut\u00e9s missionnaires florissantes<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-priere-et-le-service-qui-trouvent-grace-aux-yeux-de-dieu\/\">La pri\u00e8re et le service qui trouvent gr\u00e2ce aux yeux de Dieu<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-pouvoir-transformateur-de-lamour\/\">Le Pouvoir Transformateur de l\u2019Amour<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-puissance-surnaturelle-de-la-priere-et-de-lamour-envers-dieu\/\">La puissance surnaturelle de la pri\u00e8re et de l\u2019amour envers Dieu<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisation-au-quotidien\/\"><strong class=\"post-title\">L\u2019\u00c9vang\u00e9lisation au Quotidien<\/strong><\/a><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/chaque-acte-damour-est-evangelisation\/\">Chaque acte d\u2019amour est \u00e9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/aimer-jesus-et-le-faire-aimer\/\">Aimer J\u00e9sus et le Faire Aimer<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/adopter-un-style-de-vie-dadoration-et-de-louange\/\">Adopter un style de vie d\u2019adoration et de louange<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/priere-pour-demander-a-dieu-la-guerison\/\">Pri\u00e8re pour demander \u00e0 Dieu la gu\u00e9rison<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/ce-qui-a-prouve-attirer-les-gens-vers-le-christ\/\">Ce qui a prouv\u00e9 attirer les gens vers le Christ<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisation-trouver-la-vie-et-partager-la-vie\/\">L\u2019\u00c9vang\u00e9lisation : Trouver la Vie et Partager la Vie<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-leucharistie-source-et-sommet-de-toute-evangelisation\/\">L\u2019Eucharistie : Source et sommet de toute \u00e9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/etapes-pratiques-pour-atteindre-les-personnes-sans-communaute-chretienne\/\">Pistes pratiques pour atteindre les personnes \u00e9loign\u00e9es de la foi<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/guide-de-partage-de-la-bible-en-petits-groupes-une-approche-synodale\/\">Guide de Partage de la Bible en Petits Groupes : Une Approche Synodale<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/amener-quelquun-au-christ-en-suscitant-en-lui-un-sentiment-damour-et-de-louange-envers-dieu\/\">Amener quelqu\u2019un au Christ en suscitant en lui un sentiment d\u2019amour et de louange envers Dieu<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/proclamer-la-parole-de-dieu-un-appel-sacre\/\">Proclamer la parole de Dieu : Un appel sacr\u00e9\u00a0<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/du-declin-au-renouveau-la-transformation-de-leglise-new-life-de-farmington\/\">Du d\u00e9clin au Renouveau : La Transformation de l\u2019\u00c9glise New Life de Farmington<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/lenseignement-social-de-leglise-et-levangelisation\/\">La doctrine sociale de l\u2019\u00c9glise et l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-bienveillance-une-perspective-chretienne\/\">La Bienveillance : Une Perspective Chr\u00e9tienne<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/comment-amener-quelquun-au-christ\/\">Comment amener quelqu\u2019un au Christ<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-finalite-ultime-de-la-vie-humaine-glorifier-dieu\/\">La finalit\u00e9 ultime de la vie humaine \u2013 Glorifier Dieu<\/a><\/strong><\/strong><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/de-lagonie-a-une-nouvelle-vie-le-parcours-de-revitalisation-dune-eglise-de-campagne\/\"><strong class=\"post-title\">De l\u2019Agonie \u00e0 une Nouvelle Vie : Le Parcours de Revitalisation d\u2019une \u00c9glise de Campagne<\/strong><\/a><\/strong><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisation-en-une-phrase-goutez-et-voyez-le-seigneur-est-bon-psaume-349\/\">L\u2019\u00e9vang\u00e9lisation en une phrase: \u00ab Go\u00fbtez et voyez : le Seigneur est bon ! \u00bb (Psaume 34,9)<\/a><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-renouveau-des-eglises-rurales\/\">Le renouveau des \u00e9glises rurales<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-repondre-a-la-baisse-de-frequentation-de-nos-eglises\/\">Facteurs cl\u00e9s attirant les gens vers la foi catholique<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/repondre-a-la-diminution-de-laffluence-dans-nos-eglises\/\">R\u00e9pondre \u00e0 la baisse de fr\u00e9quentation de nos \u00e9glises<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/favoriser-une-atmosphere-sacree-lors-de-la-liturgie-dominicale\/\">Favoriser une Atmosph\u00e8re Sacr\u00e9e lors de la Liturgie Dominicale<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/prier\/priere-pour-recevoir-le-bapteme-dans-lesprit-saint\/\">Pri\u00e8re pour recevoir le bapt\u00eame dans l\u2019Esprit-Saint<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-soif-ardente-du-christ-pour-les-mes\/\">La Soif Ardente du Christ pour les \u00c2mes<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/partager-la-bonne-nouvelle-avec-les-noms-redempteurs-de-dieu\/\">Prier et Partager la Bonne Nouvelle avec les Noms R\u00e9dempteurs de Dieu<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/repondre-a-lappel-a-evangeliser\/\">R\u00e9pondre \u00e0 l\u2019Appel \u00e0 \u00c9vang\u00e9liser<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-quelle-est-la-chose-qui-plait-le-plus-a-dieu-amener-les-ames-au-christ\/\">Qu\u2019est ce qui pla\u00eet le plus \u00e0 Dieu ? Amener les \u00e2mes au Christ<\/a><\/strong><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-croissance-de-leglise-de-la-nativite-p-michael-white\/\">La croissance de l\u2019\u00c9glise de la Nativit\u00e9 (P. Michael White)<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-croissance-de-la-paroisse-saint-benedict-james-mallon\/\">La croissance de la paroisse Saint-Benedict (James Mallon)<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-cinq-piliers-de-la-foi-chretienne\/\">Cinq piliers de la vie chr\u00e9tienne<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-rencontre-personnelle-avec-jesus\/\">Rencontrer J\u00e9sus: Chemin de Transformation Personnelle<\/a><\/strong><\/strong><strong><strong class=\"post-title\"><br \/><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/que-signifie-avoir-une-relation-personnelle-avec-jesus\/\">Que signifie avoir une relation personnelle avec J\u00e9sus ?<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/liberer-le-potentiel-devangelisation-de-votre-paroisse\/\">Lib\u00e9rer le potentiel d\u2019\u00e9vang\u00e9lisation de votre paroisse<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-lobjectif-ultime-de-levangelisation\/\">L\u2019objectif ultime de l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/strong><\/li>\r\n<li><strong><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-la-soif-damour-de-dieu-et-notre-mission-de-la-faire-connaitre\/\">La soif d\u2019amour de Dieu et notre mission de la faire conna\u00eetre<\/a><\/strong><\/strong><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/des-dimanches-memorables\/\">Des dimanches m\u00e9morables<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-plan-en-trois-etapes-du-pere-bedard-pour-evangeliser\/\"><strong>Le plan en trois \u00e9tapes du p\u00e8re B\u00e9d<\/strong>ard pour \u00e9vang\u00e9liser<\/a><\/strong><\/strong><\/li>\r\n<li><strong class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/GUIDE-POUR-LA-TRANSFORMATION-MISSIONNAIRE-DES-PAROISSES.pdf\">Guide pour la transformation missionnaire des paroisses<\/a><\/strong><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/un-guide-pratique-pour-demarrer-un-petit-groupe-devangelisation\/\">Semeurs de foi : Un guide pratique pour d\u00e9marrer un petit groupe d\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-transformation-missionnaire-de-la-paroisse-de-santeustorgio\/\">La transformation missionnaire de la paroisse de Sant\u2019Eustorgio<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/creer-des-communautes-catholiques-dynamiques-sagesse-tiree-du-livre-excellent-catholic-parishes\/\"><strong class=\"post-title\">Cr\u00e9er des Communaut\u00e9s Catholiques Dynamiques : Sagesse tir\u00e9e du livre \u2018Excellent Catholic Parishes\u2019<\/strong><\/a><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/partager-levangile-en-fonction-des-besoins-et-de-la-receptivite-des-gens\/\"><strong class=\"post-title\">Partager l\u2019\u00c9vangile en fonction des besoins et de la r\u00e9ceptivit\u00e9 des gens<\/strong><\/a><\/strong><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-priere-pour-inviter-des-personnes-a-des-rencontres-devangelisation\/\">Une pri\u00e8re pour inviter des personnes \u00e0 des rencontres d\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/accueillir-les-invites-et-les-visiteurs-a-leglise\/\">Accueillir les invit\u00e9s et les visiteurs \u00e0 l\u2019\u00e9glise: les choses \u00e0 faire et \u00e0 ne pas faire<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/caracteristiques-dune-paroisse-evangelisatrice\/\">Caract\u00e9ristiques d\u2019une paroisse \u00e9vang\u00e9lisatrice<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/differentes-dimensions-de-levangelisation\/\">Diff\u00e9rentes dimensions de l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-la-vraie-mesure-du-succes\/\"><strong class=\"post-title\">La vraie mesure du succ\u00e8s<\/strong><\/a><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/article-le-pape-francois-sur-levangelisation\/\">Le pape Francois sur l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/reveiller-la-paroisse-rurale-pour-levangelisation\/\">R\u00e9veiller la paroisse rurale pour l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quest-ce-qui-amene-les-gens-au-christ\/\">Qu\u2019est-ce qui am\u00e8ne les gens au Christ ?<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-evangeliser-par-des-petits-actes-de-gentillesse\/\">\u00c9vang\u00e9liser par des petits actes de gentillesse<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-des-questions-pour-entamer-des-conversations-spirituelles\/\"><strong class=\"post-title\">Des questions pour entamer des conversations spirituelles<\/strong><\/a><\/li>\r\n<li><strong class=\"post-title\"><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/a-trois-pieds-de-lor\/\">\u00c0 trois pieds de l\u2019or<\/a><\/strong><\/strong><\/li>\r\n<li><strong class=\"post-title\"><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/evangeliser-a-travers-nos-interactions-sociales\/\">\u00c9vang\u00e9liser en d\u00e9veloppant nos comp\u00e9tences sociales<\/a><\/strong><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/rassembler-temoigner-et-inviter\/\">Rassembler, t\u00e9moigner et inviter<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/priere-pour-recevoir-les-dons-spirituels-du-saint-esprit\/\"><strong class=\"post-title\">Pri\u00e8re pour recevoir les dons spirituels du Saint Esprit<\/strong><\/a><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-langage-de-la-croix-la-voix-de-levangelisation\/\">Le langage de la croix est le langage de l\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-facteurs-cles-pour-la-croissance-de-la-paroisse\/\">Facteurs cl\u00e9s pour la croissance de la paroisse selon Rich Birch<\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-comment-vaincre-satan\/\"><strong class=\"post-title\">Comment vaincre Satan ?<\/strong><\/a><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/apporter-amour-espoir-et-guerison-par-levangile\/\"><strong class=\"post-title\">Apporter Amour, Espoir et Gu\u00e9rison par l\u2019\u00c9vangile<\/strong><\/a><\/li>\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-quest-ce-que-lamour\/\"><strong class=\"post-title\">Qu\u2019est-ce que l\u2019amour ?<\/strong><\/a><\/strong><\/li>\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-touche-par-le-maitre\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Touch\u00e9 par le Ma\u00eetre<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-un-homme-un-chien-et-lamour-ultime\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Un homme, un chien, et l\u2019amour ultime<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/des-facons-pratiques-daimer-les-autres\/\"><strong>A<\/strong><\/a><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/des-facons-pratiques-daimer-les-autres\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>u c\u0153ur de l\u2019\u00e9vang\u00e9lisation : Aimer Dieu et les autres<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/aimer-nos-ennemis-et-se-reconcilier-avec-les-autres\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Aimer nos ennemis et se r\u00e9concilier avec les autres<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-priere-bibique-pour-la-guerison\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pri\u00e8re pour la gu\u00e9rison : Tu es le Seigneur qui me gu\u00e9rit<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-vivre-une-vie-damour-lheritage-de-mere-teresa\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Vivre une vie d\u2019amour : L\u2019h\u00e9ritage de M\u00e8re Teresa<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-force-puissante-est-a-loeuvre\/\"><strong>Sous le <\/strong><\/a><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-force-puissante-est-a-loeuvre\/\" target=\"_blank\" rel=\"noreferrer noopener\">c<\/a><\/strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/une-force-puissante-est-a-loeuvre\/\"><strong>ouvert des t\u00e9n\u00e8bres, une force puissante est \u00e0 l\u2019\u0153uvre<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-evangeliser-avec-amour-et-pour-lamour\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Vivre une vie d\u2019amour : Le\u00e7ons du Nouveau Testament<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/19-orientations-pastorales-pour-le-renouveau-et-la-croissance-des-paroisses\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>19 orientations pastorales qui contribuent \u00e0 la croissance des paroisses<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/le-renouveau-missionnaire-de-la-catechese\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Le renouveau missionnaire de la cat\u00e9ch\u00e8se<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/les-caracteristiques-des-paroisses-missionnaires\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Les caract\u00e9ristiques des paroisses missionnaires<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/priere-de-guerison\/\"><strong>Pri\u00e8re de gu\u00e9rison attribu\u00e9e \u00e0 saint Padre Pio<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/partager-notre-foi\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Nous sommes appel\u00e9s \u00e0 partager notre foi avec les autres<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/devrait-on-chercher-la-croissance-de-leglise\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Devrait-on chercher la croissance de l\u2019\u00c9glise ?<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/trouvez-un-besoin-et-comblez-le\/\" target=\"_blank\" rel=\"noreferrer noopener\">Trouvez un besoin et comblez-le : R\u00e9v\u00e9ler le c\u0153ur de Dieu dans son quartier<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/evangeliser-au-quotidien\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>15 habitudes pour \u00e9vang\u00e9liser au quotidien<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-mission-de-leglise\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>La mission de l\u2019\u00c9glise<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/trois-obstacles-a-letablissement-dune-culture-dinvitation-dans-votre-paroisse\/\" target=\"_blank\" rel=\"noreferrer noopener\">Trois obstacles \u00e0 l\u2019\u00e9tablissement d\u2019une culture d\u2019invitation dans votre paroisse<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisateur-relationnel\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>L\u2019\u00e9vang\u00e9lisateur relationnel<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/faire-eglise-a-la-maison\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Faire \u00c9glise \u00e0 la maison<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-fille-aveugle\/\" target=\"_blank\" rel=\"noreferrer noopener\">La fille aveugle<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/un-groupe-de-gernouilles\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Un groupe de grenouilles<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/lelephant-attache\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>L\u2019\u00e9l\u00e9phant attach\u00e9<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/paroisse-de-la-nativite\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Le renouveau de la paroisse de la Nativit\u00e9 \u00e0 Baltimore<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-foi-grandit-copy\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>La foi grandit lorsqu\u2019on la partage<\/strong><\/a><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/dans-les-souliers-des-sans-eglises\/\" target=\"_blank\" rel=\"noreferrer noopener\">Dans les souliers des \u201csans-\u00e9glises\u201d<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-cellules-paroissiales-devangelisation-2-copy\/\" target=\"_blank\" rel=\"noreferrer noopener\">Les cellules paroissiales d\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/caracteristiques-uniques-des-paroisses-missionnaires\/\" target=\"_blank\" rel=\"noreferrer noopener\">Six caract\u00e9ristiques uniques des paroisses missionnaires<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/devenir-une-paroisse-missionnaire\/\" target=\"_blank\" rel=\"noreferrer noopener\">Quelques \u00e9tapes pour devenir une paroisse missionnaire<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/quest-ce-que-levangelisation\/\" target=\"_blank\" rel=\"noreferrer noopener\">Qu\u2019est-ce que l\u2019\u00e9vang\u00e9lisation et dans quel esprit la pratiquer ?<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/auto-evaluation\/\" target=\"_blank\" rel=\"noreferrer noopener\">Questions de discussion et d\u2019auto-\u00e9valuation pour l\u2019\u00e9vang\u00e9lisation en paroisse<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-priere-de-jesus\/\" target=\"_blank\" rel=\"noreferrer noopener\">La pri\u00e8re de J\u00e9sus: une m\u00e9thode pour prier en tout temps<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/pratiquer-leur-foi\/\" target=\"_blank\" rel=\"noreferrer noopener\">Qu\u2019est-ce qui peut aider les enfants \u00e9lev\u00e9s dans la religion catholique \u00e0 continuer \u00e0 pratiquer leur foi \u00e0 l\u2019\u00e2ge adulte ?<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-tactiques-de-satan-1ere-partie\/\" target=\"_blank\" rel=\"noreferrer noopener\">Les tactiques de Satan<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/apprendre-a-etre-missionnaire\/\" target=\"_blank\" rel=\"noreferrer noopener\">Apprendre \u00e0 \u00eatre missionnaire<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/quand-nous-crions-vers-dieu\/\" target=\"_blank\" rel=\"noreferrer noopener\">Quand nous crions vers Dieu, il r\u00e9pond<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent-copy\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pr\u00e9sence et Proclamation<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sauver ceux qui se perdent<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-paroisse-saint-nazaire-lhistoire-dune-transformation-missionnaire\/\" target=\"_blank\" rel=\"noreferrer noopener\">La paroisse Saint-Nazaire: L\u2019histoire d\u2019une transformation missionnaire<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/evangelisation-et-petits-groupes-de-partage\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9vang\u00e9lisation et petits groupes de partage<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/evangeliser-en-invitant-des-personnes-a-recevoir-jesus-comme-seigneur-et-sauveur\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9vang\u00e9liser en invitant des personnes \u00e0 recevoir J\u00e9sus comme Seigneur et Sauveur<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/vous-allez-recevoir-une-force\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vous allez recevoir une force\u2026<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/avez-vous-entendu-parler-de-la-loi-des-trois-ecoutes-et-des-sept-contacts\/\" target=\"_blank\" rel=\"noreferrer noopener\">Avez-vous entendu parler de la loi des trois \u00e9coutes et des sept contacts ?<\/a><\/strong><\/li>\r\n\r\n\r\n\r\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/trois-habitudes-dune-vie-chretienne-fructueuse\/\" target=\"_blank\" rel=\"noreferrer noopener\">Trois habitudes d\u2019une vie chr\u00e9tienne fructueuse<\/a><\/strong><\/li>\r\n<\/ul>\r\n<p class=\"has-text-align-right\"><!-- \/wp:post-content -->\r\n\r\n<!-- wp:separator --><\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p class=\"has-text-align-right\"><!-- \/wp:separator -->\r\n\r\n<!-- wp:shortcode --><\/p>\r\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\"> <a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1993 size-full\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying-100x100.png 100w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\r\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\">LECTURES RECOMMANDEES<\/a><\/h4>\r\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\" target=\"_self\" >En savoir plus <\/a>\r\n<\/div>\r\n<p class=\"has-text-align-right\"><!-- \/wp:shortcode -->\r\n\r\n<!-- wp:shortcode --><\/p>\r\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\"> <a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/prayer-group\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3620\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-300x300.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-300x300.png 300w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-100x100.png 100w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-400x400.png 400w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-210x210.png 210w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle.png 684w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\r\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/prayer-group\/\">PRI\u00c8RES ET GROUPES DE PRIERE POUR LE PROJET DIOC\u00c9SAIN DE NOUVELLE \u00c9VANG\u00c9LISATION<\/a><\/h4>\r\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"\/fr\/nouvelle-evangelisation\/prayer-group\/\" target=\"_self\" >En savoir plus<\/a>\r\n<\/div>\r\n<p class=\"has-text-align-right\"><!-- \/wp:shortcode -->\r\n\r\n<!-- wp:shortcode --><\/p>\r\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\"> <a href=\"https:\/\/pembrokediocese.com\/fr\/don\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7117 size-medium aligncenter\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-200x200.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-200x200.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-768x768.png 768w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-100x100.png 100w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-400x400.png 400w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-210x210.png 210w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept.png 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\r\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/don\/\">DONNER POUR LE PROJET DIOC\u00c9SAIN DE NOUVELLE \u00c9VANG\u00c9LISATION<\/a><\/h4>\r\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"https:\/\/pembrokediocese.com\/donate\/\" target=\"_self\" >En savoir plus<\/a>\r\n<\/div>\r\n<p class=\"has-text-align-right\"><!-- \/wp:shortcode --><\/p>","protected":false},"excerpt":{"rendered":"<p>(Image: The Lost Sheep by Robert T Barrett | Altus Fine Art) Du C\u0153ur de l\u2019\u00c9glise jaillit une vision \u00e0 deux facettes : d\u2019une part, contempler et adh\u00e9rer \u00e0 la volont\u00e9 de Dieu qui veut sauver toute l\u2019humanit\u00e9 ; d\u2019autre part, reconna\u00eetre et susciter, en chaque baptis\u00e9, la vocation de disciple missionnaire. Ces deux piliers forment le fondement m\u00eame d\u2019une \u00c9glise missionnaire. La volont\u00e9 salvifique universelle de Dieu L\u2019\u00c9criture affirme sans d\u00e9tour : \u00ab Dieu veut que tous les hommes soient sauv\u00e9s et parviennent \u00e0 la connaissance de la v\u00e9rit\u00e9 \u00bb (1 Tm 2,4). Depuis le r\u00e9cit de la Cr\u00e9ation en Gen\u00e8se jusqu\u2019\u00e0 la vision ultime de l\u2019Apocalypse, la Bible r\u00e9v\u00e8le un Dieu qui n\u2019est ni passif ni exclusif, mais qui tend activement la main \u00e0 toutes les nations, \u00e0 tous les peuples. Le Christ lui-m\u00eame d\u00e9clare : \u00ab Et moi, quand j\u2019aurai \u00e9t\u00e9 \u00e9lev\u00e9 de terre, j\u2019attirerai \u00e0 moi tous les hommes \u00bb (Jn 12,32). Sa mission de salut est universelle. Le Cat\u00e9chisme de l\u2019\u00c9glise catholique reprend cette v\u00e9rit\u00e9 avec force : \u00ab Par sa mort et sa R\u00e9surrection, J\u00e9sus-Christ a ouvert \u00e0 tous les hommes l\u2019acc\u00e8s \u00e0 la vie \u00e9ternelle \u00bb (CEC, n\u00b0 1026). Le Concile Vatican II a rappel\u00e9 avec une intensit\u00e9 renouvel\u00e9e cette universalit\u00e9, notamment dans Lumen Gentium et Gaudium et Spes. D\u00e8s lors, les pasteurs de l\u2019\u00c9glise ne peuvent se contenter de veiller sur ceux qui fr\u00e9quentent d\u00e9j\u00e0 les bancs des assembl\u00e9es ; ils sont appel\u00e9s \u00e0 chercher activement ceux et celles qui sont perdus, \u00e0 l\u2019image du Bon Pasteur : \u00ab Quel homme parmi vous, s\u2019il a cent brebis et qu\u2019il en perde une, ne laisse les quatre-vingt-dix-neuf autres au d\u00e9sert pour aller \u00e0 celle qui est perdue, jusqu\u2019\u00e0 ce qu\u2019il la retrouve ? \u00bb (Lc 15,4-7). Tout chr\u00e9tien est envoy\u00e9 L\u2019\u00c9glise n\u2019est pas simplement un refuge pour les croyants ; elle est, par essence, missionnaire. Le pape Fran\u00e7ois l\u2019affirme dans Evangelii Gaudium, n\u00b0 20 : \u00ab L\u2019action missionnaire est le paradigme de toute \u0153uvre de l\u2019\u00c9glise. \u00bb Le d\u00e9cret Ad Gentes du Concile Vatican II proclame de m\u00eame : \u00ab L\u2019\u00c9glise en p\u00e8lerinage est, par nature, missionnaire \u00bb (n\u00b0 2). Cette identit\u00e9 missionnaire n\u2019est pas r\u00e9serv\u00e9e au clerg\u00e9 ou aux religieux. Par le Bapt\u00eame et la Confirmation, chaque chr\u00e9tien est appel\u00e9 \u00e0 participer \u00e0 la mission de l\u2019\u00c9glise. Saint Jean-Paul II, dans Redemptoris Missio, n\u00b0 71, insiste : \u00ab Tous les la\u00efcs sont missionnaires en vertu de leur bapt\u00eame. \u00bb Cette conviction doit transformer le regard des responsables eccl\u00e9siaux : le peuple confi\u00e9 \u00e0 leurs soins n\u2019est pas une assembl\u00e9e passive de consommateurs de services religieux, mais un corps vivant de t\u00e9moins actifs de l\u2019\u00c9vangile. Chaque paroissien, chaque membre du Corps du Christ doit \u00eatre appel\u00e9 \u00e0 devenir missionnaire, dans sa famille, sur son lieu de travail, dans la soci\u00e9t\u00e9 tout enti\u00e8re. L\u2019exp\u00e9rience des \u00c9glises en croissance : exemples contemporains Dans de nombreuses r\u00e9gions du monde, les communaut\u00e9s chr\u00e9tiennes qui connaissent une croissance durable partagent deux traits essentiels : elles s\u2019appuient sur la conscience vive de la volont\u00e9 universelle de salut de Dieu, et elles mobilisent effectivement tous les croyants comme missionnaires. Ainsi, [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":17373,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[84,156],"tags":[],"class_list":["post-17377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-article","category-textes-a-lire"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/17377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/comments?post=17377"}],"version-history":[{"count":5,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/17377\/revisions"}],"predecessor-version":[{"id":17818,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/17377\/revisions\/17818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media\/17373"}],"wp:attachment":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media?parent=17377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/categories?post=17377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/tags?post=17377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}