{"id":17908,"date":"2025-09-23T09:24:23","date_gmt":"2025-09-23T13:24:23","guid":{"rendered":"https:\/\/pembrokediocese.com\/?p=17908"},"modified":"2025-09-23T09:26:18","modified_gmt":"2025-09-23T13:26:18","slug":"bulletin-hebdomadaire-le-23-septembre-2025-st-pio-de-pietrelcina-pretre","status":"publish","type":"post","link":"https:\/\/pembrokediocese.com\/fr\/article\/bulletin-hebdomadaire-le-23-septembre-2025-st-pio-de-pietrelcina-pretre\/","title":{"rendered":"BULLETIN HEBDOMADAIRE  &#8211; le 23 septembre 2025 (St Pio de Pietrelcina, Pr\u00eatre)"},"content":{"rendered":"<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n\r\n\r\n<h4 class=\"wp-block-heading\"><strong><i><a href=\"mailto:reception@pembrokediocese.com?subject=Abonnez-vous au bulletin hebdomadaire&amp;amp;body=Bonjour, je souhaite m'abonner au Bulletin Hebdomadaire s'il vous plait. Merci.\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-8004\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr-200x205.png\" alt=\"\" width=\"124\" height=\"127\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr-200x205.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr-768x785.png 768w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr.png 840w\" sizes=\"(max-width: 124px) 100vw, 124px\" \/><\/a><\/i><\/strong><\/h4>\r\n\r\n\r\n\r\n<h1 class=\"wp-block-heading\"><em><strong>Ma m\u00e8re et mes fr\u00e8res sont ceux qui \u00e9coutent la parole de Dieu, et qui la mettent en pratique.<\/strong><\/em><\/h1>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>(Luc 8, 19-21)<\/strong><\/h3>\r\n\r\n\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n<p>\r\n\r\n<\/p>\r\n<h2><strong>DU DIOC\u00c8SE<\/strong><\/h2>\r\n<h3><strong>Pri\u00e8res<\/strong><\/h3>\r\n<p>Pour le repos de l&rsquo;\u00e2me de S\u0153ur Marguerite Somers (S\u0153ur Mary Sheila), S\u0153ur Grise de l&rsquo;Immacul\u00e9e Conception, d\u00e9c\u00e9d\u00e9e le 15 septembre dans sa 80<sup>e<\/sup> ann\u00e9e de vie religieuse.<\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p>\r\n\r\n<\/p>\r\n<h2><strong>DE LA CECC<\/strong><\/h2>\r\n<h3><strong>Collecte 2025 pour les besoins de l\u2019\u00c9glise au Canada \u2013 lundi, septembre 22, 2025\u00a0<\/strong><\/h3>\r\n<p>La Collecte annuelle pour les besoins de l\u2019\u00c9glise au Canada aura lieu <strong>les\u00a027 et 28 septembre 2025<\/strong>. Cette initiative annuelle aide les \u00e9v\u00eaques dans leur minist\u00e8re d\u2019accompagnement, d\u2019enseignement, de direction, de sanctification et de soin de l\u2019\u00c9glise au Canada.<\/p>\r\n<p>Dans l\u2019exercice de leurs responsabilit\u00e9s \u00e9piscopales, les \u00e9v\u00eaques continuent de travailler en collaboration sur des questions doctrinales et \u00e9thiques importantes; le dialogue \u0153cum\u00e9nique et interreligieux; l\u2019\u00e9vang\u00e9lisation, la formation \u00e0 la foi et la cat\u00e9ch\u00e8se; les enjeux de justice sociale; le minist\u00e8re responsable; la promotion d\u2019une culture de la vie et de la famille; la liturgie; ainsi que les relations avec les peuples autochtones.<\/p>\r\n<p>Participer \u00e0 cette Collecte permet aux \u00e9v\u00eaques de soutenir ces initiatives essentielles, contribuant ainsi \u00e0 la mission pastorale et spirituelle de l\u2019\u00c9glise \u00e0 l\u2019\u00e9chelle nationale.<\/p>\r\n<p>Tous les fid\u00e8les sont encourag\u00e9s \u00e0 contribuer g\u00e9n\u00e9reusement \u00e0 la Collecte de cette ann\u00e9e.<\/p>\r\n<h3><strong>Lettre de suivi du pr\u00e9sident de la CECC au minist\u00e8re f\u00e9d\u00e9ral des Finances concernant\u00a0: \u00ab\u00a0Statut d\u2019organisme de bienfaisance\u00a0\u00bb (2025)\u00a0<\/strong><\/h3>\r\n<p>La lettre compl\u00e8te peut \u00eatre consult\u00e9e ici\u00a0: <a href=\"https:\/\/www.cecc.ca\/wp-content\/uploads\/2025\/09\/2025-09-12-Lettre-de-la-CECC-a-Lhonorable-Francois-Philippe-Champagne-depute.pdf\">2025-09-12-Lettre-de-la-CECC-a-Lhonorable-Francois-Philippe-Champagne-depute.pdf<\/a>.<\/p>\r\n<h3><strong>Les \u00e9v\u00eaques Catholiques du Canada se r\u00e9unissent \u00e0 l\u2019occasion de la r\u00e9union annuelle de l\u2019Assembl\u00e9e pl\u00e9ni\u00e8re<\/strong><em>\u00a0<\/em><\/h3>\r\n<p><strong>Ottawa, 15 septembre, 2025<\/strong> \u2013 Cette semaine (22 au 26 septembre 2025), les membres de la Conf\u00e9rence des \u00e9v\u00eaques catholiques du Canada (CECC) se r\u00e9uniront \u00e0 Montr\u00e9al (Qu\u00e9bec) pour la r\u00e9union annuelle de l\u2019Assembl\u00e9e pl\u00e9ni\u00e8re. Cette r\u00e9union est toujours ax\u00e9e sur la mani\u00e8re dont les \u00e9v\u00eaques du Canada peuvent servir la mission de l\u2019\u00c9glise au niveau national. Au cours de cette semaine de discussion sous la conduite de l\u2019Esprit Saint, plusieurs th\u00e8mes seront abord\u00e9s, notamment : <a href=\"https:\/\/www.cecc.ca\/communique-de-presse\/les-eveques-catholiques-du-canada-se-reunissent-a-loccasion-de-la-reunion-annuelle-de-lassemblee-pleniere\/\">(Lire la suite\u2026)<\/a><\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p>\r\n\r\n<\/p>\r\n<h2><strong>LE SAINT-SI\u00c8GE<\/strong><\/h2>\r\n<h3><strong>Intention de pri\u00e8re du Saint-P\u00e8re pour le mois de septembre 2025\u00a0<\/strong><\/h3>\r\n<p><strong>Pour notre relation avec la Cr\u00e9ation<\/strong>\u00a0\u2013 Prions pour que, inspir\u00e9s par saint Fran\u00e7ois, nous fassions l\u2019exp\u00e9rience de notre interd\u00e9pendance avec toutes les cr\u00e9atures, aim\u00e9es de Dieu et dignes d\u2019amour et de respect.<\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p>\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<h2 class=\"wp-block-heading\"><strong>JUBIL\u00c9 2025<\/strong><\/h2>\r\n<h3><strong>L&rsquo;\u00e9glise Ste Mary de Wilno &#8211; Indulgence jubilaire<\/strong><\/h3>\r\n<p>L&rsquo;\u00e9glise Ste Mary de Wilno est l&rsquo;\u00e9glise d\u00e9sign\u00e9e pour l&rsquo;indulgence jubilaire <strong>le mardi 7 octobre 2025, jour de la f\u00eate de Notre-Dame du Rosaire. <\/strong>La messe sera c\u00e9l\u00e9br\u00e9e \u00e0 11h00, suivie de l&rsquo;exposition du Saint-Sacrement tout au long de la journ\u00e9e, et se terminera par le rosaire \u00e0 15h30 et la b\u00e9n\u00e9diction \u00e0 16h00. Les confessions auront lieu de 12 h \u00e0 13 h et de 15 h \u00e0 16 h. Veuillez consulter le site <a href=\"https:\/\/pembrokediocese.com\/fr\/article\/jubile-2025-indulgence-fr\/\">Jubil\u00e9 2025 \u2013 Indulgence \u2013 Diocese of Pembroke<\/a> pour plus d&rsquo;informations sur les gr\u00e2ces de l&rsquo;indulgence jubilaire.<\/p>\r\n<h3><strong>15<sup>e<\/sup> anniversaire de la canonisation de saint fr\u00e8re Andr\u00e9\u00a0<\/strong><\/h3>\r\n<p>P\u00e8lerinage d&rsquo;automne \u00e0 l&rsquo;Oratoire Saint-Joseph dans le cadre du jubil\u00e9 2025 P\u00e8lerins d\u2019esp\u00e9rance, <strong>le dimanche 12 octobre 2025<\/strong>, provenant des archidioc\u00e8ses d&rsquo;Ottawa-Cornwall, de Kingston et de Gatineau, ainsi que des dioc\u00e8ses de Pembroke, de Saint-J\u00e9r\u00f4me et de Mont-Laurier. Pour plus d&rsquo;informations, veuillez contacter Mike Budge au 613 224-8110 ou Liane Ladouceur au 819 661-9426.<\/p>\r\n<h3><strong>Calendrier des Grands \u00c9v\u00e8nements pour le Jubil\u00e9 2025\u00a0<\/strong><\/h3>\r\n<p><a href=\"https:\/\/pembrokediocese.com\/fr\/jubile-2025\/\">Jubil\u00e9 2025 \u2013 Diocese of Pembroke<\/a><\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<h2 class=\"wp-block-heading\"><strong>\u00c9VANG\u00c9LISATION<\/strong><\/h2>\r\n<h3><strong>L\u2019\u00e9vang\u00e9lisation authentique et la pr\u00e9vention du fanatisme <\/strong><\/h3>\r\n<p><em>Par Dr Pierre-Alain Giffard<\/em><\/p>\r\n<p>D\u00e8s que J\u00e9sus a ordonn\u00e9 \u00e0 ses disciples\u202f: \u00ab\u202fAllez, faites de toutes les nations des disciples, les baptisant au nom du P\u00e8re, du Fils et du Saint\u2011Esprit, et enseignez\u2011leur \u00e0 observer tout ce que je vous ai prescrit\u202f\u00bb (Matthieu\u202f28,19\u201120), l\u2019\u00e9vang\u00e9lisation s\u2019est inscrite dans l\u2019ADN m\u00eame de l\u2019\u00c9glise. Le Concile Vatican\u202fII nous rappelle que l\u2019\u00c9glise en p\u00e8lerinage \u00ab\u202fexiste pour \u00eatre\u2026 un sacrement universel de salut\u202f\u00bb, pouss\u00e9e par l\u2019amour divin \u00e0 porter l\u2019\u00c9vangile \u00e0 chaque personne. <a href=\"https:\/\/pembrokediocese.com\/fr\/article\/article-levangelisation-authentique-et-la-prevention-du-fanatisme\/\">(Lire la suite\u2026)<\/a><\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<h2><strong>AUTRES<\/strong><\/h2>\r\n<h3><strong>\u00ab\u00a0Le fils prodigue \u2013 Recueil de po\u00e8mes\u00a0\u00bb\u00a0<\/strong><\/h3>\r\n<p>P\u00e8re R\u00e9al Ouellette a publi\u00e9 un livre intitul\u00e9 \u00ab\u00a0Le fils prodigue &#8211; Recueil de po\u00e8mes\u00a0\u00bb. Par la po\u00e9sie, il explore, verset par verset les \u00e9motions et mouvements de la c\u00e9l\u00e8bre parabole du Fils prodigue. Pour plus d&rsquo;information, veuillez consulter son site web\u00a0<em>: <\/em><a href=\"https:\/\/padrereal.com\/\">https:\/\/padrereal.com\/<\/a><em>. <\/em><\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Ma m\u00e8re et mes fr\u00e8res sont ceux qui \u00e9coutent la parole de Dieu, et qui la mettent en pratique. (Luc 8, 19-21)<\/p>\n","protected":false},"author":10,"featured_media":3815,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[114,84],"tags":[],"class_list":["post-17908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bulletin","category-article"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/17908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/comments?post=17908"}],"version-history":[{"count":4,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/17908\/revisions"}],"predecessor-version":[{"id":17912,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/17908\/revisions\/17912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media\/3815"}],"wp:attachment":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media?parent=17908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/categories?post=17908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/tags?post=17908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}