{"id":18533,"date":"2026-02-03T09:52:30","date_gmt":"2026-02-03T14:52:30","guid":{"rendered":"https:\/\/pembrokediocese.com\/?p=18533"},"modified":"2026-02-03T09:53:41","modified_gmt":"2026-02-03T14:53:41","slug":"bulletin-hebdomadaire-le-3-fevrier-2026-ferie","status":"publish","type":"post","link":"https:\/\/pembrokediocese.com\/fr\/article\/bulletin-hebdomadaire-le-3-fevrier-2026-ferie\/","title":{"rendered":"BULLETIN HEBDOMADAIRE  &#8211; le 3 f\u00e9vrier 2026 (F\u00e9rie)"},"content":{"rendered":"<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n\r\n\r\n<h4 class=\"wp-block-heading\"><strong><i><a href=\"mailto:reception@pembrokediocese.com?subject=Abonnez-vous au bulletin hebdomadaire&amp;amp;body=Bonjour, je souhaite m'abonner au Bulletin Hebdomadaire s'il vous plait. Merci.\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-8004\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr-200x205.png\" alt=\"\" width=\"124\" height=\"127\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr-200x205.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr-768x785.png 768w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr.png 840w\" sizes=\"(max-width: 124px) 100vw, 124px\" \/><\/a><\/i><\/strong><\/h4>\r\n\r\n\r\n\r\n<h1 class=\"wp-block-heading\"><strong><em>\u00ab\u00a0Jeune fille, l\u00e8ve-toi !\u00a0\u00bb<\/em><\/strong><\/h1>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>(Marc 5, 21-43)<\/strong><\/h3>\r\n\r\n\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<h2><strong>DU DIOC\u00c8SE<\/strong><\/h2>\r\n<h3><strong>Planification pastorale \u2013 Marcher ensemble dans l\u2019esp\u00e9rance<\/strong><\/h3>\r\n<p><a href=\"https:\/\/pembrokediocese.com\/fr\/message-de-leveque\/lettre-de-mgr-brehl-25-janvier-2026\/\">Lettre de Mgr Brehl \u2013 25 janvier 2026.<\/a><\/p>\r\n<h3><strong>Les paroissiens du dioc\u00e8se de Pembroke sont invit\u00e9s \u00e0 r\u00e9server la date<\/strong><\/h3>\r\n<p>Les paroissiens du dioc\u00e8se de Pembroke sont invit\u00e9s \u00e0 r\u00e9server la date<em>\u202f<\/em>pour assister \u00e0 l&rsquo;une des r\u00e9unions d&rsquo;information sur la planification pastorale qui se tiendront dans les cinq doyenn\u00e9s du dioc\u00e8se au cours des premi\u00e8res semaines du Car\u00eame. Mgr Brehl et les membres du comit\u00e9 directeur dioc\u00e9sain pr\u00e9senteront des donn\u00e9es pastorales, statistiques et financi\u00e8res pertinentes afin d&rsquo;aider les paroissiens \u00e0 poursuivre le dialogue et le discernement sur l&rsquo;avenir du dioc\u00e8se. Si vous ne pouvez pas assister \u00e0 la r\u00e9union locale de votre doyenn\u00e9, vous \u00eates les bienvenus \u00e0 l&rsquo;une des autres r\u00e9unions pr\u00e9vues.\u202f\u00a0<\/p>\r\n<p><strong>Dates et lieux des r\u00e9unions du doyenn\u00e9\u00a0<\/strong><\/p>\r\n<ul>\r\n<li><strong>Doyenn\u00e9 de Renfrew\u00a0: mardi 17 f\u00e9vrier<\/strong> \u00e0 l&rsquo;\u00e9cole secondaire St. Joseph&rsquo;s, Renfrew &#8211; de 18 h 30 \u00e0 20 h 30\u00a0<\/li>\r\n<li><strong>Doyenn\u00e9 de Pembroke\u00a0: jeudi 19 f\u00e9vrier<\/strong> \u00e0 l&rsquo;\u00e9cole secondaire Bishop Smith, Pembroke &#8211; de 18 h 30 \u00e0 20 h 30\u00a0<\/li>\r\n<li><strong>Doyenn\u00e9 de Mattawa\u00a0: samedi 21 f\u00e9vrier<\/strong> \u00e0 la salle Corbeil Park, Corbeil &#8211; fran\u00e7ais de 10 h \u00e0 12 h ; anglais de 13 h \u00e0 15 h\u00a0<\/li>\r\n<li><strong>Doyenn\u00e9 de Pontiac\u00a0: samedi 28 f\u00e9vrier<\/strong> au Club de l&rsquo;\u00c2ge d&rsquo;Or, Fort-Coulonge &#8211; en fran\u00e7ais de 10 h \u00e0 12 h ; en anglais de 13 h \u00e0 15 h\u00a0<\/li>\r\n<li><strong>Doyenn\u00e9 de Barry&rsquo;s Bay\u00a0: dimanche 1er mars<\/strong> \u00e0 l&rsquo;\u00e9cole St. John Bosco, Barry&rsquo;s Bay &#8211; de 14 h \u00e0 16 h\u00a0<\/li>\r\n<\/ul>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p>\r\n\r\n\r\n\r\n<\/p>\r\n<h2><strong>LE SAINT-SI\u00c8GE<\/strong><\/h2>\r\n<h3><strong>Intention de pri\u00e8re du Saint-P\u00e8re pour le mois de f\u00e9vrier 2026\u00a0<\/strong><\/h3>\r\n<p><strong>Pour les enfants atteints de maladies incurables<\/strong> \u2013 Prions pour que les enfants atteints de maladies incurables ainsi que leurs familles re\u00e7oivent les soins m\u00e9dicaux et le soutien n\u00e9cessaires, sans jamais perdre force et esp\u00e9rance.<\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p>\r\n\r\n<\/p>\r\n<h2><strong>DE LA CECC<\/strong><\/h2>\r\n<h3><strong>Message du pape L\u00e9on XIV pour la 34<sup>e<\/sup> Journ\u00e9e mondiale du malade (11 f\u00e9vrier 2026)\u00a0<\/strong><\/h3>\r\n<p><strong>Ottawa\u00a0<\/strong>\u2013 Le message du pape L\u00e9on\u00a0XIV pour la\u00a0<em><a href=\"https:\/\/www.vatican.va\/content\/leo-xiv\/fr\/messages\/sick\/documents\/20260113-messaggio-giornata-malato.html\"><strong>34<sup>e<\/sup>\u00a0Journ\u00e9e mondiale du malade<\/strong><\/a>,<\/em>\u00a0qui sera c\u00e9l\u00e9br\u00e9e le mercredi\u00a011\u00a0f\u00e9vrier 2026, offre le th\u00e8me de\u00a0<strong>\u00ab<\/strong><strong>\u2009<\/strong><strong>La compassion du Samaritain<\/strong><strong>\u00a0<\/strong><strong>: aimer en portant la douleur de l<\/strong><strong>\u2019<\/strong><strong>autre<\/strong><strong>\u2009<\/strong><strong>\u00bb<\/strong>.\u00a0<a href=\"https:\/\/www.cecc.ca\/communique-de-presse\/message-du-pape-leon-xiv-pour-la-34e-journee-mondiale-du-malade-11-fevrier-2026\/\">(Lire la suite\u2026)<\/a><\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>&nbsp;<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Jeune fille, l\u00e8ve-toi !\u00a0\u00bb (Marc 5, 21-43)<\/p>\n","protected":false},"author":10,"featured_media":18023,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[114,84],"tags":[],"class_list":["post-18533","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bulletin","category-article"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/18533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/comments?post=18533"}],"version-history":[{"count":1,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/18533\/revisions"}],"predecessor-version":[{"id":18534,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/18533\/revisions\/18534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media\/18023"}],"wp:attachment":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media?parent=18533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/categories?post=18533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/tags?post=18533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}