{"id":18604,"date":"2026-02-18T14:18:32","date_gmt":"2026-02-18T19:18:32","guid":{"rendered":"https:\/\/pembrokediocese.com\/?p=18604"},"modified":"2026-02-18T14:19:19","modified_gmt":"2026-02-18T19:19:19","slug":"bulletin-hebdomadaire-le-18-fevrier-2026-mercredi-des-cendres","status":"publish","type":"post","link":"https:\/\/pembrokediocese.com\/fr\/article\/bulletin-hebdomadaire-le-18-fevrier-2026-mercredi-des-cendres\/","title":{"rendered":"BULLETIN HEBDOMADAIRE  &#8211; le 18 f\u00e9vrier 2026 (Mercredi des Cendres)"},"content":{"rendered":"<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n\r\n\r\n<h4 class=\"wp-block-heading\"><strong><i><a href=\"mailto:reception@pembrokediocese.com?subject=Abonnez-vous au bulletin hebdomadaire&amp;amp;body=Bonjour, je souhaite m'abonner au Bulletin Hebdomadaire s'il vous plait. Merci.\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-8004\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr-200x205.png\" alt=\"\" width=\"124\" height=\"127\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr-200x205.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr-768x785.png 768w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr.png 840w\" sizes=\"(max-width: 124px) 100vw, 124px\" \/><\/a><\/i><\/strong><\/h4>\r\n\r\n\r\n\r\n<h1 class=\"wp-block-heading\"><strong><em>Ton P\u00e8re qui voit dans le secret te le rendra.<\/em><\/strong><\/h1>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\"><strong>(Matthieu 6, 1-6.16-18)<\/strong><\/h3>\r\n\r\n\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<h2><strong>DU DIOC\u00c8SE<\/strong><\/h2>\r\n<h3><strong>Un message de Mgr Michael Brehl, C.Ss.R. pour le Car\u00eame 2026\u00a0<\/strong><\/h3>\r\n<p>Le message de Mgr Brehl pour le Car\u00eame est maintenant disponible sur YouTube\u00a0: <a href=\"https:\/\/www.youtube.com\/watch?v=VXYzIlVzKHY\">Un message de Mgr Michael Brehl, C.Ss.R. pour le Car\u00eame 2026<\/a>.<\/p>\r\n<h3><strong>Rite d&rsquo;\u00e9lection et d\u2019acceptation de ceux et celles qui seront re\u00e7us dans la foi \u00e0 la Cath\u00e9drale St. Columbkille\u00a0<\/strong><\/h3>\r\n<p>Mgr Michael Brehl c\u00e9l\u00e9brera la messe \u00e0 la cath\u00e9drale St. Columbkille <strong>le 1<sup>er<\/sup> dimanche de Car\u00eame, le 22 f\u00e9vrier 2026 \u00e0 10h30. <\/strong>La messe et le rite d&rsquo;\u00e9lection sont destin\u00e9s \u00e0 ceux et celles qui seront baptis\u00e9s lors de la veill\u00e9e pascale, ainsi qu&rsquo;\u00e0 l&rsquo;acceptation des candidats qui seront confirm\u00e9s et re\u00e7us dans la foi. Tous ceux qui se pr\u00e9parent au bapt\u00eame et \u00e0 la r\u00e9ception dans l&rsquo;\u00c9glise dans l&rsquo;ensemble du dioc\u00e8se sont invit\u00e9s \u00e0 participer \u00e0 cette messe avec notre \u00e9v\u00eaque. Si vous avez l&rsquo;intention d&rsquo;y assister, veuillez contacter le diacre Adrien Chaput \u00e0 <a href=\"mailto:dcadrienchaput@pembrokediocese.com\">dcadrienchaput@pembrokediocese.com<\/a>.<\/p>\r\n<h3><strong>Les paroissiens du dioc\u00e8se de Pembroke sont invit\u00e9s \u00e0 r\u00e9server la date<\/strong><\/h3>\r\n<p>Les paroissiens du dioc\u00e8se de Pembroke sont invit\u00e9s \u00e0 r\u00e9server la date<em>\u202f<\/em>pour assister \u00e0 l&rsquo;une des r\u00e9unions d&rsquo;information sur la planification pastorale qui se tiendront dans les cinq doyenn\u00e9s du dioc\u00e8se au cours des premi\u00e8res semaines du Car\u00eame. Mgr Brehl et les membres du comit\u00e9 directeur dioc\u00e9sain pr\u00e9senteront des donn\u00e9es pastorales, statistiques et financi\u00e8res pertinentes afin d&rsquo;aider les paroissiens \u00e0 poursuivre le dialogue et le discernement sur l&rsquo;avenir du dioc\u00e8se. Si vous ne pouvez pas assister \u00e0 la r\u00e9union locale de votre doyenn\u00e9, vous \u00eates les bienvenus \u00e0 l&rsquo;une des autres r\u00e9unions pr\u00e9vues.\u202f\u00a0<\/p>\r\n<p><strong>Dates et lieux des r\u00e9unions du doyenn\u00e9\u00a0<\/strong><\/p>\r\n<ul>\r\n<li><strong>Doyenn\u00e9 de Pembroke\u00a0: jeudi 19 f\u00e9vrier<\/strong> \u00e0 l&rsquo;\u00e9cole secondaire Bishop Smith, Pembroke &#8211; de 18 h 30 \u00e0 20 h 30\u00a0<\/li>\r\n<li><strong>Doyenn\u00e9 de Mattawa\u00a0: samedi 21 f\u00e9vrier<\/strong> \u00e0 la salle Corbeil Park, Corbeil &#8211; fran\u00e7ais de 10 h \u00e0 12 h ; anglais de 13 h \u00e0 15 h\u00a0<\/li>\r\n<li><strong>Doyenn\u00e9 de Pontiac\u00a0: samedi 28 f\u00e9vrier<\/strong> au Club de l&rsquo;\u00c2ge d&rsquo;Or, Fort-Coulonge &#8211; en fran\u00e7ais de 10 h \u00e0 12 h ; en anglais de 13 h \u00e0 15 h\u00a0<\/li>\r\n<li><strong>Doyenn\u00e9 de Barry&rsquo;s Bay\u00a0: dimanche 1er mars<\/strong> \u00e0 l&rsquo;\u00e9cole St. John Bosco, Barry&rsquo;s Bay &#8211; de 14 h \u00e0 16 h\u00a0<\/li>\r\n<\/ul>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p>\r\n\r\n\r\n\r\n<\/p>\r\n<h2><strong>LE SAINT-SI\u00c8GE<\/strong><\/h2>\r\n<h3><strong>Intention de pri\u00e8re du Saint-P\u00e8re pour le mois de f\u00e9vrier 2026\u00a0<\/strong><\/h3>\r\n<p><strong>Pour les enfants atteints de maladies incurables<\/strong> \u2013 Prions pour que les enfants atteints de maladies incurables ainsi que leurs familles re\u00e7oivent les soins m\u00e9dicaux et le soutien n\u00e9cessaires, sans jamais perdre force et esp\u00e9rance.<\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p>\r\n\r\n<\/p>\r\n<h2><strong>DE LA CECC<\/strong><\/h2>\r\n<h3><strong>Cheminer \u00e0 travers le Car\u00eame\u00a0: R\u00e9flexions vid\u00e9o hebdomadaires \u2013 vendredi, f\u00e9vrier 13, 2026\u00a0<\/strong><\/h3>\r\n<p>La Conf\u00e9rence des \u00e9v\u00eaques catholiques du Canada (CECC) pr\u00e9sente\u00a0<a href=\"https:\/\/www.cecc.ca\/evangelisation-catechese-et-education\/ressources-video\/cheminer-ensemble-durant-le-temps-du-careme\/\">Cheminer \u00e0 travers le Car\u00eame<\/a>.\u00a0Cette s\u00e9rie de vid\u00e9os, fruit d\u2019un projet conjoint de l\u2019Office national de liturgie et le\u00a0National Liturgy Office, l\u2019Office for Evangelization and Catechesis, propose des r\u00e9flexions spirituelles hebdomadaires pour le temps du Car\u00eame. <a href=\"https:\/\/www.cecc.ca\/annonce\/2026-cheminer-a-travers-le-careme-reflexions-video-hebdomadaires\/\">(Lire la suite\u2026)<\/a><\/p>\r\n<h3><strong>Nomination d\u2019un \u00e9v\u00eaque coadjuteur pour Saint-Jean-Longueuil \u2013 mercredi le 11 f\u00e9vrier 2026<\/strong><\/h3>\r\n<p><strong>(Ottawa) \u2013<\/strong> Sa Saintet\u00e9 le pape L\u00e9on\u00a0XIV a nomm\u00e9 Mgr Martin Lalibert\u00e9, P.M.\u00c9., actuellement \u00e9v\u00eaque de Trois-Rivi\u00e8res, \u00e0 titre d\u2019\u00e9v\u00eaque coadjuteur du\u00a0<a href=\"https:\/\/www.dsjl.org\/\"><strong>dioc\u00e8se de Saint-Jean-Longueuil<\/strong><\/a>. En tant qu\u2019\u00e9v\u00eaque coadjuteur, il assistera l\u2019\u00e9v\u00eaque actuel de Saint-Jean-Longueuil, Mgr Claude Hamelin. <a href=\"https:\/\/www.cecc.ca\/communique-de-presse\/nomination-dun-eveque-coadjuteur-pour-saint-jean-longueuil\/\">(Lire la suite\u2026)<\/a><\/p>\r\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<h2><strong>CAR\u00caME<\/strong><\/h2>\r\n<h3><strong>CECC \u2013 Cheminer ensemble durant le Car\u00eame \u2013 Mercredi des Cendres 2026<\/strong><\/h3>\r\n<p>La Conf\u00e9rence des \u00e9v\u00eaques catholiques du Canada pr\u00e9sente\u00a0Cheminer ensemble durant le Car\u00eame avec Mgr Juan Carlos Londo\u00f1o, \u00e9v\u00eaque auxiliaire \u00e0 Qu\u00e9bec. Joignez-vous \u00e0 nous pour m\u00e9diter sur les \u00c9critures des dimanches du Car\u00eame 2026.<\/p>\r\n<p><strong>En ce mercredi des Cendres, Mgr Juan Carlos nous propose une r\u00e9flexion sur la signification des cendres qui sont impos\u00e9es sur nos t\u00eates et sur ce que peut signifier, aujourd\u2019hui, de je\u00fbner comme nous le demande le Christ. <\/strong><\/p>\r\n<p>Une initiative conjointe de l\u2019Office national de liturgie, du National Liturgy Office et de l\u2019Office for Evangelization and Catechesis.<\/p>\r\n<p>Vous pouvez visionner la vid\u00e9o YouTube ici\u00a0: <a href=\"https:\/\/www.youtube.com\/watch?v=lVDGzXYJmOk&amp;t=2s\">https:\/\/www.youtube.com\/watch?v=lVDGzXYJmOk&amp;t=2s<\/a>.<\/p>\r\n<p>\r\n\r\n<\/p>\r\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Ton P\u00e8re qui voit dans le secret te le rendra. (Matthieu 6, 1-6.16-18)<\/p>\n","protected":false},"author":10,"featured_media":18023,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[114,84],"tags":[],"class_list":["post-18604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bulletin","category-article"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/18604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/comments?post=18604"}],"version-history":[{"count":1,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/18604\/revisions"}],"predecessor-version":[{"id":18605,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/18604\/revisions\/18605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media\/18023"}],"wp:attachment":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media?parent=18604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/categories?post=18604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/tags?post=18604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}