{"id":7429,"date":"2021-08-06T11:12:59","date_gmt":"2021-08-06T15:12:59","guid":{"rendered":"https:\/\/pembrokediocese.com\/?p=7429"},"modified":"2022-08-19T10:52:56","modified_gmt":"2022-08-19T14:52:56","slug":"vous-allez-recevoir-une-force","status":"publish","type":"post","link":"https:\/\/pembrokediocese.com\/fr\/article\/vous-allez-recevoir-une-force\/","title":{"rendered":"ARTICLE &#8211; Vous allez recevoir une force&#8230;"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">J\u00e9sus a dit \u00e0 ses disciples: \u201cVous allez recevoir une force, celle de l&rsquo;Esprit Saint qui descendra sur vous. Vous serez alors mes t\u00e9moins \u00e0 J\u00e9rusalem, dans toute la Jud\u00e9e et la Samarie, et jusqu&rsquo;aux extr\u00e9mit\u00e9s de la terre\u201d (Actes 1,8). Dieu veut nous remplir de l\u2019Esprit Saint pour que nous proclamions aux autres son amour par toute notre vie (Romains 10,17).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cela conduit aux questions suivantes :\u00a0 Suis-je rempli de l\u2019Esprit Saint ? Et comment \u00eatre rempli de l\u2019Esprit Saint ? Comprenons d\u2019abord qu&rsquo;\u00eatre rempli du de l\u2019Esprit Saint n&rsquo;est pas une exp\u00e9rience unique. Dieu communique son Esprit de diff\u00e9rentes mani\u00e8res. Parmi les plus importantes, on trouve les sacrements et c&rsquo;est pourquoi l&rsquo;\u00c9glise recommande une participation fr\u00e9quente \u00e0 la Sainte Eucharistie et \u00e0 la Confession.\u00a0 Chaque fois que nous communion, que nous accueillons la mis\u00e9ricorde divine ou que nous passons du temps en adoration devant le Saint Sacrement, l\u2019Esprit Saint est r\u00e9pandu dans notre c\u0153ur. Il l\u2019est aussi lors de notre conversation quotidienne avec Dieu et pendant nos m\u00e9ditations des \u00c9critures; de m\u00eame lorsque nous travaillons pour aider ceux et celles qui sont dans le besoin et que nous partageons notre foi avec les autres.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nous recevons aussi sa gr\u00e2ce et nous sommes renouvel\u00e9es dans notre foi quand nous \u00e9coutons les paroles proph\u00e9tiques que Dieu ne cesse de nous donner. Yahweh nous parle proph\u00e9tiquement et personnellement aujourd\u2019hui notamment par les messages de notre M\u00e8re Marie lors de ses apparitions et par ceux du Sacr\u00e9-C\u0153ur de J\u00e9sus.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Au tout d\u00e9but du 20e si\u00e8cle, un grand mouvement de Dieu est n\u00e9 parce que des chr\u00e9tiens ont cherch\u00e9 avec ferveur \u00e0 recevoir la pl\u00e9nitude de l\u2019Esprit Saint. L\u2019Esprit Saint s&rsquo;est r\u00e9pandu dans de nombreuses d\u00e9nominations chr\u00e9tiennes alors que les fid\u00e8les s\u2019imposaient les mains. Une nouvelle vague d&rsquo;\u00e9vang\u00e9lisation et une pratique renouvel\u00e9e des charismes sont n\u00e9es de ce d\u00e9sir intense de recevoir l&rsquo;Esprit Saint. Un instrument important de ce renouveau a \u00e9t\u00e9 les s\u00e9minaires de la vie dans l&rsquo;Esprit qui ont g\u00e9n\u00e9ralement 2 objectifs principaux : Activer la puissance du Saint-Esprit chez les fid\u00e8les et promouvoir une relation intime avec J\u00e9sus-Christ notre Seigneur.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dieu veut encore aujourd\u2019hui que nous soyons remplis et guid\u00e9s par son Esprit d\u2019amour (\u00c9ph\u00e9siens 5,18). Pour cela nous avons \u00e0 Le rechercher activement, \u00e0 passer du temps avec Lui et \u00eatre toujours plus pr\u00e8s de Lui. Que cela soit notre seule ambition. Ainsi nous n\u2019aurons pas \u00e0 nous inqui\u00e9ter des fruits: en pers\u00e9v\u00e9rant, en honorant ses commandements, notre P\u00e8re viendra avec son Fils habiter en nous dans la pl\u00e9nitude de l&rsquo;Esprit selon ce que notre terre saura porter.<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">Par Pierre-Alain Giffard, directeur de la pastorale dioc\u00e9saine<\/span><\/i><\/p>\n<p><strong>Autres articles sur l&rsquo;\u00e9vang\u00e9lisation et le renouveau des paroisses :<\/strong><\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/trois-obstacles-a-letablissement-dune-culture-dinvitation-dans-votre-paroisse\/\">Trois obstacles \u00e0 l\u2019\u00e9tablissement d\u2019une culture d\u2019invitation dans votre paroisse<\/a><\/strong><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisateur-relationnel\/\"><strong class=\"post-title\">L\u2019\u00e9vang\u00e9lisateur relationnel<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/faire-eglise-a-la-maison\/\"><strong class=\"post-title\">Faire \u00c9glise \u00e0 la maison<\/strong><\/a><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-fille-aveugle\/\">La fille aveugle<\/a><\/strong><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/un-groupe-de-gernouilles\/\"><strong>Un groupe de grenouilles<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/lelephant-attache\/\"><strong>L\u2019\u00e9l\u00e9phant attach\u00e9<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/paroisse-de-la-nativite\/\"><strong>Le renouveau de la paroisse de la Nativit\u00e9 \u00e0 Baltimore<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-foi-grandit-copy\/\"><strong>La foi grandit lorsqu\u2019on la partage<\/strong><\/a><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/dans-les-souliers-des-sans-eglises\/\">Dans les souliers des \u201csans-\u00e9glises\u201d<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-cellules-paroissiales-devangelisation-2-copy\/\">Les cellules paroissiales d\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/caracteristiques-uniques-des-paroisses-missionnaires\/\">Six caract\u00e9ristiques uniques des paroisses missionnaires<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/devenir-une-paroisse-missionnaire\/\">Quelques \u00e9tapes pour devenir une paroisse missionnaire<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quest-ce-que-levangelisation\/\">Qu\u2019est-ce que l\u2019\u00e9vang\u00e9lisation et dans quel esprit la pratiquer ?<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/auto-evaluation\/\">Questions de discussion et d\u2019auto-\u00e9valuation pour l\u2019\u00e9vang\u00e9lisation en paroisse<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-priere-de-jesus\/\">La pri\u00e8re de J\u00e9sus: une m\u00e9thode pour prier en tout temps<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/pratiquer-leur-foi\/\">Qu\u2019est-ce qui peut aider les enfants \u00e9lev\u00e9s dans la religion catholique \u00e0 continuer \u00e0 pratiquer leur foi \u00e0 l\u2019\u00e2ge adulte ?<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-tactiques-de-satan-1ere-partie\/\">Les tactiques de Satan<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/apprendre-a-etre-missionnaire\/\">Apprendre \u00e0 \u00eatre missionnaire<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quand-nous-crions-vers-dieu\/\">Quand nous crions vers Dieu, il r\u00e9pond<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent-copy\/\">Pr\u00e9sence et Proclamation<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent\/\">Sauver ceux qui se perdent<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-paroisse-saint-nazaire-lhistoire-dune-transformation-missionnaire\/\">La paroisse Saint-Nazaire: L\u2019histoire d\u2019une transformation missionnaire<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/evangelisation-et-petits-groupes-de-partage\/\">\u00c9vang\u00e9lisation et petits groupes de partage<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/evangeliser-en-invitant-des-personnes-a-recevoir-jesus-comme-seigneur-et-sauveur\/\">\u00c9vang\u00e9liser en invitant des personnes \u00e0 recevoir J\u00e9sus comme Seigneur et Sauveur<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/vous-allez-recevoir-une-force\/\">Vous allez recevoir une force\u2026<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/avez-vous-entendu-parler-de-la-loi-des-trois-ecoutes-et-des-sept-contacts\/\">Avez-vous entendu parler de la loi des trois \u00e9coutes et des sept contacts ?<\/a><\/strong><\/li>\n<li class=\"post-title\"><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/trois-habitudes-dune-vie-chretienne-fructueuse\/\">Trois habitudes d\u2019une vie chr\u00e9tienne fructueuse<\/a><\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<div class=\"info\">\n<hr \/>\n<\/div>\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\">\n<p><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1993 size-full\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying-100x100.png 100w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\">LECTURES RECOMMANDEES<\/a><\/h4>\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\" target=\"_self\" >En savoir plus <\/a>\n<\/div>\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\">\n<p><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/prayer-group\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3620\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-300x300.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-300x300.png 300w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-100x100.png 100w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-400x400.png 400w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-210x210.png 210w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle.png 684w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/prayer-group\/\">PRI\u00c8RES ET GROUPES DE PRIERE POUR LE PROJET DIOC\u00c9SAIN DE NOUVELLE \u00c9VANG\u00c9LISATION<\/a><\/h4>\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"\/fr\/nouvelle-evangelisation\/prayer-group\/\" target=\"_self\" >En savoir plus<\/a>\n<\/div>\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\">\n<p><a href=\"https:\/\/pembrokediocese.com\/donate\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7117 size-medium aligncenter\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-200x200.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-200x200.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-768x768.png 768w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-100x100.png 100w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-400x400.png 400w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-210x210.png 210w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept.png 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/donate\/\">DONNER POUR LE PROJET DIOC\u00c9SAIN DE NOUVELLE \u00c9VANG\u00c9LISATION<\/a><\/h4>\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"https:\/\/pembrokediocese.com\/donate\/\" target=\"_self\" >En savoir plus<\/a>\n<\/div>\n<div id=\"gtx-trans\" style=\"position: absolute; left: -17px; top: 0.609089px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e9sus a dit \u00e0 ses disciples: \u201cVous allez recevoir une force, celle de l&rsquo;Esprit Saint qui descendra sur vous. Vous serez alors mes t\u00e9moins \u00e0 J\u00e9rusalem, dans toute la Jud\u00e9e et la Samarie, et jusqu&rsquo;aux extr\u00e9mit\u00e9s de la terre\u201d (Actes 1,8). Dieu veut nous remplir de l\u2019Esprit Saint pour que nous proclamions aux autres son amour par toute notre vie (Romains 10,17). Cela conduit aux questions suivantes :\u00a0 Suis-je rempli de l\u2019Esprit Saint ? Et comment \u00eatre rempli de l\u2019Esprit Saint ? Comprenons d\u2019abord qu&rsquo;\u00eatre rempli du de l\u2019Esprit Saint n&rsquo;est pas une exp\u00e9rience unique. Dieu communique son Esprit de diff\u00e9rentes mani\u00e8res. Parmi les plus importantes, on trouve les sacrements et c&rsquo;est pourquoi l&rsquo;\u00c9glise recommande une participation fr\u00e9quente \u00e0 la Sainte Eucharistie et \u00e0 la Confession.\u00a0 Chaque fois que nous communion, que nous accueillons la mis\u00e9ricorde divine ou que nous passons du temps en adoration devant le Saint Sacrement, l\u2019Esprit Saint est r\u00e9pandu dans notre c\u0153ur. Il l\u2019est aussi lors de notre conversation quotidienne avec Dieu et pendant nos m\u00e9ditations des \u00c9critures; de m\u00eame lorsque nous travaillons pour aider ceux et celles qui sont dans le besoin et que nous partageons notre foi avec les autres. Nous recevons aussi sa gr\u00e2ce et nous sommes renouvel\u00e9es dans notre foi quand nous \u00e9coutons les paroles proph\u00e9tiques que Dieu ne cesse de nous donner. Yahweh nous parle proph\u00e9tiquement et personnellement aujourd\u2019hui notamment par les messages de notre M\u00e8re Marie lors de ses apparitions et par ceux du Sacr\u00e9-C\u0153ur de J\u00e9sus. Au tout d\u00e9but du 20e si\u00e8cle, un grand mouvement de Dieu est n\u00e9 parce que des chr\u00e9tiens ont cherch\u00e9 avec ferveur \u00e0 recevoir la pl\u00e9nitude de l\u2019Esprit Saint. L\u2019Esprit Saint s&rsquo;est r\u00e9pandu dans de nombreuses d\u00e9nominations chr\u00e9tiennes alors que les fid\u00e8les s\u2019imposaient les mains. Une nouvelle vague d&rsquo;\u00e9vang\u00e9lisation et une pratique renouvel\u00e9e des charismes sont n\u00e9es de ce d\u00e9sir intense de recevoir l&rsquo;Esprit Saint. Un instrument important de ce renouveau a \u00e9t\u00e9 les s\u00e9minaires de la vie dans l&rsquo;Esprit qui ont g\u00e9n\u00e9ralement 2 objectifs principaux : Activer la puissance du Saint-Esprit chez les fid\u00e8les et promouvoir une relation intime avec J\u00e9sus-Christ notre Seigneur. Dieu veut encore aujourd\u2019hui que nous soyons remplis et guid\u00e9s par son Esprit d\u2019amour (\u00c9ph\u00e9siens 5,18). Pour cela nous avons \u00e0 Le rechercher activement, \u00e0 passer du temps avec Lui et \u00eatre toujours plus pr\u00e8s de Lui. Que cela soit notre seule ambition. Ainsi nous n\u2019aurons pas \u00e0 nous inqui\u00e9ter des fruits: en pers\u00e9v\u00e9rant, en honorant ses commandements, notre P\u00e8re viendra avec son Fils habiter en nous dans la pl\u00e9nitude de l&rsquo;Esprit selon ce que notre terre saura porter. Par Pierre-Alain Giffard, directeur de la pastorale dioc\u00e9saine Autres articles sur l&rsquo;\u00e9vang\u00e9lisation et le renouveau des paroisses : Trois obstacles \u00e0 l\u2019\u00e9tablissement d\u2019une culture d\u2019invitation dans votre paroisse L\u2019\u00e9vang\u00e9lisateur relationnel Faire \u00c9glise \u00e0 la maison La fille aveugle Un groupe de grenouilles L\u2019\u00e9l\u00e9phant attach\u00e9 Le renouveau de la paroisse de la Nativit\u00e9 \u00e0 Baltimore La foi grandit lorsqu\u2019on la partage Dans les souliers des \u201csans-\u00e9glises\u201d Les cellules paroissiales d\u2019\u00e9vang\u00e9lisation Six caract\u00e9ristiques uniques des paroisses missionnaires Quelques \u00e9tapes pour devenir une paroisse missionnaire Qu\u2019est-ce que l\u2019\u00e9vang\u00e9lisation et dans quel esprit la pratiquer [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[84,156],"tags":[],"class_list":["post-7429","post","type-post","status-publish","format-standard","hentry","category-article","category-textes-a-lire"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/7429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/comments?post=7429"}],"version-history":[{"count":2,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/7429\/revisions"}],"predecessor-version":[{"id":10376,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/7429\/revisions\/10376"}],"wp:attachment":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media?parent=7429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/categories?post=7429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/tags?post=7429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}