{"id":7554,"date":"2021-08-24T11:31:24","date_gmt":"2021-08-24T15:31:24","guid":{"rendered":"https:\/\/pembrokediocese.com\/bulletin\/17-aout-2021-copy\/"},"modified":"2021-08-24T11:38:20","modified_gmt":"2021-08-24T15:38:20","slug":"24-aout-2021","status":"publish","type":"post","link":"https:\/\/pembrokediocese.com\/fr\/bulletin\/24-aout-2021\/","title":{"rendered":"BULLETIN HEBDOMADAIRE  &#8211; le 24 ao\u00fbt 2021  (St Barth\u00e9lemy, ap\u00f4tre)"},"content":{"rendered":"<h3><strong><em>Voici vraiment un Isra\u00e9lite: il n&rsquo;y a pas de ruse en lui.<\/em><\/strong><\/h3>\n<p>(Jean 1, 45-51)<\/p>\n<hr \/>\n<h2><strong>DU DIOC\u00c8SE<\/strong><\/h2>\n<h3><strong>Heures du bureau durant l\u2019<\/strong><strong>\u00e9t\u00e9<\/strong><\/h3>\n<p>Les bureaux dioc\u00e9sains seront ouverts de 9h \u00e0 16h du lundi au jeudi, et de 9h \u00e0 midi le vendredi durant la p\u00e9riode s\u2019\u00e9chelonnant du 5 juillet \u00a0au 3 septembre inclusivement.<\/p>\n<hr \/>\n<h2><strong>L&rsquo;\u00c9QUIPE D&rsquo;\u00c9VANG\u00c9LISATION<\/strong><\/h2>\n<h3><strong>La paroisse Saint-Nazaire\u00a0: L\u2019histoire d\u2019une transformation missionnaire<\/strong><\/h3>\n<p><em>Par Pierre-Alain Giffard, directeur de la pastorale dioc\u00e9saine<\/em><\/p>\n<p>L\u2019\u00e9glise Saint-Nazaire est un autre exemple de transformation missionnaire paroissiale. Situ\u00e9e \u00e0 Sanary-sur-Mer en France, elle changea de cur\u00e9 en 1994. \u00c0 son arriv\u00e9e, il constata que les fid\u00e8les \u00e9taient impliqu\u00e9s dans les activit\u00e9s de la paroisse, mais que la plupart de la communaut\u00e9 \u00e9tait compos\u00e9e de personnes \u00e2g\u00e9es. <a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-paroisse-saint-nazaire-lhistoire-dune-transformation-missionnaire\/\">(Lire la suite\u2026)<\/a><\/p>\n<hr \/>\n<h2><strong>DE LA CECC<\/strong><\/h2>\n<h3><strong>\u00c9v\u00eaques catholiques du Canada \u00e0 propos de la Corporation des organismes catholiques signataires de l\u2019entente sur les pensionnats indiens<\/strong><\/h3>\n<p>Vous pouvez lire la d\u00e9claration du Bureau de direction de la CECC \u00e0 propos de la Corporation des organismes catholiques signataires de l\u2019entente sur les pensionnats indiens <a href=\"https:\/\/pembrokediocese.com\/fr\/article\/declaration-du-bureau-de-direction-de-la-conference-des-eveques-catholiques-du-canada-a-propos-de-la-corporation-des-organismes-catholiques-signataires-de-lentente-sur-les-pensionnats-indiens\/\">ici.<\/a><\/p>\n<hr \/>\n<h2><strong>L&rsquo;\u00c9DUCATION DE LA FOI<\/strong><\/h2>\n<h3><strong>Sommes-nous pr\u00eats \u00e0 commencer ? Message du diacre Adrien\u00a0<\/strong><\/h3>\n<p>Je sais que cette ann\u00e9e a \u00e9t\u00e9 difficile avec la pand\u00e9mie de COVID-19 et les restrictions de confinement. Je sais que cela a rendu la t\u00e2che difficile pour la pr\u00e9paration sacramentelle. Je sais que j\u2019ai aid\u00e9 certains d\u2019entre vous \u00e0 se connecter avec la pr\u00e9paration sacramentelle en ligne et la pr\u00e9paration \u00e0 la maison avec les parents. Alors que nous regardons vers l\u2019avenir, je veux que vous sachiez que je suis ici pour vous aider dans les pr\u00e9paratifs sacramentels. Veuillez communiquer avec moi au 613 732-7933, poste 206, ou \u00e0 <a href=\"mailto:dcadrienchaput@pembrokediocese.com\">dcadrienchaput@pembrokediocese.com<\/a>.<\/p>\n<hr \/>\n<h2><strong>\u00c9V\u00c9NEMENTS PAROISSIAUX<\/strong><\/h2>\n<h3><strong>Sainte Messe<\/strong><\/h3>\n<p>La Sainte Messe selon le Missel romain de 1962 est offerte \u00e0 la Cath\u00e9drale St Columbkille le premier samedi de chaque mois \u00e0 9 h. Il s&rsquo;agit essentiellement de la m\u00eame forme de la liturgie qui a nourri la foi de nombreux catholiques pendant des si\u00e8cles. \u00a0Des traductions en anglais de l&rsquo;ensemble de la messe sont fournies. <strong>Prochaine messe \u2013 4 septembre 2021.<\/strong><\/p>\n<hr \/>\n<h2><strong>AUTRES \u00c9V\u00c9NEMENTS CATHOLIQUES<\/strong><\/h2>\n<h3><strong>52e Congr\u00e8s eucharistique international \u2013 5-12 sept. 2021<\/strong><\/h3>\n<p>Vous \u00eates invit\u00e9s \u00e0 participer \u00e0 cet \u00e9v\u00e9nement tr\u00e8s sp\u00e9cial de l&rsquo;\u00c9glise catholique \u00e0 Budapest, en Hongrie. Le Congr\u00e8s comprendra un programme complet d&rsquo;\u00e9v\u00e9nements, dont une messe quotidienne, des t\u00e9moignages, des cat\u00e9ch\u00e8ses par diff\u00e9rents cardinaux, des ateliers, une soir\u00e9e pour les jeunes, le Festival des familles, une procession eucharistique aux chandelles et une messe de cl\u00f4ture avec le pape Fran\u00e7ois. Pour obtenir les d\u00e9tails du programme complet et la liste de tous les intervenants, rendez-vous sur <a href=\"http:\/\/www.iec2020.hu\/en\/program\">www.iec2020.hu\/en\/program<\/a> .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voici vraiment un Isra\u00e9lite: il n&rsquo;y a pas de ruse en lui. (Jean 1, 45-51) DU DIOC\u00c8SE Heures du bureau durant l\u2019\u00e9t\u00e9 Les bureaux dioc\u00e9sains seront ouverts de 9h \u00e0 16h du lundi au jeudi, et de 9h \u00e0 midi le vendredi durant la p\u00e9riode s\u2019\u00e9chelonnant du 5 juillet \u00a0au 3 septembre inclusivement. L&rsquo;\u00c9QUIPE D&rsquo;\u00c9VANG\u00c9LISATION La paroisse Saint-Nazaire\u00a0: L\u2019histoire d\u2019une transformation missionnaire Par Pierre-Alain Giffard, directeur de la pastorale dioc\u00e9saine L\u2019\u00e9glise Saint-Nazaire est un autre exemple de transformation missionnaire paroissiale. Situ\u00e9e \u00e0 Sanary-sur-Mer en France, elle changea de cur\u00e9 en 1994. \u00c0 son arriv\u00e9e, il constata que les fid\u00e8les \u00e9taient impliqu\u00e9s dans les activit\u00e9s de la paroisse, mais que la plupart de la communaut\u00e9 \u00e9tait compos\u00e9e de personnes \u00e2g\u00e9es. (Lire la suite\u2026) DE LA CECC \u00c9v\u00eaques catholiques du Canada \u00e0 propos de la Corporation des organismes catholiques signataires de l\u2019entente sur les pensionnats indiens Vous pouvez lire la d\u00e9claration du Bureau de direction de la CECC \u00e0 propos de la Corporation des organismes catholiques signataires de l\u2019entente sur les pensionnats indiens ici. L&rsquo;\u00c9DUCATION DE LA FOI Sommes-nous pr\u00eats \u00e0 commencer ? Message du diacre Adrien\u00a0 Je sais que cette ann\u00e9e a \u00e9t\u00e9 difficile avec la pand\u00e9mie de COVID-19 et les restrictions de confinement. Je sais que cela a rendu la t\u00e2che difficile pour la pr\u00e9paration sacramentelle. Je sais que j\u2019ai aid\u00e9 certains d\u2019entre vous \u00e0 se connecter avec la pr\u00e9paration sacramentelle en ligne et la pr\u00e9paration \u00e0 la maison avec les parents. Alors que nous regardons vers l\u2019avenir, je veux que vous sachiez que je suis ici pour vous aider dans les pr\u00e9paratifs sacramentels. Veuillez communiquer avec moi au 613 732-7933, poste 206, ou \u00e0 dcadrienchaput@pembrokediocese.com. \u00c9V\u00c9NEMENTS PAROISSIAUX Sainte Messe La Sainte Messe selon le Missel romain de 1962 est offerte \u00e0 la Cath\u00e9drale St Columbkille le premier samedi de chaque mois \u00e0 9 h. Il s&rsquo;agit essentiellement de la m\u00eame forme de la liturgie qui a nourri la foi de nombreux catholiques pendant des si\u00e8cles. \u00a0Des traductions en anglais de l&rsquo;ensemble de la messe sont fournies. Prochaine messe \u2013 4 septembre 2021. AUTRES \u00c9V\u00c9NEMENTS CATHOLIQUES 52e Congr\u00e8s eucharistique international \u2013 5-12 sept. 2021 Vous \u00eates invit\u00e9s \u00e0 participer \u00e0 cet \u00e9v\u00e9nement tr\u00e8s sp\u00e9cial de l&rsquo;\u00c9glise catholique \u00e0 Budapest, en Hongrie. Le Congr\u00e8s comprendra un programme complet d&rsquo;\u00e9v\u00e9nements, dont une messe quotidienne, des t\u00e9moignages, des cat\u00e9ch\u00e8ses par diff\u00e9rents cardinaux, des ateliers, une soir\u00e9e pour les jeunes, le Festival des familles, une procession eucharistique aux chandelles et une messe de cl\u00f4ture avec le pape Fran\u00e7ois. Pour obtenir les d\u00e9tails du programme complet et la liste de tous les intervenants, rendez-vous sur www.iec2020.hu\/en\/program .<\/p>\n","protected":false},"author":1,"featured_media":3815,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[114],"tags":[],"class_list":["post-7554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bulletin"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/7554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/comments?post=7554"}],"version-history":[{"count":0,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/7554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media\/3815"}],"wp:attachment":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media?parent=7554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/categories?post=7554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/tags?post=7554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}