{"id":7674,"date":"2021-09-21T10:25:38","date_gmt":"2021-09-21T14:25:38","guid":{"rendered":"https:\/\/pembrokediocese.com\/bulletin\/14-septembre-2021-copy\/"},"modified":"2021-09-21T10:25:38","modified_gmt":"2021-09-21T14:25:38","slug":"14-septembre-2021-copy","status":"publish","type":"post","link":"https:\/\/pembrokediocese.com\/fr\/bulletin\/14-septembre-2021-copy\/","title":{"rendered":"BULLETIN HEBDOMADAIRE  &#8211; le 14 septembre 2021  (La Croix Glorieuse)  Copy"},"content":{"rendered":"<h3><strong><em>Il faut que le Fils de l&rsquo;homme soit \u00e9lev\u00e9.<\/em><\/strong><\/h3>\n<p>(Jean 3, 13-17)<\/p>\n<hr \/>\n<h2><strong>DU DIOC\u00c8SE<\/strong><\/h2>\n<h3><strong>Heures de bureau de la chancellerie<\/strong><\/h3>\n<p>Nous vous rappelons que les bureaux dioc\u00e9sains sont d\u00e9sormais ouverts de 8h30 \u00e0 16h30 du lundi au vendredi.<\/p>\n<h3><strong>Journ\u00e9e d&rsquo;\u00e9tude pour les pr\u00eatres<\/strong><\/h3>\n<p>Veuillez garder nos pr\u00eatres dans vos pri\u00e8res alors qu&rsquo;ils participent \u00e0 leur journ\u00e9e d&rsquo;\u00e9tude le mardi 14 septembre. Journ\u00e9e d&rsquo;\u00e9tude pour les pr\u00eatres : Veuillez garder nos pr\u00eatres dans vos pri\u00e8res alors qu&rsquo;ils participent \u00e0 leur journ\u00e9e d&rsquo;\u00e9tude le mardi 14 septembre.<\/p>\n<h3><strong>Pri\u00e8res<\/strong><\/h3>\n<p>Veuillez prier pour le repos de l&rsquo;\u00e2me de S\u0153ur Marjorie Veronica Casey (S\u0153ur Catherine Marie), une S\u0153ur Grise de l&rsquo;Immacul\u00e9e Conception, d\u00e9c\u00e9d\u00e9e \u00e0 Pembroke le 1<sup>er<\/sup> septembre dans la 66<sup>e<\/sup> ann\u00e9e de sa vie religieuse.<\/p>\n<h3><strong>Pri\u00e8res<\/strong><\/h3>\n<p>Veuillez prier pour le repos de l&rsquo;\u00e2me de S\u0153ur Margaret Foran (S\u0153ur Mary Judith), une S\u0153ur Grise de l&rsquo;Immacul\u00e9e Conception, qui est d\u00e9c\u00e9d\u00e9e le 6 septembre dans la 70<sup>e<\/sup> ann\u00e9e de sa vie religieuse.<\/p>\n<h3><strong>Pri\u00e8res<\/strong><\/h3>\n<p>Veuillez prier pour le repos de l&rsquo;\u00e2me de Charles (Chuck) Kirkwood Sharp II (1948 &#8211; 2021), membre du personnel de Madonna House, qui est d\u00e9c\u00e9d\u00e9 paisiblement \u00e0 St. Mary&rsquo;s, Madonna House, le 10 septembre.<\/p>\n<hr \/>\n<h2><strong>L&rsquo;\u00c9QUIPE D&rsquo;\u00c9VANG\u00c9LISATION<\/strong><\/h2>\n<h3><strong>Pr\u00e9sence et proclamation<\/strong><\/h3>\n<p><em>Par Pierre-Alain Giffard, directeur de la pastorale dioc\u00e9saine<\/em><\/p>\n<p>Les positions th\u00e9ologiques sur l\u2019\u00e9vang\u00e9lisation ont souvent gravit\u00e9 autour de deux p\u00f4les : \u00ab\u00a0pr\u00e9sence\u00a0\u00bb et \u00ab\u00a0proclamation\u00a0\u00bb. Le terme \u00ab\u00a0pr\u00e9sence chr\u00e9tienne\u00a0\u00bb est n\u00e9 dans le catholicisme fran\u00e7ais. Ainsi, le bienheureux Charles de Foucauld d\u00e9crivait sa vocation comme \u00e9tant une pr\u00e9sence au milieu des gens, une pr\u00e9sence fraternelle, donn\u00e9e \u00e0 la pri\u00e8re, accueillante \u00e0 toute personne, et se mettant au service des gens. <a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent-copy\/\">(Lire la suite\u2026)<\/a><\/p>\n<hr \/>\n<h2><strong>DE LA CECC<\/strong><\/h2>\n<h3><strong>Nomination d\u2019un nouvel \u00e9v\u00eaque pour l\u2019\u00e9parchie catholique chald\u00e9enne de Mar Addai au Canada \u2013 lundi le 13 septembre 2021<\/strong><\/h3>\n<p>Le samedi 11 septembre 2021, Sa Saintet\u00e9 le pape Fran\u00e7ois a accept\u00e9 la renonciation de Mgr Bawai Soro de la gouvernance pastorale de l\u2019\u00e9parchie catholique chald\u00e9enne de Mar Addai au Canada, o\u00f9 il a \u00e9t\u00e9 \u00e9v\u00eaque \u00e9parchial au cours des derni\u00e8res quatre ann\u00e9es. Au m\u00eame moment, le Saint-P\u00e8re a \u00e9galement nomm\u00e9 Mgr Robert Saeed Jarjis comme nouvel \u00e9v\u00eaque \u00e9parchial de la m\u00eame circonscription eccl\u00e9siastique. <a href=\"https:\/\/www.cccb.ca\/fr\/media-release\/nomination-dun-nouvel-eveque-pour-leparchie-catholique-chaldeenne-de-mar-addai-au-canada\/\">(Lire la suite\u2026)<\/a><\/p>\n<h3><strong>Publication du document pr\u00e9paratoire pour le synode sur la synodalit\u00e9 2023 \u2013 vendredi, septembre 10, 2021<\/strong><\/h3>\n<p>Le Secr\u00e9tariat g\u00e9n\u00e9ral du Synode des \u00e9v\u00eaques a publi\u00e9 le document pr\u00e9paratoire pour la XVI Assembl\u00e9e g\u00e9n\u00e9rale ordinaire du Synode des \u00e9v\u00eaques qui aura lieu pendant le mois d\u2019octobre 2023 sur le th\u00e8me <strong>\u00ab Pour une \u00c9glise synodale : communion, participation et mission \u00bb.<\/strong> Le Vademecum (ou manuel) a \u00e9galement \u00e9t\u00e9 publi\u00e9 pour guider l\u2019\u00e9coute et le discernement lors de la phase de consultation dans les \u00e9glises locales.<\/p>\n<p><strong><a href=\"https:\/\/www.cccb.ca\/wp-content\/uploads\/2021\/09\/DOCUMENTO-PREPARATORIO-FRANCESE.pdf\">Synode des \u00e9v\u00eaques 2023 \u2013 Document<\/a><a href=\"https:\/\/www.cccb.ca\/wp-content\/uploads\/2021\/09\/DOCUMENTO-PREPARATORIO-FRANCESE.pdf\"> pr\u00e9paratoire<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.cccb.ca\/wp-content\/uploads\/2021\/09\/EN-Vademecum-with-Appendices-A-B-CD.pdf\">Synode des \u00e9v\u00eaques 2023 \u2013 Vademecum pour<\/a><a href=\"https:\/\/www.cccb.ca\/wp-content\/uploads\/2021\/09\/EN-Vademecum-with-Appendices-A-B-CD.pdf\"> le synode sur la synodalit\u00e9<\/a><\/strong> <em>(disponible en anglais seulement)<\/em><\/p>\n<hr \/>\n<h2><strong>VATICAN NEWS<\/strong><\/h2>\n<h3><strong>Fran\u00e7ois invite les pr\u00eatres \u00e0 plus d\u2019\u00e9coute<\/strong><\/h3>\n<p>Depuis la fen\u00eatre du palais apostolique, le pape Fran\u00e7ois a offert une m\u00e9ditation sur l\u2019\u00e9vangile du jour \u00abIl fait entendre les sourds et parler les muets \u00bb (Mc 7, 31-37). Il a invit\u00e9 chacun, notamment les pr\u00eatres, \u00e0 se questionner sur sa mani\u00e8re d&rsquo;\u00e9couter les autres. <a href=\"https:\/\/www.vaticannews.va\/fr\/pape\/news\/2021-09\/angelus-5-septembre-2021-pape-francois-ecoute-effata.html\">https:\/\/www.vaticannews.va\/fr\/pape\/news\/2021-09\/angelus-5-septembre-2021-pape-francois-ecoute-effata.html<\/a>.<\/p>\n<hr \/>\n<h2><strong>L&rsquo;\u00c9DUCATION DE LA FOI<\/strong><\/h2>\n<h3><strong>Sommes-nous pr\u00eats \u00e0 commencer ? Message du diacre Adrien\u00a0<\/strong><\/h3>\n<p>Je sais que cette ann\u00e9e a \u00e9t\u00e9 difficile avec la pand\u00e9mie de COVID-19 et les restrictions de confinement. Je sais que cela a rendu la t\u00e2che difficile pour la pr\u00e9paration sacramentelle. Je sais que j\u2019ai aid\u00e9 certains d\u2019entre vous \u00e0 se connecter avec la pr\u00e9paration sacramentelle en ligne et la pr\u00e9paration \u00e0 la maison avec les parents. Alors que nous regardons vers l\u2019avenir, je veux que vous sachiez que je suis ici pour vous aider dans les pr\u00e9paratifs sacramentels. Veuillez communiquer avec moi au 613 732-7933, poste 206, ou \u00e0 <a href=\"mailto:dcadrienchaput@pembrokediocese.com\">dcadrienchaput@pembrokediocese.com<\/a>.<\/p>\n<hr \/>\n<h2><strong>\u00c9V\u00c9NEMENTS PAROISSIAUX<\/strong><\/h2>\n<h3><strong>Sainte Messe<\/strong><\/h3>\n<p>La Sainte Messe selon le Missel romain de 1962 est offerte \u00e0 la Cath\u00e9drale St Columbkille le premier samedi de chaque mois \u00e0 9 h. Il s&rsquo;agit essentiellement de la m\u00eame forme de la liturgie qui a nourri la foi de nombreux catholiques pendant des si\u00e8cles. \u00a0Des traductions en anglais de l&rsquo;ensemble de la messe sont fournies. <strong>Prochaine messe \u2013 2 octobre 2021.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il faut que le Fils de l&rsquo;homme soit \u00e9lev\u00e9. (Jean 3, 13-17) DU DIOC\u00c8SE Heures de bureau de la chancellerie Nous vous rappelons que les bureaux dioc\u00e9sains sont d\u00e9sormais ouverts de 8h30 \u00e0 16h30 du lundi au vendredi. Journ\u00e9e d&rsquo;\u00e9tude pour les pr\u00eatres Veuillez garder nos pr\u00eatres dans vos pri\u00e8res alors qu&rsquo;ils participent \u00e0 leur journ\u00e9e d&rsquo;\u00e9tude le mardi 14 septembre. Journ\u00e9e d&rsquo;\u00e9tude pour les pr\u00eatres : Veuillez garder nos pr\u00eatres dans vos pri\u00e8res alors qu&rsquo;ils participent \u00e0 leur journ\u00e9e d&rsquo;\u00e9tude le mardi 14 septembre. Pri\u00e8res Veuillez prier pour le repos de l&rsquo;\u00e2me de S\u0153ur Marjorie Veronica Casey (S\u0153ur Catherine Marie), une S\u0153ur Grise de l&rsquo;Immacul\u00e9e Conception, d\u00e9c\u00e9d\u00e9e \u00e0 Pembroke le 1er septembre dans la 66e ann\u00e9e de sa vie religieuse. Pri\u00e8res Veuillez prier pour le repos de l&rsquo;\u00e2me de S\u0153ur Margaret Foran (S\u0153ur Mary Judith), une S\u0153ur Grise de l&rsquo;Immacul\u00e9e Conception, qui est d\u00e9c\u00e9d\u00e9e le 6 septembre dans la 70e ann\u00e9e de sa vie religieuse. Pri\u00e8res Veuillez prier pour le repos de l&rsquo;\u00e2me de Charles (Chuck) Kirkwood Sharp II (1948 &#8211; 2021), membre du personnel de Madonna House, qui est d\u00e9c\u00e9d\u00e9 paisiblement \u00e0 St. Mary&rsquo;s, Madonna House, le 10 septembre. L&rsquo;\u00c9QUIPE D&rsquo;\u00c9VANG\u00c9LISATION Pr\u00e9sence et proclamation Par Pierre-Alain Giffard, directeur de la pastorale dioc\u00e9saine Les positions th\u00e9ologiques sur l\u2019\u00e9vang\u00e9lisation ont souvent gravit\u00e9 autour de deux p\u00f4les : \u00ab\u00a0pr\u00e9sence\u00a0\u00bb et \u00ab\u00a0proclamation\u00a0\u00bb. Le terme \u00ab\u00a0pr\u00e9sence chr\u00e9tienne\u00a0\u00bb est n\u00e9 dans le catholicisme fran\u00e7ais. Ainsi, le bienheureux Charles de Foucauld d\u00e9crivait sa vocation comme \u00e9tant une pr\u00e9sence au milieu des gens, une pr\u00e9sence fraternelle, donn\u00e9e \u00e0 la pri\u00e8re, accueillante \u00e0 toute personne, et se mettant au service des gens. (Lire la suite\u2026) DE LA CECC Nomination d\u2019un nouvel \u00e9v\u00eaque pour l\u2019\u00e9parchie catholique chald\u00e9enne de Mar Addai au Canada \u2013 lundi le 13 septembre 2021 Le samedi 11 septembre 2021, Sa Saintet\u00e9 le pape Fran\u00e7ois a accept\u00e9 la renonciation de Mgr Bawai Soro de la gouvernance pastorale de l\u2019\u00e9parchie catholique chald\u00e9enne de Mar Addai au Canada, o\u00f9 il a \u00e9t\u00e9 \u00e9v\u00eaque \u00e9parchial au cours des derni\u00e8res quatre ann\u00e9es. Au m\u00eame moment, le Saint-P\u00e8re a \u00e9galement nomm\u00e9 Mgr Robert Saeed Jarjis comme nouvel \u00e9v\u00eaque \u00e9parchial de la m\u00eame circonscription eccl\u00e9siastique. (Lire la suite\u2026) Publication du document pr\u00e9paratoire pour le synode sur la synodalit\u00e9 2023 \u2013 vendredi, septembre 10, 2021 Le Secr\u00e9tariat g\u00e9n\u00e9ral du Synode des \u00e9v\u00eaques a publi\u00e9 le document pr\u00e9paratoire pour la XVI Assembl\u00e9e g\u00e9n\u00e9rale ordinaire du Synode des \u00e9v\u00eaques qui aura lieu pendant le mois d\u2019octobre 2023 sur le th\u00e8me \u00ab Pour une \u00c9glise synodale : communion, participation et mission \u00bb. Le Vademecum (ou manuel) a \u00e9galement \u00e9t\u00e9 publi\u00e9 pour guider l\u2019\u00e9coute et le discernement lors de la phase de consultation dans les \u00e9glises locales. Synode des \u00e9v\u00eaques 2023 \u2013 Document pr\u00e9paratoire Synode des \u00e9v\u00eaques 2023 \u2013 Vademecum pour le synode sur la synodalit\u00e9 (disponible en anglais seulement) VATICAN NEWS Fran\u00e7ois invite les pr\u00eatres \u00e0 plus d\u2019\u00e9coute Depuis la fen\u00eatre du palais apostolique, le pape Fran\u00e7ois a offert une m\u00e9ditation sur l\u2019\u00e9vangile du jour \u00abIl fait entendre les sourds et parler les muets \u00bb (Mc 7, 31-37). Il a invit\u00e9 chacun, notamment les pr\u00eatres, \u00e0 se questionner sur sa mani\u00e8re d&rsquo;\u00e9couter les autres. https:\/\/www.vaticannews.va\/fr\/pape\/news\/2021-09\/angelus-5-septembre-2021-pape-francois-ecoute-effata.html. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3815,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[114],"tags":[],"class_list":["post-7674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bulletin"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/7674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/comments?post=7674"}],"version-history":[{"count":0,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/7674\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media\/3815"}],"wp:attachment":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media?parent=7674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/categories?post=7674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/tags?post=7674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}