{"id":7687,"date":"2021-09-23T11:17:20","date_gmt":"2021-09-23T15:17:20","guid":{"rendered":"https:\/\/pembrokediocese.com\/textes-a-lire\/quand-nous-crions-vers-dieu-copy\/"},"modified":"2022-08-19T11:01:39","modified_gmt":"2022-08-19T15:01:39","slug":"apprendre-a-etre-missionnaire","status":"publish","type":"post","link":"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/apprendre-a-etre-missionnaire\/","title":{"rendered":"ARTICLE &#8211; Apprendre \u00e0 \u00eatre missionnaire"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Apprendre \u00e0 \u00eatre missionnaire se fait dans un contexte et une attitude d&rsquo;amour pour les personnes qui ne connaissent pas le Christ ou qui ne le suivent pas. Cela exige d&rsquo;\u00eatre ouvert aux id\u00e9es et aux perspectives des autres et de suspendre nos id\u00e9es personnelles, culturelles et religieuses pour \u00e9couter leur exp\u00e9rience de vie. Le chemin vers la mission est pav\u00e9 de compassion et d&#8217;empathie.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Apprendre \u00e0 \u00eatre missionnaire, c&rsquo;est aussi chercher \u00e0 voir nos paroisses \u00e0 travers les yeux des personnes en recherche, c\u2019est sentir leur c\u0153ur lorsqu&rsquo;elles participent \u00e0 nos c\u00e9l\u00e9brations, c\u2019est se mettre \u00e0 leur place lorsqu&rsquo;elles visitent notre \u00e9glise pour la premi\u00e8re fois. Comprendraient-elles le vocabulaire utilis\u00e9 dans l&rsquo;hom\u00e9lie ?\u00a0 Quelqu&rsquo;un remarquera-t-il leur pr\u00e9sence et les fera-t-il se sentir les bienvenus ? Si nous voulons \u00eatre une \u00c9glise missionnaire, ne devrions-nous pas cr\u00e9er et favoriser pour elles une exp\u00e9rience d&rsquo;\u00e9glise qui soit enthousiasmante, personnelle, accueillante, pertinente et qui favorise la rencontre avec le sacr\u00e9, la rencontre avec J\u00e9sus vivant et habitant parmi nous ? Puisons dans la r\u00e9serve infinie de mis\u00e9ricorde de Dieu pour ceux et celles qui souffrent et qui se perdent et partagerons l&rsquo;\u00c9vangile avec des actions et des mots qui toucheront leur c\u0153ur.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Alors que nous voyons notre soci\u00e9t\u00e9 et ses modes de vie si souvent model\u00e9s sur le mat\u00e9rialisme, le consum\u00e9risme, l\u2019h\u00e9donisme et l&rsquo;accumulation des richesses, ayons le courage de rechercher les int\u00e9r\u00eats de Dieu qui sont la paix, la r\u00e9conciliation, l&rsquo;amour et le salut \u00e9ternel des personnes qui nous entourent. Oui, sachons tout laisser pour suivre J\u00e9sus.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nous prions pour que cette ann\u00e9e pastorale soit l&rsquo;occasion de tourner notre regard vers l&rsquo;ext\u00e9rieur, vers ceux et celles qui ne connaissent pas ou ne suivent pas le Christ, afin que nous ne nous contentions pas de parler de mission et d&rsquo;\u00e9vang\u00e9lisation, mais que nous trouvions et mettions en oeuvre des moyens concrets pour r\u00e9pondre avec audace, en actes et en paroles, \u00e0 la pauvret\u00e9 et \u00e0 la faim spirituelles de ceux et celles qui nous entourent.<\/span><\/p>\n<p style=\"text-align: right;\">Pierre-Alain Giffard, directeur de la pastorale dioc\u00e9saine<\/p>\n<p>Autres articles :<\/p>\n<ul>\n<li><strong class=\"post-title\"><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/trois-obstacles-a-letablissement-dune-culture-dinvitation-dans-votre-paroisse\/\">Trois obstacles \u00e0 l\u2019\u00e9tablissement d\u2019une culture d\u2019invitation dans votre paroisse<\/a><\/strong><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/levangelisateur-relationnel\/\"><strong class=\"post-title\">L\u2019\u00e9vang\u00e9lisateur relationnel<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/faire-eglise-a-la-maison\/\"><strong class=\"post-title\">Faire \u00c9glise \u00e0 la maison<\/strong><\/a><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-fille-aveugle\/\">La fille aveugle<\/a><\/strong><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/un-groupe-de-gernouilles\/\"><strong>Un groupe de grenouilles<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/lelephant-attache\/\"><strong>L\u2019\u00e9l\u00e9phant attach\u00e9<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/paroisse-de-la-nativite\/\"><strong>Le renouveau de la paroisse de la Nativit\u00e9 \u00e0 Baltimore<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/la-foi-grandit-copy\/\"><strong>La foi grandit lorsqu\u2019on la partage<\/strong><\/a><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/dans-les-souliers-des-sans-eglises\/\">Dans les souliers des \u201csans-\u00e9glises\u201d<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-cellules-paroissiales-devangelisation-2-copy\/\">Les cellules paroissiales d\u2019\u00e9vang\u00e9lisation<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/caracteristiques-uniques-des-paroisses-missionnaires\/\">Six caract\u00e9ristiques uniques des paroisses missionnaires<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/devenir-une-paroisse-missionnaire\/\">Quelques \u00e9tapes pour devenir une paroisse missionnaire<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quest-ce-que-levangelisation\/\">Qu\u2019est-ce que l\u2019\u00e9vang\u00e9lisation et dans quel esprit la pratiquer ?<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/auto-evaluation\/\">Questions de discussion et d\u2019auto-\u00e9valuation pour l\u2019\u00e9vang\u00e9lisation en paroisse<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-priere-de-jesus\/\">La pri\u00e8re de J\u00e9sus: une m\u00e9thode pour prier en tout temps<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/pratiquer-leur-foi\/\">Qu\u2019est-ce qui peut aider les enfants \u00e9lev\u00e9s dans la religion catholique \u00e0 continuer \u00e0 pratiquer leur foi \u00e0 l\u2019\u00e2ge adulte ?<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/les-tactiques-de-satan-1ere-partie\/\">Les tactiques de Satan<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/apprendre-a-etre-missionnaire\/\">Apprendre \u00e0 \u00eatre missionnaire<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/quand-nous-crions-vers-dieu\/\">Quand nous crions vers Dieu, il r\u00e9pond<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent-copy\/\">Pr\u00e9sence et Proclamation<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/sauver-ceux-qui-se-perdent\/\">Sauver ceux qui se perdent<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/la-paroisse-saint-nazaire-lhistoire-dune-transformation-missionnaire\/\">La paroisse Saint-Nazaire: L\u2019histoire d\u2019une transformation missionnaire<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/evangelisation-et-petits-groupes-de-partage\/\">\u00c9vang\u00e9lisation et petits groupes de partage<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/evangeliser-en-invitant-des-personnes-a-recevoir-jesus-comme-seigneur-et-sauveur\/\">\u00c9vang\u00e9liser en invitant des personnes \u00e0 recevoir J\u00e9sus comme Seigneur et Sauveur<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/article\/vous-allez-recevoir-une-force\/\">Vous allez recevoir une force\u2026<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/avez-vous-entendu-parler-de-la-loi-des-trois-ecoutes-et-des-sept-contacts\/\">Avez-vous entendu parler de la loi des trois \u00e9coutes et des sept contacts ?<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/trois-habitudes-dune-vie-chretienne-fructueuse\/\">Trois habitudes d\u2019une vie chr\u00e9tienne fructueuse<\/a><\/strong><\/li>\n<\/ul>\n<div class=\"info\">\n<hr \/>\n<\/div>\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\">\n<p><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1993 size-full\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/Bible-studying-100x100.png 100w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\">LECTURES RECOMMANDEES<\/a><\/h4>\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"\/fr\/nouvelle-evangelisation\/lectures-recommandees\/\" target=\"_self\" >En savoir plus <\/a>\n<\/div>\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\">\n<p><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/prayer-group\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3620\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-300x300.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-300x300.png 300w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-100x100.png 100w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-400x400.png 400w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle-210x210.png 210w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/girl-praying-circle.png 684w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/fr\/nouvelle-evangelisation\/prayer-group\/\">PRI\u00c8RES ET GROUPES DE PRIERE POUR LE PROJET DIOC\u00c9SAIN DE NOUVELLE \u00c9VANG\u00c9LISATION<\/a><\/h4>\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"\/fr\/nouvelle-evangelisation\/prayer-group\/\" target=\"_self\" >En savoir plus<\/a>\n<\/div>\n<div class=\"col-md-4 \" data-appear-animation=\"bounceInRight\">\n<p><a href=\"https:\/\/pembrokediocese.com\/donate\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7117 size-medium aligncenter\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-200x200.png\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-200x200.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-150x150.png 150w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-768x768.png 768w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-100x100.png 100w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-400x400.png 400w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept-210x210.png 210w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/donate-concept.png 800w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/pembrokediocese.com\/donate\/\">DONNER POUR LE PROJET DIOC\u00c9SAIN DE NOUVELLE \u00c9VANG\u00c9LISATION<\/a><\/h4>\n<p style=\"text-align: center;\"><a class=\"btn btn-primary  \" href=\"https:\/\/pembrokediocese.com\/donate\/\" target=\"_self\" >En savoir plus<\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Apprendre \u00e0 \u00eatre missionnaire se fait dans un contexte et une attitude d&rsquo;amour pour les personnes qui ne connaissent pas le Christ ou qui ne le suivent pas. Cela exige d&rsquo;\u00eatre ouvert aux id\u00e9es et aux perspectives des autres et de suspendre nos id\u00e9es personnelles, culturelles et religieuses pour \u00e9couter leur exp\u00e9rience de vie. Le chemin vers la mission est pav\u00e9 de compassion et d&#8217;empathie. Apprendre \u00e0 \u00eatre missionnaire, c&rsquo;est aussi chercher \u00e0 voir nos paroisses \u00e0 travers les yeux des personnes en recherche, c\u2019est sentir leur c\u0153ur lorsqu&rsquo;elles participent \u00e0 nos c\u00e9l\u00e9brations, c\u2019est se mettre \u00e0 leur place lorsqu&rsquo;elles visitent notre \u00e9glise pour la premi\u00e8re fois. Comprendraient-elles le vocabulaire utilis\u00e9 dans l&rsquo;hom\u00e9lie ?\u00a0 Quelqu&rsquo;un remarquera-t-il leur pr\u00e9sence et les fera-t-il se sentir les bienvenus ? Si nous voulons \u00eatre une \u00c9glise missionnaire, ne devrions-nous pas cr\u00e9er et favoriser pour elles une exp\u00e9rience d&rsquo;\u00e9glise qui soit enthousiasmante, personnelle, accueillante, pertinente et qui favorise la rencontre avec le sacr\u00e9, la rencontre avec J\u00e9sus vivant et habitant parmi nous ? Puisons dans la r\u00e9serve infinie de mis\u00e9ricorde de Dieu pour ceux et celles qui souffrent et qui se perdent et partagerons l&rsquo;\u00c9vangile avec des actions et des mots qui toucheront leur c\u0153ur.\u00a0 Alors que nous voyons notre soci\u00e9t\u00e9 et ses modes de vie si souvent model\u00e9s sur le mat\u00e9rialisme, le consum\u00e9risme, l\u2019h\u00e9donisme et l&rsquo;accumulation des richesses, ayons le courage de rechercher les int\u00e9r\u00eats de Dieu qui sont la paix, la r\u00e9conciliation, l&rsquo;amour et le salut \u00e9ternel des personnes qui nous entourent. Oui, sachons tout laisser pour suivre J\u00e9sus.\u00a0 Nous prions pour que cette ann\u00e9e pastorale soit l&rsquo;occasion de tourner notre regard vers l&rsquo;ext\u00e9rieur, vers ceux et celles qui ne connaissent pas ou ne suivent pas le Christ, afin que nous ne nous contentions pas de parler de mission et d&rsquo;\u00e9vang\u00e9lisation, mais que nous trouvions et mettions en oeuvre des moyens concrets pour r\u00e9pondre avec audace, en actes et en paroles, \u00e0 la pauvret\u00e9 et \u00e0 la faim spirituelles de ceux et celles qui nous entourent. Pierre-Alain Giffard, directeur de la pastorale dioc\u00e9saine Autres articles : Trois obstacles \u00e0 l\u2019\u00e9tablissement d\u2019une culture d\u2019invitation dans votre paroisse L\u2019\u00e9vang\u00e9lisateur relationnel Faire \u00c9glise \u00e0 la maison La fille aveugle Un groupe de grenouilles L\u2019\u00e9l\u00e9phant attach\u00e9 Le renouveau de la paroisse de la Nativit\u00e9 \u00e0 Baltimore La foi grandit lorsqu\u2019on la partage Dans les souliers des \u201csans-\u00e9glises\u201d Les cellules paroissiales d\u2019\u00e9vang\u00e9lisation Six caract\u00e9ristiques uniques des paroisses missionnaires Quelques \u00e9tapes pour devenir une paroisse missionnaire Qu\u2019est-ce que l\u2019\u00e9vang\u00e9lisation et dans quel esprit la pratiquer ? Questions de discussion et d\u2019auto-\u00e9valuation pour l\u2019\u00e9vang\u00e9lisation en paroisse La pri\u00e8re de J\u00e9sus: une m\u00e9thode pour prier en tout temps Qu\u2019est-ce qui peut aider les enfants \u00e9lev\u00e9s dans la religion catholique \u00e0 continuer \u00e0 pratiquer leur foi \u00e0 l\u2019\u00e2ge adulte ? Les tactiques de Satan Apprendre \u00e0 \u00eatre missionnaire Quand nous crions vers Dieu, il r\u00e9pond Pr\u00e9sence et Proclamation Sauver ceux qui se perdent La paroisse Saint-Nazaire: L\u2019histoire d\u2019une transformation missionnaire \u00c9vang\u00e9lisation et petits groupes de partage \u00c9vang\u00e9liser en invitant des personnes \u00e0 recevoir J\u00e9sus comme Seigneur et Sauveur Vous allez recevoir une force\u2026 Avez-vous entendu parler de la loi des trois \u00e9coutes [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[156],"tags":[],"class_list":["post-7687","post","type-post","status-publish","format-standard","hentry","category-textes-a-lire"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/7687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/comments?post=7687"}],"version-history":[{"count":1,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/7687\/revisions"}],"predecessor-version":[{"id":10387,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/7687\/revisions\/10387"}],"wp:attachment":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media?parent=7687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/categories?post=7687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/tags?post=7687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}