{"id":8138,"date":"2021-11-30T09:58:56","date_gmt":"2021-11-30T14:58:56","guid":{"rendered":"https:\/\/pembrokediocese.com\/bulletin\/23-novembre-2021-copy\/"},"modified":"2021-11-30T10:25:35","modified_gmt":"2021-11-30T15:25:35","slug":"30-novembre-2021","status":"publish","type":"post","link":"https:\/\/pembrokediocese.com\/fr\/bulletin\/30-novembre-2021\/","title":{"rendered":"BULLETIN HEBDOMADAIRE  &#8211; le 30 novembre 2021  (St Andr\u00e9, Ap\u00f4tre)"},"content":{"rendered":"<h4><strong><i><a href=\"mailto:reception@pembrokediocese.com?subject=Abonnez-vous au bulletin hebdomadaire&amp;amp;body=Bonjour, je souhaite m'abonner au Bulletin Hebdomadaire s'il vous plait. Merci.\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-8004\" src=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr-200x205.png\" alt=\"\" width=\"124\" height=\"127\" srcset=\"https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr-200x205.png 200w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr-768x785.png 768w, https:\/\/pembrokediocese.com\/wp-content\/uploads\/subscribe-banner-fr.png 840w\" sizes=\"(max-width: 124px) 100vw, 124px\" \/><\/a><\/i><\/strong><\/h4>\n<h3><strong><em>Aussit\u00f4t, laissant leurs filets, ils le suivrent.<\/em><\/strong><\/h3>\n<p>(Matthieu 4, 18-22)<\/p>\n<hr \/>\n<h2><strong>MESSAGES DE L&rsquo;\u00c9V<\/strong><strong>\u00ca<\/strong><strong>QUE<\/strong><\/h2>\n<p><strong>Message de Mgr Guy Desrochers concernant la d\u00e9mission de l\u2019abb\u00e9 Justin Bertrand\u00a0:<\/strong> Lire <a href=\"https:\/\/pembrokediocese.com\/fr\/article\/message-de-mgr-guy-desrochers-concernant-la-demission-de-labbe-justin-bertrand\/\">ici<\/a>.<\/p>\n<hr \/>\n<h2><strong>MESSAGE DE <\/strong><strong>L&rsquo;\u00c9V<\/strong><strong>\u00ca<\/strong><strong>QUE POUR L&rsquo;AVENT<\/strong><\/h2>\n<h3><strong>La saison de l\u2019Avent est arriv\u00e9e!<\/strong><\/h3>\n<p><strong>Chers fr\u00e8res et s\u0153urs dans le Christ,<\/strong><\/p>\n<p>En latin, le mot \u2018Avent\u2019 s\u2019\u00e9crit \u00ab\u00a0Adventus\u00a0\u00bb. Cela se traduit litt\u00e9ralement par \u00ab\u00a0arriv\u00e9e, av\u00e8nement\u00a0\u00bb d\u2019o\u00f9 le latin chr\u00e9tien le traduit par \u00ab\u00a0venue du Christ\u00a0\u00bb. On rapporte que c\u2019est le pape Gr\u00e9goire le Grand qui a instaur\u00e9 ce temps liturgique vers la fin du VI<sup>e<\/sup> si\u00e8cle. <a href=\"https:\/\/pembrokediocese.com\/fr\/article\/saison-de-lavent-est-arrivee\/\">(Lire la suite\u2026)<\/a><\/p>\n<hr \/>\n<h2><strong>DU DIOC\u00c8SE<\/strong><\/h2>\n<h3><strong>Nouvelle page web pour le parcours synodal dans le dioc\u00e8se de Pembroke<\/strong><\/h3>\n<p>Comme vous le savez, le pape Fran\u00e7ois a lanc\u00e9 dans l\u2019\u00c9glise un vaste chemin synodal. Il appelle tous les catholiques \u00e0 prendre du temps pour s\u2019\u00e9couter mutuellement et \u00e0 se laisser \u201cbousculer\u201d par l\u2019Esprit Saint. \u00c0 travers ce synode, nous nous demandons: \u201cQu\u2019est-ce que Dieu veut nous dire en ce moment?\u201d. Et nous aspirons \u00e0 d\u00e9couvrir des chemins de communion, de participation et de mission.<\/p>\n<p><strong><a href=\"https:\/\/pembrokediocese.com\/fr\/synode\/\">Une page web a \u00e9t\u00e9 cr\u00e9\u00e9e sur le site du dioc\u00e8se<\/a><\/strong> pour d\u00e9crire ce \u00e0 quoi ressemble ce parcours synodal dans notre dioc\u00e8se. On peut y acc\u00e9der facilement \u00e0 partir de la page d&rsquo;accueil. Nous vous invitons \u00e0 la visiter et \u00e0 commencer \u00e0 prier et \u00e0 r\u00e9fl\u00e9chir aux questions de ce synode.<\/p>\n<h3><strong>Nominations pastorales<\/strong><\/h3>\n<p>Monseigneur Guy Desrochers, C.Ss.R., annonce les nominations pastorales suivantes:<\/p>\n<ul>\n<li><strong>Le p\u00e8re Steven Ballard<\/strong> est nomm\u00e9 cur\u00e9 de la paroisse St John Chrysostom, Arnprior, et de la paroisse Our Lady of Perpetual Help, Braeside. <strong>Cette nomination entre en vigueur le 1er f\u00e9vrier 2022.<\/strong><\/li>\n<li><strong>Le p\u00e8re Justin Bertrand<\/strong> a d\u00e9missionn\u00e9 du minist\u00e8re sacerdotal et a exprim\u00e9 son d\u00e9sir de demander une dispense des obligations de l&rsquo;\u00e9tat cl\u00e9rical.<\/li>\n<li><strong>Le p\u00e8re John Burchat<\/strong> est nomm\u00e9 cur\u00e9 de la paroisse St Lawrence O&rsquo;Toole, Barry&rsquo;s Bay, de la paroisse Holy Canadian Martyrs, Combermere, et de la mission St Francis de Sales, Latchford Bridge. <strong>Cette nomination entre en vigueur le 1er f\u00e9vrier 2022.<\/strong> Un pr\u00eatre de Madonna House poursuivra l&rsquo;administration jusqu&rsquo;\u00e0 la fin du mois de d\u00e9cembre.<\/li>\n<li><strong>Le p\u00e8re Patrick Dobec<\/strong> est nomm\u00e9 cur\u00e9 de la paroisse Our Lady of Sorrows, Petawawa. <strong>Cette nomination entre en vigueur le 1er f\u00e9vrier 2022.<\/strong><\/li>\n<li><strong>Le p\u00e8re R\u00e9al Ouellette<\/strong> restera dans les paroisses de Saint-Thomas-d&rsquo;Aquin, Astorville, Sainte-Bernadette, Bonfield, et Sacred Heart, Corbeil.<\/li>\n<li><strong>Le p\u00e8re Peter Proulx<\/strong> terminera son minist\u00e8re \u00e0 temps partiel en tant que vicaire paroissial de la paroisse St John Chrysostom, Arnprior.<\/li>\n<li><strong>Le p\u00e8re Robert Ryan<\/strong> terminera son minist\u00e8re \u00e0 la paroisse Our Lady of Perpetual Help, Braeside, alors qu&rsquo;il poursuit sa convalescence apr\u00e8s un cancer.<\/li>\n<li><strong>Le p\u00e8re Basil Tanguay<\/strong> est nomm\u00e9 vicaire paroissial \u00e0 temps partiel aux paroisses de St James the Greater, Portage-du-Fort, Immacul\u00e9e-Conception, Bryson, Ste-Anne, \u00cele-du-Grand Calumet et St John the Evangelist, Campbell&rsquo;s Bay. <strong>Cette nomination est entr\u00e9e en vigueur le 1er novembre 2021.<\/strong><\/li>\n<\/ul>\n<h3><strong>Ordo \u2013 calendriers pour l\u2019ann\u00e9e 2021-22<\/strong><em>\u00a0<\/em><\/h3>\n<p>Ordo \u2013 calendriers pour l\u2019ann\u00e9e 2021-22 sont maintenant disponibles \u00e0 l\u2019\u00e9v\u00each\u00e9 pour 20$ seulement. Veuillez communiquer avec Donna Biggs au 613 732-7933 poste 203 ou <a href=\"mailto:donnabiggs@pembrokediocese.com\">donnabiggs@pembrokediocese.com<\/a>.<\/p>\n<h3><strong>Nous avons d\u00e9m\u00e9nag\u00e9 !<\/strong><\/h3>\n<p>Veuillez noter qu&rsquo;en raison de r\u00e9novations, la chancellerie et les bureaux de l&rsquo;\u00e9v\u00eaque ont temporairement d\u00e9m\u00e9nag\u00e9 au 545, rue Pembroke Ouest, Pembroke. Toute correspondance peut encore \u00eatre envoy\u00e9e \u00e0 C.P. 7, Pembroke, ON, K8A 6X1.<\/p>\n<hr \/>\n<h2><strong>V\u00c9RIT\u00c9 ET R\u00c9CONCILIATION<\/strong><\/h2>\n<h3><strong>CECC \u2013 Ressources \u00e9ducatives (D\u00e9l\u00e9gation autochtone : 17-20 d\u00e9cembre (Cit\u00e9 du Vatican))<\/strong><\/h3>\n<p>Chaque semaine, \u00e0 partir du dimanche 21\u00a0novembre 2021, en la solennit\u00e9 du Christ-Roi, la CECC diffusera une vid\u00e9o dans laquelle \u2019un \u00e9v\u00eaque r\u00e9fl\u00e9chit \u00e0 la lecture de l\u2019\u00c9vangile pour chaque dimanche jusqu\u2019\u00e0 No\u00ebl. Cette ann\u00e9e, les r\u00e9flexions sont inspir\u00e9es par la d\u00e9l\u00e9gation autochtone qui rencontrera le pape Fran\u00e7ois au Vatican du 17\u00a0au 20\u00a0d\u00e9cembre 2021. Chaque r\u00e9flexion vid\u00e9o est bas\u00e9e sur l\u2019une des cinq \u00e9tapes essentielles de la r\u00e9conciliation\u00a0: examen, confession, repentir, r\u00e9paration (faire amende honorable) et r\u00e9conciliation.<\/p>\n<p>Au fur et \u00e0 mesure que chaque nouvelle vid\u00e9o est diffus\u00e9e, vous trouverez sur cette page deux ressources \u00e9ducatives d\u2019accompagnement pour faciliter vos r\u00e9flexions personnelles hebdomadair<a href=\"https:\/\/www.cccb.ca\/fr\/peuples-autochtones\/delegation-autochtone-17-20-decembre-2021-cite-du-vatican\/ressources-educatives\/\">\u00a0<\/a>es. Le processus ci-dessous sugg\u00e8re une fa\u00e7on d\u2019utiliser la vid\u00e9o et les ressources \u00e9ducatives ensemble pour approfondir la r\u00e9flexion sur chaque th\u00e8me.<a href=\"https:\/\/www.cccb.ca\/fr\/peuples-autochtones\/delegation-autochtone-17-20-decembre-2021-cite-du-vatican\/ressources-educatives\/\">(Lire la suite\u2026)<\/a><\/p>\n<hr \/>\n<h2><strong>L&rsquo;\u00c9QUIPE D&rsquo;\u00c9VANG\u00c9LISATION<\/strong><\/h2>\n<h3><strong>Qu\u2019est-ce qui peut aider les enfants \u00e9lev\u00e9s dans la religion catholique \u00e0 continuer \u00e0 pratiquer leur foi \u00e0 l\u2019\u00e2ge adulte?<\/strong><\/h3>\n<p>Selon l\u2019enqu\u00eate faite par The Pillar Survey on Religious Attitudes and Practices, certains facteurs permettent de pr\u00e9dire si les enfants \u00e9lev\u00e9s dans la religion catholique continueront \u00e0 la pratiquer \u00e0 l\u2019\u00e2ge adulte. Ces facteurs sont les suivants : <a href=\"https:\/\/pembrokediocese.com\/fr\/textes-a-lire\/pratiquer-leur-foi\/\">(Lire la suite\u2026)<\/a><\/p>\n<hr \/>\n<h2><strong>DE LA CECC<\/strong><\/h2>\n<h3><strong>Journ\u00e9e nationale de pri\u00e8re en solidarit\u00e9 avec les peuples autochtones 2021 \u2013 jeudi, novembre 25, 2021<\/strong><\/h3>\n<p>Le 12 d\u00e9cembre, f\u00eate de Notre-Dame de Guadalupe, l\u2019\u00c9glise au Canada c\u00e9l\u00e8bre la Journ\u00e9e nationale de pri\u00e8re en solidarit\u00e9 avec les peuples autochtones.<\/p>\n<p>Approuv\u00e9 par les \u00e9v\u00eaques du Canada, ce projet est coordonn\u00e9 par le Conseil autochtone catholique du Canada \u00a0depuis 2002.<\/p>\n<p>Cette ann\u00e9e, la r\u00e9flexion du Conseil s\u2019articule autour du th\u00e8me\u00a0Nous sommes appel\u00e9s \u00e0 la gu\u00e9rison, le pardon, la r\u00e9conciliation. \u00ab\u00a0Nous, le Corps du Christ, sommes appel\u00e9s \u00e0 vivre dans l\u2019amiti\u00e9 et l\u2019harmonie avec tous les peuples. Nous sommes fr\u00e8res et s\u0153urs de notre unique Dieu Cr\u00e9ateur. \u00c0 nous tous, Dieu donne tout. Dieu cr\u00e9e et pr\u00e9serve la merveilleuse diversit\u00e9 des peuples, des cultures, des races et des croyances.\u00a0\u00bb<\/p>\n<p><strong><a href=\"https:\/\/www.cccb.ca\/wp-content\/uploads\/2021\/11\/2021-Journee-nationale-de-priere.pdf\">Message 2021 du Conseil autochtone catholique du Canada<\/a><\/strong><\/p>\n<h3><strong>D\u00e9cret d\u2019entr\u00e9e en vigueur \u2013 Nouvelle traduction fran\u00e7aise du Missel romain<\/strong><\/h3>\n<p>Lire la lettre <a href=\"https:\/\/www.cccb.ca\/fr\/letter\/decret-no-2021-01-f-decret-dentree-en-vigeur-nouvelle-traduction-francaise-du-missel-romain\/\">ici<\/a>.<\/p>\n<hr \/>\n<h2><strong>VATICAN NEWS<\/strong><\/h2>\n<h3><strong>Intention de pri\u00e8re du Saint-P\u00e8re pour le mois de d\u00e9cembre<\/strong><\/h3>\n<p>Intention pour l&rsquo;\u00e9vang\u00e9lisation &#8211; Cat\u00e9chistes. Prions pour les cat\u00e9chistes, appel\u00e9s \u00e0 annoncer la Parole de Dieu : qu&rsquo;ils en soient les t\u00e9moins, avec courage et cr\u00e9ativit\u00e9 et dans la puissance de l&rsquo;Esprit Saint.<\/p>\n<hr \/>\n<h2><strong>\u00c9V\u00c9NEMENTS PAROISSIAUX<\/strong><\/h2>\n<h3><strong>Sainte Messe<\/strong><\/h3>\n<p>La Sainte Messe selon le Missel romain de 1962 est offerte \u00e0 la Cath\u00e9drale St Columbkille le premier samedi de chaque mois \u00e0 9 h. Il s&rsquo;agit essentiellement de la m\u00eame forme de la liturgie qui a nourri la foi de nombreux catholiques pendant des si\u00e8cles. \u00a0Des traductions en anglais de l&rsquo;ensemble de la messe sont fournies. <strong>Prochaine messe \u2013 4 d\u00e9cembre 2021.<\/strong><\/p>\n<hr \/>\n<h2><strong>AVENT<\/strong><\/h2>\n<h3><strong>CECC \u2013 Cheminer ensemble durant l\u2019Avent 2021 \u2013 Les peuples autochtones et l\u2019\u00c9glise : avancer ensemble vers la gu\u00e9rison et la r\u00e9conciliation<\/strong><\/h3>\n<p>Chaque semaine, \u00e0 partir du dimanche 21 novembre 2021, en la solennit\u00e9 du Christ Roi, la CECC diffusera un enregistrement vid\u00e9o d\u2019un \u00e9v\u00eaque au Canada qui r\u00e9fl\u00e9chira sur la lecture de l\u2019\u00c9vangile pour chaque dimanche de l\u2019Avent. Les r\u00e9flexions de cette ann\u00e9e ont \u00e9t\u00e9 \u00e9labor\u00e9es en vue de\u00a0<strong><a href=\"https:\/\/www.cccb.ca\/fr\/announcement\/declaration-de-la-cecc-date-de-la-delegation-aupres-du-saint-siege\/\">la d\u00e9l\u00e9gation autochtone qui se rendra \u00e0 Rome pour rencontrer le pape Fran\u00e7ois du 17 au 20 d\u00e9cembre 2021<\/a><\/strong>. Chaque r\u00e9flexion est bas\u00e9e sur l\u2019une des cinq \u00e9tapes essentielles de la r\u00e9conciliation : l\u2019examen, la confession, le repentir, la r\u00e9paration (faire amende honorable) et la r\u00e9conciliation. De m\u00eame, nous esp\u00e9rons que ces r\u00e9flexions aideront les fid\u00e8les, autochtones et non autochtones, \u00e0 se pr\u00e9parer \u00e0\u00a0<strong><a href=\"https:\/\/www.cccb.ca\/fr\/media-release\/les-eveques-canadiens-accueilleront-le-pape-francois-au-canada-a-loccasion-dun-pelerinage-historique-de-guerison-et-de-reconciliation\/\">l\u2019\u00e9ventuel voyage apostolique du pape Fran\u00e7ois au Canada<\/a><\/strong>. <a href=\"https:\/\/www.cccb.ca\/fr\/evangelisation-catechese-et-education\/ressources-video\/cheminer-ensemble-durant-lavent\/\">(Lire la suite\u2026)<\/a><\/p>\n<hr \/>\n<h2><strong>AUTRES \u00c9V\u00c9NEMENTS CATHOLIQUES<\/strong><\/h2>\n<h3><strong>Conf\u00e9rence gratuite en ligne du fr\u00e8re Michel Gourgues<\/strong><\/h3>\n<p><strong>Conf\u00e9rence gratuite en ligne du fr\u00e8re Michel Gourgues<\/strong>, dominicain et professeur de Nouveau Testament au Coll\u00e8ge Universitaire Dominicain (campus de Montr\u00e9al et d&rsquo;Ottawa) : \u00ab\u00a0L&rsquo;Esprit de v\u00e9rit\u00e9 et le discernement de l&rsquo;\u00e9v\u00e9nement J\u00e9sus dans l&rsquo;\u00e9vangile de Jean\u00a0\u00bb le <strong>mardi 30 novembre 2021 \u00e0 19h30. <\/strong>Inscrivez-vous en envoyant un courriel \u00e0 <a href=\"mailto:cdevs@udominicaine.ca\">cdevs@udominicaine.ca<\/a>.<\/p>\n<h3><strong>Nouvelle traduction fran\u00e7aise du Missel romain<\/strong><\/h3>\n<p>\u00c0 partir du dimanche 28 novembre 2021, les communaut\u00e9s francophones utiliseront une nouvelle traduction fran\u00e7aise du Missel romain. Pour nous aider \u00e0 ce changement, le P\u00e8re R\u00e9al Ouellette a enregistr\u00e9 une pr\u00e9sentation \u00e0 ce sujet que vous pouvez consulter sur sa cha\u00eene YouTube :\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=O7Y8d7YGz7A\">https:\/\/www.youtube.com\/watch?v=O7Y8d7YGz7A<\/a>.<\/p>\n<hr \/>\n<h2><strong>AUTRES<\/strong><\/h2>\n<h3><strong>Orgue \u00e9lectrique \u00e0 donner<\/strong><\/h3>\n<p>Les personnes int\u00e9ress\u00e9es peuvent contacter Ghislaine au 819 689-5489.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aussit\u00f4t, laissant leurs filets, ils le suivrent. (Matthieu 4, 18-22) MESSAGES DE L&rsquo;\u00c9V\u00caQUE Message de Mgr Guy Desrochers concernant la d\u00e9mission de l\u2019abb\u00e9 Justin Bertrand\u00a0: Lire ici. MESSAGE DE L&rsquo;\u00c9V\u00caQUE POUR L&rsquo;AVENT La saison de l\u2019Avent est arriv\u00e9e! Chers fr\u00e8res et s\u0153urs dans le Christ, En latin, le mot \u2018Avent\u2019 s\u2019\u00e9crit \u00ab\u00a0Adventus\u00a0\u00bb. Cela se traduit litt\u00e9ralement par \u00ab\u00a0arriv\u00e9e, av\u00e8nement\u00a0\u00bb d\u2019o\u00f9 le latin chr\u00e9tien le traduit par \u00ab\u00a0venue du Christ\u00a0\u00bb. On rapporte que c\u2019est le pape Gr\u00e9goire le Grand qui a instaur\u00e9 ce temps liturgique vers la fin du VIe si\u00e8cle. (Lire la suite\u2026) DU DIOC\u00c8SE Nouvelle page web pour le parcours synodal dans le dioc\u00e8se de Pembroke Comme vous le savez, le pape Fran\u00e7ois a lanc\u00e9 dans l\u2019\u00c9glise un vaste chemin synodal. Il appelle tous les catholiques \u00e0 prendre du temps pour s\u2019\u00e9couter mutuellement et \u00e0 se laisser \u201cbousculer\u201d par l\u2019Esprit Saint. \u00c0 travers ce synode, nous nous demandons: \u201cQu\u2019est-ce que Dieu veut nous dire en ce moment?\u201d. Et nous aspirons \u00e0 d\u00e9couvrir des chemins de communion, de participation et de mission. Une page web a \u00e9t\u00e9 cr\u00e9\u00e9e sur le site du dioc\u00e8se pour d\u00e9crire ce \u00e0 quoi ressemble ce parcours synodal dans notre dioc\u00e8se. On peut y acc\u00e9der facilement \u00e0 partir de la page d&rsquo;accueil. Nous vous invitons \u00e0 la visiter et \u00e0 commencer \u00e0 prier et \u00e0 r\u00e9fl\u00e9chir aux questions de ce synode. Nominations pastorales Monseigneur Guy Desrochers, C.Ss.R., annonce les nominations pastorales suivantes: Le p\u00e8re Steven Ballard est nomm\u00e9 cur\u00e9 de la paroisse St John Chrysostom, Arnprior, et de la paroisse Our Lady of Perpetual Help, Braeside. Cette nomination entre en vigueur le 1er f\u00e9vrier 2022. Le p\u00e8re Justin Bertrand a d\u00e9missionn\u00e9 du minist\u00e8re sacerdotal et a exprim\u00e9 son d\u00e9sir de demander une dispense des obligations de l&rsquo;\u00e9tat cl\u00e9rical. Le p\u00e8re John Burchat est nomm\u00e9 cur\u00e9 de la paroisse St Lawrence O&rsquo;Toole, Barry&rsquo;s Bay, de la paroisse Holy Canadian Martyrs, Combermere, et de la mission St Francis de Sales, Latchford Bridge. Cette nomination entre en vigueur le 1er f\u00e9vrier 2022. Un pr\u00eatre de Madonna House poursuivra l&rsquo;administration jusqu&rsquo;\u00e0 la fin du mois de d\u00e9cembre. Le p\u00e8re Patrick Dobec est nomm\u00e9 cur\u00e9 de la paroisse Our Lady of Sorrows, Petawawa. Cette nomination entre en vigueur le 1er f\u00e9vrier 2022. Le p\u00e8re R\u00e9al Ouellette restera dans les paroisses de Saint-Thomas-d&rsquo;Aquin, Astorville, Sainte-Bernadette, Bonfield, et Sacred Heart, Corbeil. Le p\u00e8re Peter Proulx terminera son minist\u00e8re \u00e0 temps partiel en tant que vicaire paroissial de la paroisse St John Chrysostom, Arnprior. Le p\u00e8re Robert Ryan terminera son minist\u00e8re \u00e0 la paroisse Our Lady of Perpetual Help, Braeside, alors qu&rsquo;il poursuit sa convalescence apr\u00e8s un cancer. Le p\u00e8re Basil Tanguay est nomm\u00e9 vicaire paroissial \u00e0 temps partiel aux paroisses de St James the Greater, Portage-du-Fort, Immacul\u00e9e-Conception, Bryson, Ste-Anne, \u00cele-du-Grand Calumet et St John the Evangelist, Campbell&rsquo;s Bay. Cette nomination est entr\u00e9e en vigueur le 1er novembre 2021. Ordo \u2013 calendriers pour l\u2019ann\u00e9e 2021-22\u00a0 Ordo \u2013 calendriers pour l\u2019ann\u00e9e 2021-22 sont maintenant disponibles \u00e0 l\u2019\u00e9v\u00each\u00e9 pour 20$ seulement. Veuillez communiquer avec Donna Biggs au 613 732-7933 poste 203 ou donnabiggs@pembrokediocese.com. Nous avons d\u00e9m\u00e9nag\u00e9 ! Veuillez noter qu&rsquo;en raison de r\u00e9novations, la chancellerie et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3815,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[114],"tags":[],"class_list":["post-8138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bulletin"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/8138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/comments?post=8138"}],"version-history":[{"count":0,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/posts\/8138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media\/3815"}],"wp:attachment":[{"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/media?parent=8138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/categories?post=8138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pembrokediocese.com\/fr\/wp-json\/wp\/v2\/tags?post=8138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}